{"id":38278,"date":"2026-05-13T16:40:03","date_gmt":"2026-05-13T14:40:03","guid":{"rendered":"https:\/\/skgd.pl\/?p=38278"},"modified":"2026-05-13T15:28:54","modified_gmt":"2026-05-13T13:28:54","slug":"superstar-laureaci-3","status":"publish","type":"post","link":"https:\/\/skgd.pl\/de\/superstar-laureaci-3\/","title":{"rendered":"Superstar Preistr\u00e4ger"},"content":{"rendered":"<p>In der vorherigen Ausgabe gewann das Duo Julia Ernst und Micha\u0142 Peszel den 1. Platz in der Kategorie C.<span>&nbsp;<\/span><img loading=\"lazy\" decoding=\"async\" class=\"an1\" draggable=\"false\" src=\"https:\/\/fonts.gstatic.com\/s\/e\/notoemoji\/17.0\/1f3b6\/32.png\" alt=\"\ud83c\udfb6\" width=\"14\" height=\"14\" data-emoji=\"\ud83c\udfb6\" aria-label=\"\ud83c\udfb6\"><\/p>\n<p>Die jungen K\u00fcnstler verbanden ihre Leidenschaft f\u00fcr Musik und begeisterten gemeinsam das Publikum w\u00e4hrend des Abschlusskonzerts in Malapane. Ihr Auftritt zeigte, dass Talent, Engagement und die Freude am gemeinsamen Musizieren bis auf das Siegerpodest des SUPERSTAR-Wettbewerbs f\u00fchren k\u00f6nnen.<\/p>\n<p>Wir laden euch herzlich ein, ihren Auftritt beim Abschlusskonzert in Malapane anzusehen!<span>&nbsp;<\/span><img loading=\"lazy\" decoding=\"async\" class=\"an1\" draggable=\"false\" src=\"https:\/\/fonts.gstatic.com\/s\/e\/notoemoji\/17.0\/1f3a4\/32.png\" alt=\"\ud83c\udfa4\" width=\"15\" height=\"15\" data-emoji=\"\ud83c\udfa4\" aria-label=\"\ud83c\udfa4\"><\/p>\n<div id='' class='wpcp-container'><div id='UseyourDrive' class=' video  wpcp-has-scroll-to-top' data-module-id='' style='display:none'><noscript><div class='UseyourDrive-nojsmessage'>Um diesen Inhalt anzuzeigen, m\u00fcssen Sie JavaScript in Ihrem Browser aktiviert haben.<br\/><a href='http:\/\/www.enable-javascript.com\/' target='_blank'>Gehen Sie dazu bitte wie folgt vor<\/a>.<\/div><\/noscript><div id='UseyourDrive-fa708b97dedfc308f683fe90440faa6e' class='wpcp-module UseyourDrive media video jsdisabled' data-list='media' data-token='fa708b97dedfc308f683fe90440faa6e' data-account-id='115230797372415529152' data-id='' data-sort='name:asc' data-source='a2d9f47655dd19176d99296103e84376' data-layout='grid'><div\r\n  class=\"wpcp__main-container wpcp__loading wpcp__video \" \r\n  style=\"width:100%; max-width:100%;--wpcp-data-aspect-ratio:16\/9;\"\r\n  data-show-playlist=\"0\" \r\n  data-open-playlist=\"1\"\r\n  data-playlist-inline=\"0\"\r\n  data-playlist-autoplay=\"1\"\r\n  data-playlist-loop=\"0\"\r\n  data-controls=\"prevtrack,playpause,nexttrack,volume,current,duration,fullscreen\"\r\n  data-ads-tag-url=\"\"\r\n  data-ads-skip=\"5\"\r\n  data-max-height=\"none\"  \r\n  data-aspect-ratio=\"16\/9\"  \r\n  >\r\n  <div class=\"loading initialize\">\r\n    <svg class=\"loader-spinner\" viewBox=\"25 25 50 50\"><circle class=\"path\" cx=\"50\" cy=\"50\" r=\"20\" fill=\"none\" stroke-width=\"3\" stroke-miterlimit=\"10\"><\/circle><\/svg>\r\n  <\/div>\r\n  <video  preload=\"metadata\" playsinline webkit-playsinline><\/video>\r\n<\/div>\r\n<style>\r\n  #UseyourDrive-fa708b97dedfc308f683fe90440faa6e .wpcp__container.wpcp__video,\r\n  #UseyourDrive-fa708b97dedfc308f683fe90440faa6e .wpcp__main-container video,\r\n  #UseyourDrive-fa708b97dedfc308f683fe90440faa6e .wpcp__main-container.wpcp__loading.wpcp__video,\r\n  #UseyourDrive-fa708b97dedfc308f683fe90440faa6e .wpcp__playlist-item-thumbnail>img {\r\n    aspect-ratio: 16\/9 !important;\r\n  }\r\n<\/style>\r\n<\/div><\/div><script type='text\/javascript'>if (typeof(jQuery) !== 'undefined' && typeof(jQuery.cp) !== 'undefined' && typeof(jQuery.cp.UseyourDrive) === 'function') { jQuery('#UseyourDrive-fa708b97dedfc308f683fe90440faa6e').UseyourDrive(UseyourDrive_vars); };<\/script><\/div>\n<p>M\u00f6chtest du auch ein Superstar-Preistr\u00e4ger werden? Dann melde dich jetzt f\u00fcr SUPERSTAR 2026 an!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"an1\" draggable=\"false\" src=\"https:\/\/fonts.gstatic.com\/s\/e\/notoemoji\/17.0\/1f3b5\/32.png\" alt=\"\ud83c\udfb5\" width=\"15\" height=\"15\" data-emoji=\"\ud83c\udfb5\" aria-label=\"\ud83c\udfb5\"><span>&nbsp;<\/span>W\u00e4hle ein deutsches Lied<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"an1\" draggable=\"false\" src=\"https:\/\/fonts.gstatic.com\/s\/e\/notoemoji\/17.0\/1f3a7\/32.png\" alt=\"\ud83c\udfa7\" width=\"17\" height=\"17\" data-emoji=\"\ud83c\udfa7\" aria-label=\"\ud83c\udfa7\"><span>&nbsp;<\/span>Nimm deinen Auftritt auf und sende ihn an:<span>&nbsp;<\/span><a href=\"mailto:ewa.mroz@skgd.pl\" target=\"_blank\" rel=\"noopener\">ewa.mroz@skgd.pl<\/a><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"an1\" draggable=\"false\" src=\"https:\/\/fonts.gstatic.com\/s\/e\/notoemoji\/17.0\/1f4dd\/32.png\" alt=\"\ud83d\udcdd\" width=\"19\" height=\"19\" data-emoji=\"\ud83d\udcdd\" aria-label=\"\ud83d\udcdd\"><span>&nbsp;<\/span>F\u00fclle das Online-Anmeldeformular aus:<span>&nbsp;<\/span><a href=\"https:\/\/forms.gle\/brx9Mrcyh4Rz1j2Q6\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/forms.gle\/brx9Mrcyh4Rz1j2Q6&amp;source=gmail&amp;ust=1778754704975000&amp;usg=AOvVaw2e1m-bLaqZjq5U0u5zbgFE\">formularz zg\u0142oszeniowy<\/a><\/p>\n<p>Warte nicht \u2013 zeig dein Talent und erlebe zusammen mit uns ein musikalisches Abenteuer!<span>&nbsp;<\/span><img loading=\"lazy\" decoding=\"async\" class=\"an1\" draggable=\"false\" src=\"https:\/\/fonts.gstatic.com\/s\/e\/notoemoji\/17.0\/1f3a4\/32.png\" alt=\"\ud83c\udfa4\" width=\"17\" height=\"17\" data-emoji=\"\ud83c\udfa4\" aria-label=\"\ud83c\udfa4\"><\/p>\n<p>Das Projekt wurde vom polnischen Ministerium des Inneren und der Verwaltung und vom Bundesministerium des Innern und f\u00fcr Heimat (BMI) durch den VdG finanziert.<\/p>","protected":false},"excerpt":{"rendered":"<p>In der vorherigen Ausgabe gewann das Duo Julia Ernst und Micha\u0142 Peszel den 1. Platz in der Kategorie C.&nbsp; Die jungen K\u00fcnstler verbanden ihre Leidenschaft f\u00fcr Musik und begeisterten gemeinsam das Publikum w\u00e4hrend des Abschlusskonzerts in Malapane. Ihr Auftritt zeigte, dass Talent, Engagement und die Freude am gemeinsamen Musizieren bis auf das Siegerpodest des SUPERSTAR-Wettbewerbs [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":38279,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[733,1],"tags":[],"class_list":["post-38278","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kultura","category-aktualnosci"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Superstar Preistr\u00e4ger - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skgd.pl\/superstar-laureaci-3\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Superstar Preistr\u00e4ger - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"og:description\" content=\"In der vorherigen Ausgabe gewann das Duo Julia Ernst und Micha\u0142 Peszel den 1. Platz in der Kategorie C.&nbsp; Die jungen K\u00fcnstler verbanden ihre Leidenschaft f\u00fcr Musik und begeisterten gemeinsam das Publikum w\u00e4hrend des Abschlusskonzerts in Malapane. Ihr Auftritt zeigte, dass Talent, Engagement und die Freude am gemeinsamen Musizieren bis auf das Siegerpodest des SUPERSTAR-Wettbewerbs [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skgd.pl\/superstar-laureaci-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T14:40:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:28:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skgd.pl\/wp-content\/uploads\/2026\/05\/Projekt-bez-nazwy-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anna Koschny\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skgd.pl\/#website\",\"url\":\"https:\/\/skgd.pl\/\",\"name\":\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"description\":\"Deutsche Minderheit in Polen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skgd.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/superstar-laureaci-3\/#primaryimage\",\"url\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2026\/05\/Projekt-bez-nazwy-1.png\",\"contentUrl\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2026\/05\/Projekt-bez-nazwy-1.png\",\"width\":1080,\"height\":1350},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skgd.pl\/superstar-laureaci-3\/#webpage\",\"url\":\"https:\/\/skgd.pl\/superstar-laureaci-3\/\",\"name\":\"Superstar Preistr\u00e4ger - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"isPartOf\":{\"@id\":\"https:\/\/skgd.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skgd.pl\/superstar-laureaci-3\/#primaryimage\"},\"datePublished\":\"2026-05-13T14:40:03+00:00\",\"dateModified\":\"2026-05-13T13:28:54+00:00\",\"author\":{\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/3949b133860add46d83a0c68af13c928\"},\"breadcrumb\":{\"@id\":\"https:\/\/skgd.pl\/superstar-laureaci-3\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skgd.pl\/superstar-laureaci-3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skgd.pl\/superstar-laureaci-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/skgd.pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Superstar Laureaci\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/3949b133860add46d83a0c68af13c928\",\"name\":\"Anna Koschny\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4e81b53917072303a83a06648cc779cc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4e81b53917072303a83a06648cc779cc?s=96&d=mm&r=g\",\"caption\":\"Anna Koschny\"},\"url\":\"https:\/\/skgd.pl\/de\/author\/anna-koschnyskgd-pl\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Superstar Preistr\u00e4ger - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skgd.pl\/superstar-laureaci-3\/","og_locale":"de_DE","og_type":"article","og_title":"Superstar Preistr\u00e4ger - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","og_description":"In der vorherigen Ausgabe gewann das Duo Julia Ernst und Micha\u0142 Peszel den 1. Platz in der Kategorie C.&nbsp; Die jungen K\u00fcnstler verbanden ihre Leidenschaft f\u00fcr Musik und begeisterten gemeinsam das Publikum w\u00e4hrend des Abschlusskonzerts in Malapane. Ihr Auftritt zeigte, dass Talent, Engagement und die Freude am gemeinsamen Musizieren bis auf das Siegerpodest des SUPERSTAR-Wettbewerbs [&hellip;]","og_url":"https:\/\/skgd.pl\/superstar-laureaci-3\/","og_site_name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","article_published_time":"2026-05-13T14:40:03+00:00","article_modified_time":"2026-05-13T13:28:54+00:00","og_image":[{"width":1080,"height":1350,"url":"https:\/\/skgd.pl\/wp-content\/uploads\/2026\/05\/Projekt-bez-nazwy-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Anna Koschny","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/skgd.pl\/#website","url":"https:\/\/skgd.pl\/","name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","description":"Deutsche Minderheit in Polen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skgd.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/superstar-laureaci-3\/#primaryimage","url":"https:\/\/skgd.pl\/wp-content\/uploads\/2026\/05\/Projekt-bez-nazwy-1.png","contentUrl":"https:\/\/skgd.pl\/wp-content\/uploads\/2026\/05\/Projekt-bez-nazwy-1.png","width":1080,"height":1350},{"@type":"WebPage","@id":"https:\/\/skgd.pl\/superstar-laureaci-3\/#webpage","url":"https:\/\/skgd.pl\/superstar-laureaci-3\/","name":"Superstar Preistr\u00e4ger - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","isPartOf":{"@id":"https:\/\/skgd.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skgd.pl\/superstar-laureaci-3\/#primaryimage"},"datePublished":"2026-05-13T14:40:03+00:00","dateModified":"2026-05-13T13:28:54+00:00","author":{"@id":"https:\/\/skgd.pl\/#\/schema\/person\/3949b133860add46d83a0c68af13c928"},"breadcrumb":{"@id":"https:\/\/skgd.pl\/superstar-laureaci-3\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skgd.pl\/superstar-laureaci-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/skgd.pl\/superstar-laureaci-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/skgd.pl\/"},{"@type":"ListItem","position":2,"name":"Superstar Laureaci"}]},{"@type":"Person","@id":"https:\/\/skgd.pl\/#\/schema\/person\/3949b133860add46d83a0c68af13c928","name":"Anna Koschny","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4e81b53917072303a83a06648cc779cc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4e81b53917072303a83a06648cc779cc?s=96&d=mm&r=g","caption":"Anna Koschny"},"url":"https:\/\/skgd.pl\/de\/author\/anna-koschnyskgd-pl\/"}]}},"_links":{"self":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/38278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/comments?post=38278"}],"version-history":[{"count":4,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/38278\/revisions"}],"predecessor-version":[{"id":38283,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/38278\/revisions\/38283"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media\/38279"}],"wp:attachment":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media?parent=38278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/categories?post=38278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/tags?post=38278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}