{"id":33846,"date":"2023-12-28T10:23:49","date_gmt":"2023-12-28T09:23:49","guid":{"rendered":"https:\/\/skgd.pl\/?p=33846"},"modified":"2024-02-07T15:08:51","modified_gmt":"2024-02-07T14:08:51","slug":"przygody-antonii-juz-dzis-dostepne-online-2","status":"publish","type":"post","link":"https:\/\/skgd.pl\/de\/przygody-antonii-juz-dzis-dostepne-online-2\/","title":{"rendered":"DIE ABENTEUER VON ANTONIA SCHON HEUTE ONLINE ERH\u00c4LTLICH!"},"content":{"rendered":"<p>Heute haben wir f\u00fcr die j\u00fcngsten unter Euch, die zu Hause Langeweile haben, eine \u00dcberraschung vorbereitet.<\/p>\n<p>Schon heute findet die Premiere des Kinderbuches <strong>,,<\/strong><em><strong>Antonia. Das Sockenfieber\u201d<\/strong><\/em>&nbsp;online statt.<\/p>\n<p>Die Publikation ist an Kinder in Vorschulalter und fr\u00fchen Schulalter gewidmet. Es stellt den Kindern in interessanter und attraktiver Art und Weise die Vielfalt der Gesellschaft da, welche die Deutsche Minderheit in der Oppelner Region mitkreiert. Die Publikation ist zweisprachig, also sowohl in der deutschen, als auch in der polnischen Sprache. Das Kinderbuch ist klar und zug\u00e4nglich f\u00fcr ihre Empf\u00e4nger geschrieben. Zum lesen ermuntern bunte Illustrationen, die visuell jedes neugierige Auge anziehen. Schon heute k\u00f6nnen Sie das Buch in elektronischer Version auf eure Bildschirme runterladen (Die PFD Version zum runterladen befindet sich rechts).<\/p>\n<p>F\u00fcr diejenigen, die noch nicht lesen k\u00f6nnen oder erst die Sprache lernen, haben wir ein H\u00f6rspiel sowohl in Deutsch, als auch Polnisch online gestellt (Der Link zu beiden Sprachversionen ist unten angegeben).<\/p>\n<p>Also los! Verw\u00e4ndeln wir unsere H\u00e4user in weite Meere und gehen mit Antonia in See, um ihre Socken zu finden!<\/p>\n<p><em><strong>H\u00f6rspiel:<\/strong><\/em><\/p>\n<p><em><strong>Deutsche Version:<\/strong><\/em><\/p>\n<p><audio class=\"wp-audio-shortcode\" id=\"audio-33846-2\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/skgd.pl\/wp-content\/uploads\/2023\/12\/Antonia-2_DE.mp3?_=2\" \/><a href=\"https:\/\/skgd.pl\/wp-content\/uploads\/2023\/12\/Antonia-2_DE.mp3\">https:\/\/skgd.pl\/wp-content\/uploads\/2023\/12\/Antonia-2_DE.mp3<\/a><\/audio><\/p>","protected":false},"excerpt":{"rendered":"<p>Heute haben wir f\u00fcr die j\u00fcngsten unter Euch, die zu Hause Langeweile haben, eine \u00dcberraschung vorbereitet. Schon heute findet die Premiere des Kinderbuches ,,Antonia. Das Sockenfieber\u201d&nbsp;online statt. Die Publikation ist an Kinder in Vorschulalter und fr\u00fchen Schulalter gewidmet. Es stellt den Kindern in interessanter und attraktiver Art und Weise die Vielfalt der Gesellschaft da, welche [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":33847,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-33846","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktualnosci"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>DIE ABENTEUER VON ANTONIA SCHON HEUTE ONLINE ERH\u00c4LTLICH! - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skgd.pl\/de\/przygody-antonii-juz-dzis-dostepne-online-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DIE ABENTEUER VON ANTONIA SCHON HEUTE ONLINE ERH\u00c4LTLICH! - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"og:description\" content=\"Heute haben wir f\u00fcr die j\u00fcngsten unter Euch, die zu Hause Langeweile haben, eine \u00dcberraschung vorbereitet. Schon heute findet die Premiere des Kinderbuches ,,Antonia. Das Sockenfieber\u201d&nbsp;online statt. Die Publikation ist an Kinder in Vorschulalter und fr\u00fchen Schulalter gewidmet. Es stellt den Kindern in interessanter und attraktiver Art und Weise die Vielfalt der Gesellschaft da, welche [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skgd.pl\/de\/przygody-antonii-juz-dzis-dostepne-online-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-28T09:23:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-07T14:08:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skgd.pl\/wp-content\/uploads\/2024\/01\/okladka-Antonia-reklama-1-str-731x1024-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"731\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Bewko\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skgd.pl\/#website\",\"url\":\"https:\/\/skgd.pl\/\",\"name\":\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"description\":\"Deutsche Minderheit in Polen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skgd.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/de\/przygody-antonii-juz-dzis-dostepne-online-2\/#primaryimage\",\"url\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2024\/01\/okladka-Antonia-reklama-1-str-731x1024-1.png\",\"contentUrl\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2024\/01\/okladka-Antonia-reklama-1-str-731x1024-1.png\",\"width\":731,\"height\":1024},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skgd.pl\/de\/przygody-antonii-juz-dzis-dostepne-online-2\/#webpage\",\"url\":\"https:\/\/skgd.pl\/de\/przygody-antonii-juz-dzis-dostepne-online-2\/\",\"name\":\"DIE ABENTEUER VON ANTONIA SCHON HEUTE ONLINE ERH\u00c4LTLICH! - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"isPartOf\":{\"@id\":\"https:\/\/skgd.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skgd.pl\/de\/przygody-antonii-juz-dzis-dostepne-online-2\/#primaryimage\"},\"datePublished\":\"2023-12-28T09:23:49+00:00\",\"dateModified\":\"2024-02-07T14:08:51+00:00\",\"author\":{\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/3fb073cb271b54c7c3d73598166a8846\"},\"breadcrumb\":{\"@id\":\"https:\/\/skgd.pl\/de\/przygody-antonii-juz-dzis-dostepne-online-2\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skgd.pl\/de\/przygody-antonii-juz-dzis-dostepne-online-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skgd.pl\/de\/przygody-antonii-juz-dzis-dostepne-online-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/skgd.pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DIE ABENTEUER VON ANTONIA SCHON HEUTE ONLINE ERH\u00c4LTLICH!\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/3fb073cb271b54c7c3d73598166a8846\",\"name\":\"Daniel Bewko\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/58105dc9f309bee138f8b2d07926d45653268d482d54de84622dc38b358069e5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/58105dc9f309bee138f8b2d07926d45653268d482d54de84622dc38b358069e5?s=96&d=mm&r=g\",\"caption\":\"Daniel Bewko\"},\"url\":\"https:\/\/skgd.pl\/de\/author\/daniel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DIE ABENTEUER VON ANTONIA SCHON HEUTE ONLINE ERH\u00c4LTLICH! - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skgd.pl\/de\/przygody-antonii-juz-dzis-dostepne-online-2\/","og_locale":"de_DE","og_type":"article","og_title":"DIE ABENTEUER VON ANTONIA SCHON HEUTE ONLINE ERH\u00c4LTLICH! - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","og_description":"Heute haben wir f\u00fcr die j\u00fcngsten unter Euch, die zu Hause Langeweile haben, eine \u00dcberraschung vorbereitet. Schon heute findet die Premiere des Kinderbuches ,,Antonia. Das Sockenfieber\u201d&nbsp;online statt. Die Publikation ist an Kinder in Vorschulalter und fr\u00fchen Schulalter gewidmet. Es stellt den Kindern in interessanter und attraktiver Art und Weise die Vielfalt der Gesellschaft da, welche [&hellip;]","og_url":"https:\/\/skgd.pl\/de\/przygody-antonii-juz-dzis-dostepne-online-2\/","og_site_name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","article_published_time":"2023-12-28T09:23:49+00:00","article_modified_time":"2024-02-07T14:08:51+00:00","og_image":[{"width":731,"height":1024,"url":"https:\/\/skgd.pl\/wp-content\/uploads\/2024\/01\/okladka-Antonia-reklama-1-str-731x1024-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Daniel Bewko","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/skgd.pl\/#website","url":"https:\/\/skgd.pl\/","name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","description":"Deutsche Minderheit in Polen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skgd.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/de\/przygody-antonii-juz-dzis-dostepne-online-2\/#primaryimage","url":"https:\/\/skgd.pl\/wp-content\/uploads\/2024\/01\/okladka-Antonia-reklama-1-str-731x1024-1.png","contentUrl":"https:\/\/skgd.pl\/wp-content\/uploads\/2024\/01\/okladka-Antonia-reklama-1-str-731x1024-1.png","width":731,"height":1024},{"@type":"WebPage","@id":"https:\/\/skgd.pl\/de\/przygody-antonii-juz-dzis-dostepne-online-2\/#webpage","url":"https:\/\/skgd.pl\/de\/przygody-antonii-juz-dzis-dostepne-online-2\/","name":"DIE ABENTEUER VON ANTONIA SCHON HEUTE ONLINE ERH\u00c4LTLICH! - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","isPartOf":{"@id":"https:\/\/skgd.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skgd.pl\/de\/przygody-antonii-juz-dzis-dostepne-online-2\/#primaryimage"},"datePublished":"2023-12-28T09:23:49+00:00","dateModified":"2024-02-07T14:08:51+00:00","author":{"@id":"https:\/\/skgd.pl\/#\/schema\/person\/3fb073cb271b54c7c3d73598166a8846"},"breadcrumb":{"@id":"https:\/\/skgd.pl\/de\/przygody-antonii-juz-dzis-dostepne-online-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skgd.pl\/de\/przygody-antonii-juz-dzis-dostepne-online-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/skgd.pl\/de\/przygody-antonii-juz-dzis-dostepne-online-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/skgd.pl\/"},{"@type":"ListItem","position":2,"name":"DIE ABENTEUER VON ANTONIA SCHON HEUTE ONLINE ERH\u00c4LTLICH!"}]},{"@type":"Person","@id":"https:\/\/skgd.pl\/#\/schema\/person\/3fb073cb271b54c7c3d73598166a8846","name":"Daniel Bewko","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/58105dc9f309bee138f8b2d07926d45653268d482d54de84622dc38b358069e5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/58105dc9f309bee138f8b2d07926d45653268d482d54de84622dc38b358069e5?s=96&d=mm&r=g","caption":"Daniel Bewko"},"url":"https:\/\/skgd.pl\/de\/author\/daniel\/"}]}},"_links":{"self":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/33846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/comments?post=33846"}],"version-history":[{"count":4,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/33846\/revisions"}],"predecessor-version":[{"id":33929,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/33846\/revisions\/33929"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media\/33847"}],"wp:attachment":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media?parent=33846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/categories?post=33846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/tags?post=33846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}