{"id":33133,"date":"2023-09-01T18:00:43","date_gmt":"2023-09-01T16:00:43","guid":{"rendered":"https:\/\/skgd.pl\/?p=33133"},"modified":"2023-09-01T13:06:22","modified_gmt":"2023-09-01T11:06:22","slug":"list-przewodniczacego-znssk-w-polsce-do-szkol-z-nauczaniem-j-niemieckiego-jako-j-mniejszosci-2023-24","status":"publish","type":"post","link":"https:\/\/skgd.pl\/de\/list-przewodniczacego-znssk-w-polsce-do-szkol-z-nauczaniem-j-niemieckiego-jako-j-mniejszosci-2023-24\/","title":{"rendered":"Brief des VdG-Vorsitzenden an Schulen mit Deutschunterricht als Minderheitensprache 2023\/24"},"content":{"rendered":"<p><em>Schulleiterinnen und Schulleiter<\/em><\/p>\n<p><em>von Schulen mit Deutschunterricht<\/em><\/p>\n<p><em>als Minderheitensprache<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>Sehr geehrte Damen und Herren,<\/em><\/p>\n<p>das neue Schuljahr 2023\/2024, das am 1. September beginnt, wird bereits das zweite Jahr in der Geschichte des freien Polens nach 1989 sein, in dem die Kinder polnischer Staatsb\u00fcrger mit deutscher Nationalit\u00e4t systematisch diskriminiert werden.<\/p>\n<p>Die am 4. Februar 2022 in Kraft getretene Verordnung des Ministers f\u00fcr Bildung und Wissenschaft, mit einer Reduzierung des Deutschunterrichts als Minderheitensprache von drei auf eine Stunde pro Woche, hat zur Folge, dass etwa 55.000 Kinder, die Deutsch als Minderheitensprache lernen, in polnischen Schulen weiterhin diskriminiert werden. Als Vertreter der deutschen Minderheit bem\u00fchen wir uns st\u00e4ndig, dass die Verordnung, die zu dieser Situation gef\u00fchrt hat und die sich direkt gegen die Kinder und ihre Bildungschancen und damit auch gegen ihre Zukunft richtet, aus dem Verkehr gezogen wird. Leider hat die Regierung der Republik Polen trotz vieler Proteste, verschickter Briefe und Rechtsgutachten diese diskriminierende Entscheidung bis heute nicht ge\u00e4ndert.<\/p>\n<p>Trotz der Gespr\u00e4che mit dem Minister Czarnek und seiner Versprechen am 30. November 2022 in Warschau und am 22. Januar 2023 in Oppeln wird diese diskriminierende Verordnung, die nur die Kinder der deutschen Minderheit betrifft (andere nationale und ethnische Minderheiten, die in Polen leben, haben weiterhin Zugang zu 3 Unterrichtstunden Minderheitensprache pro Woche), wurde nicht zur\u00fcckgezogen. Gleichzeitig handelt es sich um genau diese Kinder, die in Zukunft nicht nur ein positives Bild von Polen als einem Land aufbauen sollen, das tolerant und respektvoll gegen\u00fcber seinen B\u00fcrgern ist, unabh\u00e4ngig von ihrer Herkunft und Nationalit\u00e4t, sondern auch die positiven Beziehungen zwischen Polen und Deutschland pflegen und entwickeln sollen, die f\u00fcr die Gestaltung des zuk\u00fcnftigen Europas so wichtig sind. Wir halten es f\u00fcr unzul\u00e4ssig, dass anstelle von diplomatischen L\u00f6sungen die diskriminierenden und folglich auch die Kinder stigmatisierenden L\u00f6sungen eingef\u00fchrt werden, die als Instrument f\u00fcr schlecht durchdachte politische \u201eVerhandlungen\u201c gedacht werden. In einer Situation, in der die Kenntnis einer Sprache eine soziale Schl\u00fcsselkompetenz und f\u00fcr Minderheitengemeinschaften eine Voraussetzung f\u00fcr das \u00dcberleben ihrer Kultur, ihres Erbes und ihrer Identit\u00e4t sind, l\u00f6sen solche Ma\u00dfnahmen nicht nur nichts, sondern zerst\u00f6ren direkt die Errungenschaften vieler Generationen von B\u00fcrgern der Republik Polen.<\/p>\n<p>Angesichts der Schwierigkeiten, mit denen die Schulen und die Deutschlehrerinnen und -lehrer konfrontiert sind, m\u00f6chte ich mich bei allen lokalen Beh\u00f6rden, Gemeindevorsteherinnen und Gemeindevorstehern, B\u00fcrgermeisterinnen und B\u00fcrgermeistern, Stadtpr\u00e4sidentinnen und Stadtpr\u00e4sidenten, Schulleiterinnen und Schulleitern sowie den Verantwortlichen der Tr\u00e4gervereine der Bildungseinrichtungen bedanken, die in Anerkennung des Wertes der Sprache im Schuljahr 2023\/2024 beschlossen haben, zus\u00e4tzliche Stunden f\u00fcr Deutsch als Minderheitensprache (zus\u00e4tzlich zu einer Pflichtstunde) zu finanzieren oder den zweisprachigen Unterricht einzuf\u00fchren. Danke, dass Sie in Ihren lokalen Gemeinschaften ein deutliches Zeichen setzen, dass Kinder an erster Stelle stehen und dass Sie Diskriminierung und Stigmatisierung aus nationalen Gr\u00fcnden nicht dulden! Und ich m\u00f6chte mich in besonderer Weise bei den Lehrern und Eltern bedanken, f\u00fcr die die deutsche Sprache einen Wert hat, die sie an die n\u00e4chste Generation weitergeben wollen und die sich trotz aller Schwierigkeiten f\u00fcr ihr \u00dcberleben einsetzen.<\/p>\n<p>Ich danke Ihnen f\u00fcr Ihr Engagement f\u00fcr die deutsche Sprache in einer Situation, in der wir einerseits seit \u00fcber einem Jahr mit einer Reduzierung des Deutschunterrichts zu tun haben, andererseits wissen wir, dass die Arbeitnehmer mit guten Deutschkenntnissen auf dem Arbeitsmarkt gefragt sind. Allein in der Woiwodschaft Oppeln haben sich in den letzten Jahren mehrere Unternehmen mit deutschem Kapital oder deutschsprachigen Kunden angesiedelt, wodurch etwa 2.500 Arbeitspl\u00e4tze geschaffen wurden, die Deutschkenntnisse erfordern.<\/p>\n<p>Die Bildung ist nicht nur auf die Schule beschr\u00e4nkt. Daher m\u00f6chte ich Sie einladen, sich die au\u00dferschulischen Angebote der Organisationen der deutschen Minderheit anzuschauen, die Sie u.a. auf der Bildungsplattform der deutschen Minderheit finden:&nbsp;<a href=\"http:\/\/www.supereule.pl\/\">www.supereule.pl<\/a>. Wir m\u00f6chten Sie \u00fcber aktuelle Probleme und Fragestellungen im Bildungsbereich informieren, Sie aber auch dazu inspirieren, das au\u00dferschulische Bildungsangebot der deutschen Minderheit zu nutzen.<\/p>\n<p>Auf dieser Plattform finden Sie ein breites Angebot an Aktivit\u00e4ten, Workshops, Wettbewerben und Schulungen f\u00fcr alle Altersgruppen sowie die Bestimmungen der polnischen und europ\u00e4ischen Gesetzgebung und Kommentare zur Organisation des Minderheitenunterrichts. mit Kommentaren \u00fcber die Organisation des Minderheitenunterrichts. Auf besondere Weise m\u00f6chten wir Sie auf das innovative Projekt LernRAUM.pl aufmerksam machen, in dem Sie Ihre Sprachkenntnisse verbessern und gleichzeitig Ihre verschiedenen Leidenschaften und Interessen entwickeln k\u00f6nnen.<\/p>\n<p>In einer pluralistischen Gesellschaft gibt es keine privilegierten Standpunkte, daher danke ich Ihnen daf\u00fcr, dass Sie bei jungen Menschen eine Haltung der Offenheit gegen\u00fcber der Welt und anderen Menschen f\u00f6rdern. Gleichzeitig bitte ich Sie, die deutsche Sprache und die deutsche Kultur weiterhin zu f\u00f6rdern. F\u00fcr das neue Schuljahr w\u00fcnsche ich allen Sch\u00fclerinnen und Sch\u00fclern viele M\u00f6glichkeiten, in einer Atmosph\u00e4re des gegenseitigen Verst\u00e4ndnisses zu wachsen, und ich w\u00fcnsche uns allen eine Gemeinschaft, in der das dialogische Projekt von morgen gestaltet wird.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Hochachtungsvoll<\/em><\/p>\n<p><em>Rafa\u0142 Bartek<\/em><\/p>\n<p><em>VdG-Vorsitzender<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Schulleiterinnen und Schulleiter von Schulen mit Deutschunterricht als Minderheitensprache &nbsp; Sehr geehrte Damen und Herren, das neue Schuljahr 2023\/2024, das am 1. September beginnt, wird bereits das zweite Jahr in der Geschichte des freien Polens nach 1989 sein, in dem die Kinder polnischer Staatsb\u00fcrger mit deutscher Nationalit\u00e4t systematisch diskriminiert werden. Die am 4. Februar 2022 [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":33135,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[731,1],"tags":[],"class_list":["post-33133","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-edukacja","category-aktualnosci"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Brief des VdG-Vorsitzenden an Schulen mit Deutschunterricht als Minderheitensprache 2023\/24 - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skgd.pl\/de\/list-przewodniczacego-znssk-w-polsce-do-szkol-z-nauczaniem-j-niemieckiego-jako-j-mniejszosci-2023-24\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brief des VdG-Vorsitzenden an Schulen mit Deutschunterricht als Minderheitensprache 2023\/24 - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"og:description\" content=\"Schulleiterinnen und Schulleiter von Schulen mit Deutschunterricht als Minderheitensprache &nbsp; Sehr geehrte Damen und Herren, das neue Schuljahr 2023\/2024, das am 1. September beginnt, wird bereits das zweite Jahr in der Geschichte des freien Polens nach 1989 sein, in dem die Kinder polnischer Staatsb\u00fcrger mit deutscher Nationalit\u00e4t systematisch diskriminiert werden. Die am 4. Februar 2022 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skgd.pl\/de\/list-przewodniczacego-znssk-w-polsce-do-szkol-z-nauczaniem-j-niemieckiego-jako-j-mniejszosci-2023-24\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-01T16:00:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-01T11:06:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skgd.pl\/wp-content\/uploads\/2023\/09\/List-przewodniczacego-ZNSSK-w-Polsce-do-szkol-z-nauczaniem-j.-niemieckiego-jako-j.-mniejszosci-202324.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Bewko\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skgd.pl\/#website\",\"url\":\"https:\/\/skgd.pl\/\",\"name\":\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"description\":\"Deutsche Minderheit in Polen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skgd.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/de\/list-przewodniczacego-znssk-w-polsce-do-szkol-z-nauczaniem-j-niemieckiego-jako-j-mniejszosci-2023-24\/#primaryimage\",\"url\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2023\/09\/List-przewodniczacego-ZNSSK-w-Polsce-do-szkol-z-nauczaniem-j.-niemieckiego-jako-j.-mniejszosci-202324.png\",\"contentUrl\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2023\/09\/List-przewodniczacego-ZNSSK-w-Polsce-do-szkol-z-nauczaniem-j.-niemieckiego-jako-j.-mniejszosci-202324.png\",\"width\":1080,\"height\":1080},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skgd.pl\/de\/list-przewodniczacego-znssk-w-polsce-do-szkol-z-nauczaniem-j-niemieckiego-jako-j-mniejszosci-2023-24\/#webpage\",\"url\":\"https:\/\/skgd.pl\/de\/list-przewodniczacego-znssk-w-polsce-do-szkol-z-nauczaniem-j-niemieckiego-jako-j-mniejszosci-2023-24\/\",\"name\":\"Brief des VdG-Vorsitzenden an Schulen mit Deutschunterricht als Minderheitensprache 2023\/24 - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"isPartOf\":{\"@id\":\"https:\/\/skgd.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skgd.pl\/de\/list-przewodniczacego-znssk-w-polsce-do-szkol-z-nauczaniem-j-niemieckiego-jako-j-mniejszosci-2023-24\/#primaryimage\"},\"datePublished\":\"2023-09-01T16:00:43+00:00\",\"dateModified\":\"2023-09-01T11:06:22+00:00\",\"author\":{\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/3fb073cb271b54c7c3d73598166a8846\"},\"breadcrumb\":{\"@id\":\"https:\/\/skgd.pl\/de\/list-przewodniczacego-znssk-w-polsce-do-szkol-z-nauczaniem-j-niemieckiego-jako-j-mniejszosci-2023-24\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skgd.pl\/de\/list-przewodniczacego-znssk-w-polsce-do-szkol-z-nauczaniem-j-niemieckiego-jako-j-mniejszosci-2023-24\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skgd.pl\/de\/list-przewodniczacego-znssk-w-polsce-do-szkol-z-nauczaniem-j-niemieckiego-jako-j-mniejszosci-2023-24\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/skgd.pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brief des VdG-Vorsitzenden an Schulen mit Deutschunterricht als Minderheitensprache 2023\/24\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/3fb073cb271b54c7c3d73598166a8846\",\"name\":\"Daniel Bewko\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/58105dc9f309bee138f8b2d07926d45653268d482d54de84622dc38b358069e5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/58105dc9f309bee138f8b2d07926d45653268d482d54de84622dc38b358069e5?s=96&d=mm&r=g\",\"caption\":\"Daniel Bewko\"},\"url\":\"https:\/\/skgd.pl\/de\/author\/daniel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brief des VdG-Vorsitzenden an Schulen mit Deutschunterricht als Minderheitensprache 2023\/24 - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skgd.pl\/de\/list-przewodniczacego-znssk-w-polsce-do-szkol-z-nauczaniem-j-niemieckiego-jako-j-mniejszosci-2023-24\/","og_locale":"de_DE","og_type":"article","og_title":"Brief des VdG-Vorsitzenden an Schulen mit Deutschunterricht als Minderheitensprache 2023\/24 - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","og_description":"Schulleiterinnen und Schulleiter von Schulen mit Deutschunterricht als Minderheitensprache &nbsp; Sehr geehrte Damen und Herren, das neue Schuljahr 2023\/2024, das am 1. September beginnt, wird bereits das zweite Jahr in der Geschichte des freien Polens nach 1989 sein, in dem die Kinder polnischer Staatsb\u00fcrger mit deutscher Nationalit\u00e4t systematisch diskriminiert werden. Die am 4. Februar 2022 [&hellip;]","og_url":"https:\/\/skgd.pl\/de\/list-przewodniczacego-znssk-w-polsce-do-szkol-z-nauczaniem-j-niemieckiego-jako-j-mniejszosci-2023-24\/","og_site_name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","article_published_time":"2023-09-01T16:00:43+00:00","article_modified_time":"2023-09-01T11:06:22+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/skgd.pl\/wp-content\/uploads\/2023\/09\/List-przewodniczacego-ZNSSK-w-Polsce-do-szkol-z-nauczaniem-j.-niemieckiego-jako-j.-mniejszosci-202324.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Daniel Bewko","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/skgd.pl\/#website","url":"https:\/\/skgd.pl\/","name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","description":"Deutsche Minderheit in Polen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skgd.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/de\/list-przewodniczacego-znssk-w-polsce-do-szkol-z-nauczaniem-j-niemieckiego-jako-j-mniejszosci-2023-24\/#primaryimage","url":"https:\/\/skgd.pl\/wp-content\/uploads\/2023\/09\/List-przewodniczacego-ZNSSK-w-Polsce-do-szkol-z-nauczaniem-j.-niemieckiego-jako-j.-mniejszosci-202324.png","contentUrl":"https:\/\/skgd.pl\/wp-content\/uploads\/2023\/09\/List-przewodniczacego-ZNSSK-w-Polsce-do-szkol-z-nauczaniem-j.-niemieckiego-jako-j.-mniejszosci-202324.png","width":1080,"height":1080},{"@type":"WebPage","@id":"https:\/\/skgd.pl\/de\/list-przewodniczacego-znssk-w-polsce-do-szkol-z-nauczaniem-j-niemieckiego-jako-j-mniejszosci-2023-24\/#webpage","url":"https:\/\/skgd.pl\/de\/list-przewodniczacego-znssk-w-polsce-do-szkol-z-nauczaniem-j-niemieckiego-jako-j-mniejszosci-2023-24\/","name":"Brief des VdG-Vorsitzenden an Schulen mit Deutschunterricht als Minderheitensprache 2023\/24 - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","isPartOf":{"@id":"https:\/\/skgd.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skgd.pl\/de\/list-przewodniczacego-znssk-w-polsce-do-szkol-z-nauczaniem-j-niemieckiego-jako-j-mniejszosci-2023-24\/#primaryimage"},"datePublished":"2023-09-01T16:00:43+00:00","dateModified":"2023-09-01T11:06:22+00:00","author":{"@id":"https:\/\/skgd.pl\/#\/schema\/person\/3fb073cb271b54c7c3d73598166a8846"},"breadcrumb":{"@id":"https:\/\/skgd.pl\/de\/list-przewodniczacego-znssk-w-polsce-do-szkol-z-nauczaniem-j-niemieckiego-jako-j-mniejszosci-2023-24\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skgd.pl\/de\/list-przewodniczacego-znssk-w-polsce-do-szkol-z-nauczaniem-j-niemieckiego-jako-j-mniejszosci-2023-24\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/skgd.pl\/de\/list-przewodniczacego-znssk-w-polsce-do-szkol-z-nauczaniem-j-niemieckiego-jako-j-mniejszosci-2023-24\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/skgd.pl\/"},{"@type":"ListItem","position":2,"name":"Brief des VdG-Vorsitzenden an Schulen mit Deutschunterricht als Minderheitensprache 2023\/24"}]},{"@type":"Person","@id":"https:\/\/skgd.pl\/#\/schema\/person\/3fb073cb271b54c7c3d73598166a8846","name":"Daniel Bewko","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/58105dc9f309bee138f8b2d07926d45653268d482d54de84622dc38b358069e5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/58105dc9f309bee138f8b2d07926d45653268d482d54de84622dc38b358069e5?s=96&d=mm&r=g","caption":"Daniel Bewko"},"url":"https:\/\/skgd.pl\/de\/author\/daniel\/"}]}},"_links":{"self":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/33133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/comments?post=33133"}],"version-history":[{"count":1,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/33133\/revisions"}],"predecessor-version":[{"id":33136,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/33133\/revisions\/33136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media\/33135"}],"wp:attachment":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media?parent=33133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/categories?post=33133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/tags?post=33133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}