{"id":32812,"date":"2023-06-21T07:50:09","date_gmt":"2023-06-21T05:50:09","guid":{"rendered":"https:\/\/skgd.pl\/?p=32812"},"modified":"2023-06-21T07:50:09","modified_gmt":"2023-06-21T05:50:09","slug":"spotkanie-letnie-czlonkow-kola-dfk-opole-grudzice","status":"publish","type":"post","link":"https:\/\/skgd.pl\/de\/spotkanie-letnie-czlonkow-kola-dfk-opole-grudzice\/","title":{"rendered":"Sommertreffen im DFK Oppeln-Gruden"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: justify; margin-right: 0cm; margin-left: 0cm;\"><span style=\"font-size: 12pt;\"><span><span lang=\"DE\" style=\"font-size: 14.0pt;\">Am Sonntag, den 11. Juni&nbsp; wurde vom DFK Oppeln-Gruden ein Treffen f\u00fcr die Mitglieder organisiert. Im Rahmen der Veranstaltung ist der DFK-Chor \u201eGruden-Melodie\u201c mit sch\u00f6nen <\/span><span style=\"font-size: 14.0pt;\"><a style=\"color: blue; text-decoration: underline;\" title=\"&quot;Repertoire&quot; auf T\u00fcrkisch\" href=\"https:\/\/de.bab.la\/woerterbuch\/deutsch-tuerkisch\/repertoire\" target=\"_blank\" rel=\"noopener\"><span lang=\"DE\" style=\"text-decoration: none;\"><span>Repertoire<\/span><\/span><\/a><\/span><span lang=\"DE\" style=\"font-size: 14.0pt;\"> aufgetreten.&nbsp; Besonderer G\u00e4st des Treffens war Pfarrer Jan Piechoczek, der die deutschen Gottestdienste jednen Sonntag in der Kirche in Gruden feiert. Die Stimmung war sehr gut, es wurde viel gesungen und es gab auch Zeit f\u00fcr viele nette Gespr\u00e4che.<\/span><\/span><\/span><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Am Sonntag, den 11. Juni&nbsp; wurde vom DFK Oppeln-Gruden ein Treffen f\u00fcr die Mitglieder organisiert. Im Rahmen der Veranstaltung ist der DFK-Chor \u201eGruden-Melodie\u201c mit sch\u00f6nen Repertoire aufgetreten.&nbsp; Besonderer G\u00e4st des Treffens war Pfarrer Jan Piechoczek, der die deutschen Gottestdienste jednen Sonntag in der Kirche in Gruden feiert. Die Stimmung war sehr gut, es wurde viel [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":32813,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[275],"tags":[],"class_list":["post-32812","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dfk-opole-grudzice-oppeln-gruden"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sommertreffen im DFK Oppeln-Gruden - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skgd.pl\/en\/spotkanie-letnie-czlonkow-kola-dfk-opole-grudzice\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sommertreffen im DFK Oppeln-Gruden - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"og:description\" content=\"Am Sonntag, den 11. Juni&nbsp; wurde vom DFK Oppeln-Gruden ein Treffen f\u00fcr die Mitglieder organisiert. Im Rahmen der Veranstaltung ist der DFK-Chor \u201eGruden-Melodie\u201c mit sch\u00f6nen Repertoire aufgetreten.&nbsp; Besonderer G\u00e4st des Treffens war Pfarrer Jan Piechoczek, der die deutschen Gottestdienste jednen Sonntag in der Kirche in Gruden feiert. Die Stimmung war sehr gut, es wurde viel [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skgd.pl\/en\/spotkanie-letnie-czlonkow-kola-dfk-opole-grudzice\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-21T05:50:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skgd.pl\/wp-content\/uploads\/2023\/06\/20230611_174835-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skgd.pl\/#website\",\"url\":\"https:\/\/skgd.pl\/\",\"name\":\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"description\":\"Deutsche Minderheit in Polen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skgd.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/en\/spotkanie-letnie-czlonkow-kola-dfk-opole-grudzice\/#primaryimage\",\"url\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2023\/06\/20230611_174835-scaled.jpg\",\"contentUrl\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2023\/06\/20230611_174835-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skgd.pl\/en\/spotkanie-letnie-czlonkow-kola-dfk-opole-grudzice\/#webpage\",\"url\":\"https:\/\/skgd.pl\/en\/spotkanie-letnie-czlonkow-kola-dfk-opole-grudzice\/\",\"name\":\"Sommertreffen im DFK Oppeln-Gruden - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"isPartOf\":{\"@id\":\"https:\/\/skgd.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skgd.pl\/en\/spotkanie-letnie-czlonkow-kola-dfk-opole-grudzice\/#primaryimage\"},\"datePublished\":\"2023-06-21T05:50:09+00:00\",\"dateModified\":\"2023-06-21T05:50:09+00:00\",\"author\":{\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/709172ef205731476e77391cc87c04e8\"},\"breadcrumb\":{\"@id\":\"https:\/\/skgd.pl\/en\/spotkanie-letnie-czlonkow-kola-dfk-opole-grudzice\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skgd.pl\/en\/spotkanie-letnie-czlonkow-kola-dfk-opole-grudzice\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skgd.pl\/en\/spotkanie-letnie-czlonkow-kola-dfk-opole-grudzice\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/skgd.pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"(Polski) Spotkanie letnie cz\u0142onk\u00f3w ko\u0142a DFK Opole-Grudzice\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/709172ef205731476e77391cc87c04e8\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a352aecaac6403c9ea5013a95dbe945e910d71bc652d01a07313977398158711?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a352aecaac6403c9ea5013a95dbe945e910d71bc652d01a07313977398158711?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/skgd.pl\/de\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sommertreffen im DFK Oppeln-Gruden - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skgd.pl\/en\/spotkanie-letnie-czlonkow-kola-dfk-opole-grudzice\/","og_locale":"de_DE","og_type":"article","og_title":"Sommertreffen im DFK Oppeln-Gruden - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","og_description":"Am Sonntag, den 11. Juni&nbsp; wurde vom DFK Oppeln-Gruden ein Treffen f\u00fcr die Mitglieder organisiert. Im Rahmen der Veranstaltung ist der DFK-Chor \u201eGruden-Melodie\u201c mit sch\u00f6nen Repertoire aufgetreten.&nbsp; Besonderer G\u00e4st des Treffens war Pfarrer Jan Piechoczek, der die deutschen Gottestdienste jednen Sonntag in der Kirche in Gruden feiert. Die Stimmung war sehr gut, es wurde viel [&hellip;]","og_url":"https:\/\/skgd.pl\/en\/spotkanie-letnie-czlonkow-kola-dfk-opole-grudzice\/","og_site_name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","article_published_time":"2023-06-21T05:50:09+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/skgd.pl\/wp-content\/uploads\/2023\/06\/20230611_174835-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/skgd.pl\/#website","url":"https:\/\/skgd.pl\/","name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","description":"Deutsche Minderheit in Polen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skgd.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/en\/spotkanie-letnie-czlonkow-kola-dfk-opole-grudzice\/#primaryimage","url":"https:\/\/skgd.pl\/wp-content\/uploads\/2023\/06\/20230611_174835-scaled.jpg","contentUrl":"https:\/\/skgd.pl\/wp-content\/uploads\/2023\/06\/20230611_174835-scaled.jpg","width":2560,"height":1920},{"@type":"WebPage","@id":"https:\/\/skgd.pl\/en\/spotkanie-letnie-czlonkow-kola-dfk-opole-grudzice\/#webpage","url":"https:\/\/skgd.pl\/en\/spotkanie-letnie-czlonkow-kola-dfk-opole-grudzice\/","name":"Sommertreffen im DFK Oppeln-Gruden - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","isPartOf":{"@id":"https:\/\/skgd.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skgd.pl\/en\/spotkanie-letnie-czlonkow-kola-dfk-opole-grudzice\/#primaryimage"},"datePublished":"2023-06-21T05:50:09+00:00","dateModified":"2023-06-21T05:50:09+00:00","author":{"@id":"https:\/\/skgd.pl\/#\/schema\/person\/709172ef205731476e77391cc87c04e8"},"breadcrumb":{"@id":"https:\/\/skgd.pl\/en\/spotkanie-letnie-czlonkow-kola-dfk-opole-grudzice\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skgd.pl\/en\/spotkanie-letnie-czlonkow-kola-dfk-opole-grudzice\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/skgd.pl\/en\/spotkanie-letnie-czlonkow-kola-dfk-opole-grudzice\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/skgd.pl\/"},{"@type":"ListItem","position":2,"name":"(Polski) Spotkanie letnie cz\u0142onk\u00f3w ko\u0142a DFK Opole-Grudzice"}]},{"@type":"Person","@id":"https:\/\/skgd.pl\/#\/schema\/person\/709172ef205731476e77391cc87c04e8","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a352aecaac6403c9ea5013a95dbe945e910d71bc652d01a07313977398158711?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a352aecaac6403c9ea5013a95dbe945e910d71bc652d01a07313977398158711?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/skgd.pl\/de\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/32812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/comments?post=32812"}],"version-history":[{"count":2,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/32812\/revisions"}],"predecessor-version":[{"id":32815,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/32812\/revisions\/32815"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media\/32813"}],"wp:attachment":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media?parent=32812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/categories?post=32812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/tags?post=32812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}