{"id":32446,"date":"2023-05-05T10:00:09","date_gmt":"2023-05-05T08:00:09","guid":{"rendered":"https:\/\/skgd.pl\/?p=32446"},"modified":"2023-05-08T08:17:39","modified_gmt":"2023-05-08T06:17:39","slug":"wsparcie-finansowe-koncertow-powiatowych-2023","status":"publish","type":"post","link":"https:\/\/skgd.pl\/de\/wsparcie-finansowe-koncertow-powiatowych-2023\/","title":{"rendered":"Finanzielle Unterst\u00fctzung f\u00fcr die Kreiskonzerte 2023!"},"content":{"rendered":"<p>Sehr geehrte Damen und Herren,<\/p>\n<p>wir freuen uns, Ihnen mitteilen zu k\u00f6nnen, dass am 28.04.2023<span> die Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien einen Vertrag Nr. 6-73\/WMNiE\/2023 mit dem Ministerium f\u00fcr Inneres und Verwaltung, der Abteilung f\u00fcr religi\u00f6se Konfessionen sowie nationale und ethnische Minderheiten zur Umsetzung der Aufgabe&nbsp;<\/span><em>\u201eKreiskonzerte &#8211; Deutsche musikalische Minderheit<\/em><em>\u201d <\/em>unterzeichnete.<\/p>\n<p>Wir bedanken uns f\u00fcr die Unterst\u00fctzung.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sehr geehrte Damen und Herren, wir freuen uns, Ihnen mitteilen zu k\u00f6nnen, dass am 28.04.2023 die Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien einen Vertrag Nr. 6-73\/WMNiE\/2023 mit dem Ministerium f\u00fcr Inneres und Verwaltung, der Abteilung f\u00fcr religi\u00f6se Konfessionen sowie nationale und ethnische Minderheiten zur Umsetzung der Aufgabe&nbsp;\u201eKreiskonzerte &#8211; Deutsche musikalische Minderheit\u201d unterzeichnete. Wir bedanken [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":32450,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[733,1],"tags":[],"class_list":["post-32446","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kultura","category-aktualnosci"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Finanzielle Unterst\u00fctzung f\u00fcr die Kreiskonzerte 2023! - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skgd.pl\/de\/wsparcie-finansowe-koncertow-powiatowych-2023\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Finanzielle Unterst\u00fctzung f\u00fcr die Kreiskonzerte 2023! - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"og:description\" content=\"Sehr geehrte Damen und Herren, wir freuen uns, Ihnen mitteilen zu k\u00f6nnen, dass am 28.04.2023 die Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien einen Vertrag Nr. 6-73\/WMNiE\/2023 mit dem Ministerium f\u00fcr Inneres und Verwaltung, der Abteilung f\u00fcr religi\u00f6se Konfessionen sowie nationale und ethnische Minderheiten zur Umsetzung der Aufgabe&nbsp;\u201eKreiskonzerte &#8211; Deutsche musikalische Minderheit\u201d unterzeichnete. Wir bedanken [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skgd.pl\/de\/wsparcie-finansowe-koncertow-powiatowych-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-05T08:00:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-08T06:17:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skgd.pl\/wp-content\/uploads\/2023\/05\/\u201eKoncerty-powiatowe-Muzyczna-Mniejszosc-Niemiecka-\u201eKreiskonzerte-Deutsche-musikalische-Minderheit.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Bewko\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skgd.pl\/#website\",\"url\":\"https:\/\/skgd.pl\/\",\"name\":\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"description\":\"Deutsche Minderheit in Polen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skgd.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/de\/wsparcie-finansowe-koncertow-powiatowych-2023\/#primaryimage\",\"url\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2023\/05\/\u201eKoncerty-powiatowe-Muzyczna-Mniejszosc-Niemiecka-\u201eKreiskonzerte-Deutsche-musikalische-Minderheit.png\",\"contentUrl\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2023\/05\/\u201eKoncerty-powiatowe-Muzyczna-Mniejszosc-Niemiecka-\u201eKreiskonzerte-Deutsche-musikalische-Minderheit.png\",\"width\":1080,\"height\":1080},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skgd.pl\/de\/wsparcie-finansowe-koncertow-powiatowych-2023\/#webpage\",\"url\":\"https:\/\/skgd.pl\/de\/wsparcie-finansowe-koncertow-powiatowych-2023\/\",\"name\":\"Finanzielle Unterst\u00fctzung f\u00fcr die Kreiskonzerte 2023! - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"isPartOf\":{\"@id\":\"https:\/\/skgd.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skgd.pl\/de\/wsparcie-finansowe-koncertow-powiatowych-2023\/#primaryimage\"},\"datePublished\":\"2023-05-05T08:00:09+00:00\",\"dateModified\":\"2023-05-08T06:17:39+00:00\",\"author\":{\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/3fb073cb271b54c7c3d73598166a8846\"},\"breadcrumb\":{\"@id\":\"https:\/\/skgd.pl\/de\/wsparcie-finansowe-koncertow-powiatowych-2023\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skgd.pl\/de\/wsparcie-finansowe-koncertow-powiatowych-2023\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skgd.pl\/de\/wsparcie-finansowe-koncertow-powiatowych-2023\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/skgd.pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Finanzielle Unterst\u00fctzung f\u00fcr die Kreiskonzerte 2023!\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/3fb073cb271b54c7c3d73598166a8846\",\"name\":\"Daniel Bewko\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/58105dc9f309bee138f8b2d07926d45653268d482d54de84622dc38b358069e5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/58105dc9f309bee138f8b2d07926d45653268d482d54de84622dc38b358069e5?s=96&d=mm&r=g\",\"caption\":\"Daniel Bewko\"},\"url\":\"https:\/\/skgd.pl\/de\/author\/daniel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Finanzielle Unterst\u00fctzung f\u00fcr die Kreiskonzerte 2023! - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skgd.pl\/de\/wsparcie-finansowe-koncertow-powiatowych-2023\/","og_locale":"de_DE","og_type":"article","og_title":"Finanzielle Unterst\u00fctzung f\u00fcr die Kreiskonzerte 2023! - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","og_description":"Sehr geehrte Damen und Herren, wir freuen uns, Ihnen mitteilen zu k\u00f6nnen, dass am 28.04.2023 die Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien einen Vertrag Nr. 6-73\/WMNiE\/2023 mit dem Ministerium f\u00fcr Inneres und Verwaltung, der Abteilung f\u00fcr religi\u00f6se Konfessionen sowie nationale und ethnische Minderheiten zur Umsetzung der Aufgabe&nbsp;\u201eKreiskonzerte &#8211; Deutsche musikalische Minderheit\u201d unterzeichnete. Wir bedanken [&hellip;]","og_url":"https:\/\/skgd.pl\/de\/wsparcie-finansowe-koncertow-powiatowych-2023\/","og_site_name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","article_published_time":"2023-05-05T08:00:09+00:00","article_modified_time":"2023-05-08T06:17:39+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/skgd.pl\/wp-content\/uploads\/2023\/05\/\u201eKoncerty-powiatowe-Muzyczna-Mniejszosc-Niemiecka-\u201eKreiskonzerte-Deutsche-musikalische-Minderheit.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Daniel Bewko","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/skgd.pl\/#website","url":"https:\/\/skgd.pl\/","name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","description":"Deutsche Minderheit in Polen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skgd.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/de\/wsparcie-finansowe-koncertow-powiatowych-2023\/#primaryimage","url":"https:\/\/skgd.pl\/wp-content\/uploads\/2023\/05\/\u201eKoncerty-powiatowe-Muzyczna-Mniejszosc-Niemiecka-\u201eKreiskonzerte-Deutsche-musikalische-Minderheit.png","contentUrl":"https:\/\/skgd.pl\/wp-content\/uploads\/2023\/05\/\u201eKoncerty-powiatowe-Muzyczna-Mniejszosc-Niemiecka-\u201eKreiskonzerte-Deutsche-musikalische-Minderheit.png","width":1080,"height":1080},{"@type":"WebPage","@id":"https:\/\/skgd.pl\/de\/wsparcie-finansowe-koncertow-powiatowych-2023\/#webpage","url":"https:\/\/skgd.pl\/de\/wsparcie-finansowe-koncertow-powiatowych-2023\/","name":"Finanzielle Unterst\u00fctzung f\u00fcr die Kreiskonzerte 2023! - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","isPartOf":{"@id":"https:\/\/skgd.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skgd.pl\/de\/wsparcie-finansowe-koncertow-powiatowych-2023\/#primaryimage"},"datePublished":"2023-05-05T08:00:09+00:00","dateModified":"2023-05-08T06:17:39+00:00","author":{"@id":"https:\/\/skgd.pl\/#\/schema\/person\/3fb073cb271b54c7c3d73598166a8846"},"breadcrumb":{"@id":"https:\/\/skgd.pl\/de\/wsparcie-finansowe-koncertow-powiatowych-2023\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skgd.pl\/de\/wsparcie-finansowe-koncertow-powiatowych-2023\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/skgd.pl\/de\/wsparcie-finansowe-koncertow-powiatowych-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/skgd.pl\/"},{"@type":"ListItem","position":2,"name":"Finanzielle Unterst\u00fctzung f\u00fcr die Kreiskonzerte 2023!"}]},{"@type":"Person","@id":"https:\/\/skgd.pl\/#\/schema\/person\/3fb073cb271b54c7c3d73598166a8846","name":"Daniel Bewko","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/58105dc9f309bee138f8b2d07926d45653268d482d54de84622dc38b358069e5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/58105dc9f309bee138f8b2d07926d45653268d482d54de84622dc38b358069e5?s=96&d=mm&r=g","caption":"Daniel Bewko"},"url":"https:\/\/skgd.pl\/de\/author\/daniel\/"}]}},"_links":{"self":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/32446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/comments?post=32446"}],"version-history":[{"count":3,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/32446\/revisions"}],"predecessor-version":[{"id":32459,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/32446\/revisions\/32459"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media\/32450"}],"wp:attachment":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media?parent=32446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/categories?post=32446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/tags?post=32446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}