{"id":31307,"date":"2022-12-05T10:00:35","date_gmt":"2022-12-05T09:00:35","guid":{"rendered":"https:\/\/skgd.pl\/?p=31307"},"modified":"2022-12-02T14:04:47","modified_gmt":"2022-12-02T13:04:47","slug":"wydanie-ksiazki-wielowarstwowy-kolaz-marianny-roth","status":"publish","type":"post","link":"https:\/\/skgd.pl\/de\/wydanie-ksiazki-wielowarstwowy-kolaz-marianny-roth\/","title":{"rendered":"Ver\u00f6ffentlichung des Buches \u201cEine Vielschichtige Collage\u201d von Marianna Roth"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: justify;\"><span>Das Haus der Deutsch-Polnischen Zusammenarbeit und die SKGD laden herzlich zu<\/span> <span>einem<\/span> <span>Treffen<\/span> <span>zur<\/span> <span>Ank\u00fcndigung<\/span> <span>der<\/span> <span>Ver\u00f6ffentlichung<\/span> <span>des<\/span> <span>Buches<\/span> <span>\u201cEine Vielschichtige<\/span> <span>Collage\u201d<\/span> <span>von<\/span> <span>Marianna<\/span> <span>Roth<\/span>, <span>einer<\/span> <span>in<\/span> <span>Oppeln<\/span> <span>geborenen<\/span> <span>J\u00fcdin<\/span>, am <span>10<\/span>. Dezember <span>2022<\/span> <span>um<\/span> <span>15<\/span>. <span>00<\/span> <span>Uhr<\/span> <span>in das<\/span> <span>Dokumentations<\/span>&#8211; <span>und<\/span> <span>Ausstellungszentrum<\/span> der Deutschen Minderheit <span>in<\/span> <span>Oppeln<\/span> <span>an<\/span> <span>der<\/span> <span>Szpitalna-Stra\u00dfe<\/span> <span>11<\/span>.<\/p>\n<p style=\"text-align: justify;\"><span>Moderiert<\/span> <span>wird<\/span> <span>das<\/span> <span>Treffen<\/span> <span>von<\/span> <span>Frau<\/span> <span>Beata<\/span> <span>Kubica<\/span> <span>und<\/span> <span>Herrn<\/span> <span>Gerhard<\/span> <span>Schiller<\/span>, <span>die<\/span> <span>das<\/span> <span>Buch<\/span> <span>\u00fcbersetzt<\/span> <span>und<\/span> <span>bearbeitet<\/span> <span>haben<\/span>. <span>Diese<\/span> <span>Publikation<\/span> <span>wird<\/span> <span>einzigartig<\/span> <span>sein<\/span>, <span>denn<\/span> <span>sie<\/span> <span>ist<\/span> <span>ein<\/span> <span>einzigartiges<\/span> <span>Material<\/span>, <span>das<\/span> <span>ein<\/span> <span>neues<\/span>, <span>bisher<\/span> <span>unbekanntes<\/span> <span>Kapitel<\/span> <span>in<\/span> <span>der<\/span> <span>Geschichte<\/span> <span>Oppelns<\/span> <span>zeigt<\/span>, <span>in<\/span> <span>dem<\/span> <span>das<\/span> <span>Schicksal<\/span> <span>der<\/span> <span>Menschen<\/span> <span>j\u00fcdischer<\/span> <span>Herkunft<\/span> <span>beschrieben<\/span> <span>wird<\/span>.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Das Haus der Deutsch-Polnischen Zusammenarbeit und die SKGD laden herzlich zu einem Treffen zur Ank\u00fcndigung der Ver\u00f6ffentlichung des Buches \u201cEine Vielschichtige Collage\u201d von Marianna Roth, einer in Oppeln geborenen J\u00fcdin, am 10. Dezember 2022 um 15. 00 Uhr in das Dokumentations&#8211; und Ausstellungszentrum der Deutschen Minderheit in Oppeln an der Szpitalna-Stra\u00dfe 11. Moderiert wird das [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":31308,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-31307","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktualnosci"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ver\u00f6ffentlichung des Buches \u201cEine Vielschichtige Collage\u201d von Marianna Roth - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skgd.pl\/de\/wydanie-ksiazki-wielowarstwowy-kolaz-marianny-roth\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ver\u00f6ffentlichung des Buches \u201cEine Vielschichtige Collage\u201d von Marianna Roth - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"og:description\" content=\"Das Haus der Deutsch-Polnischen Zusammenarbeit und die SKGD laden herzlich zu einem Treffen zur Ank\u00fcndigung der Ver\u00f6ffentlichung des Buches \u201cEine Vielschichtige Collage\u201d von Marianna Roth, einer in Oppeln geborenen J\u00fcdin, am 10. Dezember 2022 um 15. 00 Uhr in das Dokumentations&#8211; und Ausstellungszentrum der Deutschen Minderheit in Oppeln an der Szpitalna-Stra\u00dfe 11. Moderiert wird das [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skgd.pl\/de\/wydanie-ksiazki-wielowarstwowy-kolaz-marianny-roth\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-05T09:00:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-02T13:04:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skgd.pl\/wp-content\/uploads\/2022\/12\/Aurelia-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1587\" \/>\n\t<meta property=\"og:image:height\" content=\"2245\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joanna Hassa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skgd.pl\/#website\",\"url\":\"https:\/\/skgd.pl\/\",\"name\":\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"description\":\"Deutsche Minderheit in Polen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skgd.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/de\/wydanie-ksiazki-wielowarstwowy-kolaz-marianny-roth\/#primaryimage\",\"url\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2022\/12\/Aurelia-1.jpg\",\"contentUrl\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2022\/12\/Aurelia-1.jpg\",\"width\":1587,\"height\":2245},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skgd.pl\/de\/wydanie-ksiazki-wielowarstwowy-kolaz-marianny-roth\/#webpage\",\"url\":\"https:\/\/skgd.pl\/de\/wydanie-ksiazki-wielowarstwowy-kolaz-marianny-roth\/\",\"name\":\"Ver\u00f6ffentlichung des Buches \u201cEine Vielschichtige Collage\u201d von Marianna Roth - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"isPartOf\":{\"@id\":\"https:\/\/skgd.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skgd.pl\/de\/wydanie-ksiazki-wielowarstwowy-kolaz-marianny-roth\/#primaryimage\"},\"datePublished\":\"2022-12-05T09:00:35+00:00\",\"dateModified\":\"2022-12-02T13:04:47+00:00\",\"author\":{\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\"},\"breadcrumb\":{\"@id\":\"https:\/\/skgd.pl\/de\/wydanie-ksiazki-wielowarstwowy-kolaz-marianny-roth\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skgd.pl\/de\/wydanie-ksiazki-wielowarstwowy-kolaz-marianny-roth\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skgd.pl\/de\/wydanie-ksiazki-wielowarstwowy-kolaz-marianny-roth\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/skgd.pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ver\u00f6ffentlichung des Buches \u201cEine Vielschichtige Collage\u201d von Marianna Roth\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\",\"name\":\"Joanna Hassa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"caption\":\"Joanna Hassa\"},\"url\":\"https:\/\/skgd.pl\/de\/author\/asia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ver\u00f6ffentlichung des Buches \u201cEine Vielschichtige Collage\u201d von Marianna Roth - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skgd.pl\/de\/wydanie-ksiazki-wielowarstwowy-kolaz-marianny-roth\/","og_locale":"de_DE","og_type":"article","og_title":"Ver\u00f6ffentlichung des Buches \u201cEine Vielschichtige Collage\u201d von Marianna Roth - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","og_description":"Das Haus der Deutsch-Polnischen Zusammenarbeit und die SKGD laden herzlich zu einem Treffen zur Ank\u00fcndigung der Ver\u00f6ffentlichung des Buches \u201cEine Vielschichtige Collage\u201d von Marianna Roth, einer in Oppeln geborenen J\u00fcdin, am 10. Dezember 2022 um 15. 00 Uhr in das Dokumentations&#8211; und Ausstellungszentrum der Deutschen Minderheit in Oppeln an der Szpitalna-Stra\u00dfe 11. Moderiert wird das [&hellip;]","og_url":"https:\/\/skgd.pl\/de\/wydanie-ksiazki-wielowarstwowy-kolaz-marianny-roth\/","og_site_name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","article_published_time":"2022-12-05T09:00:35+00:00","article_modified_time":"2022-12-02T13:04:47+00:00","og_image":[{"width":1587,"height":2245,"url":"https:\/\/skgd.pl\/wp-content\/uploads\/2022\/12\/Aurelia-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Joanna Hassa","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/skgd.pl\/#website","url":"https:\/\/skgd.pl\/","name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","description":"Deutsche Minderheit in Polen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skgd.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/de\/wydanie-ksiazki-wielowarstwowy-kolaz-marianny-roth\/#primaryimage","url":"https:\/\/skgd.pl\/wp-content\/uploads\/2022\/12\/Aurelia-1.jpg","contentUrl":"https:\/\/skgd.pl\/wp-content\/uploads\/2022\/12\/Aurelia-1.jpg","width":1587,"height":2245},{"@type":"WebPage","@id":"https:\/\/skgd.pl\/de\/wydanie-ksiazki-wielowarstwowy-kolaz-marianny-roth\/#webpage","url":"https:\/\/skgd.pl\/de\/wydanie-ksiazki-wielowarstwowy-kolaz-marianny-roth\/","name":"Ver\u00f6ffentlichung des Buches \u201cEine Vielschichtige Collage\u201d von Marianna Roth - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","isPartOf":{"@id":"https:\/\/skgd.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skgd.pl\/de\/wydanie-ksiazki-wielowarstwowy-kolaz-marianny-roth\/#primaryimage"},"datePublished":"2022-12-05T09:00:35+00:00","dateModified":"2022-12-02T13:04:47+00:00","author":{"@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03"},"breadcrumb":{"@id":"https:\/\/skgd.pl\/de\/wydanie-ksiazki-wielowarstwowy-kolaz-marianny-roth\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skgd.pl\/de\/wydanie-ksiazki-wielowarstwowy-kolaz-marianny-roth\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/skgd.pl\/de\/wydanie-ksiazki-wielowarstwowy-kolaz-marianny-roth\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/skgd.pl\/"},{"@type":"ListItem","position":2,"name":"Ver\u00f6ffentlichung des Buches \u201cEine Vielschichtige Collage\u201d von Marianna Roth"}]},{"@type":"Person","@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03","name":"Joanna Hassa","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","caption":"Joanna Hassa"},"url":"https:\/\/skgd.pl\/de\/author\/asia\/"}]}},"_links":{"self":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/31307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/comments?post=31307"}],"version-history":[{"count":2,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/31307\/revisions"}],"predecessor-version":[{"id":31310,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/31307\/revisions\/31310"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media\/31308"}],"wp:attachment":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media?parent=31307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/categories?post=31307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/tags?post=31307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}