{"id":31213,"date":"2022-12-03T16:10:17","date_gmt":"2022-12-03T15:10:17","guid":{"rendered":"https:\/\/skgd.pl\/?p=31213"},"modified":"2022-11-23T16:11:51","modified_gmt":"2022-11-23T15:11:51","slug":"deutschstammtisch-20-12-2022","status":"publish","type":"post","link":"https:\/\/skgd.pl\/de\/deutschstammtisch-20-12-2022\/","title":{"rendered":"Deutschstammtisch, 20.12.2022"},"content":{"rendered":"<p><span>Hall\u00f6chen,<\/span><br \/>\n<span>Es ist wieder Stammtisch Zeit!<\/span><br \/>\n<span>Auch dieses Mal treffen wir uns in cooler und entspannter Atmosph\u00e4re am Nachmittag und bleiben beim Stammtisch gerne auch bis zum Abend mit der deutschen Sprache am Tisch!<\/span><br \/>\n<span>Alle k\u00f6nnen mitmachen! Denkt aber daran \u2013 beim Stammtisch wird Deutsch gesprochen (Aber keine Angst! Kein Meister ist noch vom Himmel gefallen, das hei\u00dft so viel wie: Ihr m\u00fcsst es nicht perfekt sprechen!).<\/span><br \/>\n<span>Wir treffen uns dieses Mal bei einer weihnachtlichen Stimmung! Wer Lust auf Weihnachtsstimmung hat, ist herzlich auf den Oppelner Ring eingeladen, wo der Weihnachtsmarkt stattfindet und wo wir uns diesmal treffen werden! Ihr m\u00fcsst unbedingt dabei sein!<\/span><br \/>\n<span>Du wei\u00dft nicht, wor\u00fcber du sprechen kannst? Kein Stress \u2013 uns f\u00e4llt schon was ein!<\/span><br \/>\n<span>Wir sehen uns am 20.12.2022 (Dienstag). Start um 17.00 Uhr.<\/span><br \/>\n<span>Der Stammtisch wird traditionell vom DFK Oppeln-Zentrum organisiert.<\/span><br \/>\n<span>Du bist kein Mitglied des DFKs? Das ist \u00fcberhaupt kein Problem!!!<\/span><br \/>\n<span>Komm einfach vorbei und sprich!<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Hall\u00f6chen, Es ist wieder Stammtisch Zeit! Auch dieses Mal treffen wir uns in cooler und entspannter Atmosph\u00e4re am Nachmittag und bleiben beim Stammtisch gerne auch bis zum Abend mit der deutschen Sprache am Tisch! Alle k\u00f6nnen mitmachen! Denkt aber daran \u2013 beim Stammtisch wird Deutsch gesprochen (Aber keine Angst! Kein Meister ist noch vom Himmel [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":31214,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[666],"tags":[],"class_list":["post-31213","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dfk-opole-centrum"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Deutschstammtisch, 20.12.2022 - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skgd.pl\/de\/deutschstammtisch-20-12-2022\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deutschstammtisch, 20.12.2022 - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"og:description\" content=\"Hall\u00f6chen, Es ist wieder Stammtisch Zeit! Auch dieses Mal treffen wir uns in cooler und entspannter Atmosph\u00e4re am Nachmittag und bleiben beim Stammtisch gerne auch bis zum Abend mit der deutschen Sprache am Tisch! Alle k\u00f6nnen mitmachen! Denkt aber daran \u2013 beim Stammtisch wird Deutsch gesprochen (Aber keine Angst! Kein Meister ist noch vom Himmel [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skgd.pl\/de\/deutschstammtisch-20-12-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-03T15:10:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-23T15:11:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skgd.pl\/wp-content\/uploads\/2022\/11\/Stammtisch-8.png\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joanna Hassa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skgd.pl\/#website\",\"url\":\"https:\/\/skgd.pl\/\",\"name\":\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"description\":\"Deutsche Minderheit in Polen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skgd.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/de\/deutschstammtisch-20-12-2022\/#primaryimage\",\"url\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2022\/11\/Stammtisch-8.png\",\"contentUrl\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2022\/11\/Stammtisch-8.png\",\"width\":940,\"height\":788},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skgd.pl\/de\/deutschstammtisch-20-12-2022\/#webpage\",\"url\":\"https:\/\/skgd.pl\/de\/deutschstammtisch-20-12-2022\/\",\"name\":\"Deutschstammtisch, 20.12.2022 - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"isPartOf\":{\"@id\":\"https:\/\/skgd.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skgd.pl\/de\/deutschstammtisch-20-12-2022\/#primaryimage\"},\"datePublished\":\"2022-12-03T15:10:17+00:00\",\"dateModified\":\"2022-11-23T15:11:51+00:00\",\"author\":{\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\"},\"breadcrumb\":{\"@id\":\"https:\/\/skgd.pl\/de\/deutschstammtisch-20-12-2022\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skgd.pl\/de\/deutschstammtisch-20-12-2022\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skgd.pl\/de\/deutschstammtisch-20-12-2022\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/skgd.pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deutschstammtisch, 20.12.2022\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\",\"name\":\"Joanna Hassa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"caption\":\"Joanna Hassa\"},\"url\":\"https:\/\/skgd.pl\/de\/author\/asia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deutschstammtisch, 20.12.2022 - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skgd.pl\/de\/deutschstammtisch-20-12-2022\/","og_locale":"de_DE","og_type":"article","og_title":"Deutschstammtisch, 20.12.2022 - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","og_description":"Hall\u00f6chen, Es ist wieder Stammtisch Zeit! Auch dieses Mal treffen wir uns in cooler und entspannter Atmosph\u00e4re am Nachmittag und bleiben beim Stammtisch gerne auch bis zum Abend mit der deutschen Sprache am Tisch! Alle k\u00f6nnen mitmachen! Denkt aber daran \u2013 beim Stammtisch wird Deutsch gesprochen (Aber keine Angst! Kein Meister ist noch vom Himmel [&hellip;]","og_url":"https:\/\/skgd.pl\/de\/deutschstammtisch-20-12-2022\/","og_site_name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","article_published_time":"2022-12-03T15:10:17+00:00","article_modified_time":"2022-11-23T15:11:51+00:00","og_image":[{"width":940,"height":788,"url":"https:\/\/skgd.pl\/wp-content\/uploads\/2022\/11\/Stammtisch-8.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Joanna Hassa","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/skgd.pl\/#website","url":"https:\/\/skgd.pl\/","name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","description":"Deutsche Minderheit in Polen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skgd.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/de\/deutschstammtisch-20-12-2022\/#primaryimage","url":"https:\/\/skgd.pl\/wp-content\/uploads\/2022\/11\/Stammtisch-8.png","contentUrl":"https:\/\/skgd.pl\/wp-content\/uploads\/2022\/11\/Stammtisch-8.png","width":940,"height":788},{"@type":"WebPage","@id":"https:\/\/skgd.pl\/de\/deutschstammtisch-20-12-2022\/#webpage","url":"https:\/\/skgd.pl\/de\/deutschstammtisch-20-12-2022\/","name":"Deutschstammtisch, 20.12.2022 - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","isPartOf":{"@id":"https:\/\/skgd.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skgd.pl\/de\/deutschstammtisch-20-12-2022\/#primaryimage"},"datePublished":"2022-12-03T15:10:17+00:00","dateModified":"2022-11-23T15:11:51+00:00","author":{"@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03"},"breadcrumb":{"@id":"https:\/\/skgd.pl\/de\/deutschstammtisch-20-12-2022\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skgd.pl\/de\/deutschstammtisch-20-12-2022\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/skgd.pl\/de\/deutschstammtisch-20-12-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/skgd.pl\/"},{"@type":"ListItem","position":2,"name":"Deutschstammtisch, 20.12.2022"}]},{"@type":"Person","@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03","name":"Joanna Hassa","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","caption":"Joanna Hassa"},"url":"https:\/\/skgd.pl\/de\/author\/asia\/"}]}},"_links":{"self":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/31213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/comments?post=31213"}],"version-history":[{"count":1,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/31213\/revisions"}],"predecessor-version":[{"id":31215,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/31213\/revisions\/31215"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media\/31214"}],"wp:attachment":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media?parent=31213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/categories?post=31213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/tags?post=31213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}