{"id":29999,"date":"2022-07-07T11:27:04","date_gmt":"2022-07-07T09:27:04","guid":{"rendered":"https:\/\/skgd.pl\/?p=29999"},"modified":"2022-07-07T11:27:04","modified_gmt":"2022-07-07T09:27:04","slug":"kalendarz-z-zycia-tskn","status":"publish","type":"post","link":"https:\/\/skgd.pl\/de\/kalendarz-z-zycia-tskn\/","title":{"rendered":"Kalender &#8220;Aus dem Leben der SKGD&#8221;"},"content":{"rendered":"<p><\/p>\n<div class=\"txt-2\">\n<div class=\"txt-3\">\n<p>Am 28. Juni 2022 unterzeichnete die Sozial-Kulturelle Gesellschaft der Deutschen in Oppelner-Schlesien den Vertrag 4-83\/WMNiE\/2022 mit dem Polnischen Ministerium f\u00fcr Inneres und Verwaltung, Abteilung f\u00fcr religi\u00f6se Konfessionen sowie nationale und ethnische Minderheiten zur Umsetzung der Aufgabe \u201cKalender &#8220;Aus dem Leben der SKGD&#8221;\u201d.<\/p>\n<p>Wir bedanken uns f\u00fcr die Zuwendung und ermutigen Sie, das Projekt in den Medien der SKGD zu verfolgen<\/p>\n<div class=\"pagination\">&nbsp;<\/div>\n<\/div>\n<\/div>\n<div class=\"clearfix\">&nbsp;<\/div>\n<div class=\"a2a_kit a2a_kit_size_32 addtoany_list\">&nbsp;<\/div>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Am 28. Juni 2022 unterzeichnete die Sozial-Kulturelle Gesellschaft der Deutschen in Oppelner-Schlesien den Vertrag 4-83\/WMNiE\/2022 mit dem Polnischen Ministerium f\u00fcr Inneres und Verwaltung, Abteilung f\u00fcr religi\u00f6se Konfessionen sowie nationale und ethnische Minderheiten zur Umsetzung der Aufgabe \u201cKalender &#8220;Aus dem Leben der SKGD&#8221;\u201d. Wir bedanken uns f\u00fcr die Zuwendung und ermutigen Sie, das Projekt in den [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":29993,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-29999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktualnosci"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kalender &quot;Aus dem Leben der SKGD&quot; - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skgd.pl\/kalendarz-z-zycia-tskn\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kalender &quot;Aus dem Leben der SKGD&quot; - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"og:description\" content=\"Am 28. Juni 2022 unterzeichnete die Sozial-Kulturelle Gesellschaft der Deutschen in Oppelner-Schlesien den Vertrag 4-83\/WMNiE\/2022 mit dem Polnischen Ministerium f\u00fcr Inneres und Verwaltung, Abteilung f\u00fcr religi\u00f6se Konfessionen sowie nationale und ethnische Minderheiten zur Umsetzung der Aufgabe \u201cKalender &#8220;Aus dem Leben der SKGD&#8221;\u201d. Wir bedanken uns f\u00fcr die Zuwendung und ermutigen Sie, das Projekt in den [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skgd.pl\/kalendarz-z-zycia-tskn\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-07T09:27:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skgd.pl\/wp-content\/uploads\/2022\/06\/Kalendarz-Z-Zycia-TSKN-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"andrea.pownuk@skgd.pl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skgd.pl\/#website\",\"url\":\"https:\/\/skgd.pl\/\",\"name\":\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"description\":\"Deutsche Minderheit in Polen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skgd.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/kalendarz-z-zycia-tskn\/#primaryimage\",\"url\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2022\/06\/Kalendarz-Z-Zycia-TSKN-1.png\",\"contentUrl\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2022\/06\/Kalendarz-Z-Zycia-TSKN-1.png\",\"width\":940,\"height\":788},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skgd.pl\/kalendarz-z-zycia-tskn\/#webpage\",\"url\":\"https:\/\/skgd.pl\/kalendarz-z-zycia-tskn\/\",\"name\":\"Kalender \\\"Aus dem Leben der SKGD\\\" - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"isPartOf\":{\"@id\":\"https:\/\/skgd.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skgd.pl\/kalendarz-z-zycia-tskn\/#primaryimage\"},\"datePublished\":\"2022-07-07T09:27:04+00:00\",\"dateModified\":\"2022-07-07T09:27:04+00:00\",\"author\":{\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/85c707754c582098cd63fe84414fb7ec\"},\"breadcrumb\":{\"@id\":\"https:\/\/skgd.pl\/kalendarz-z-zycia-tskn\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skgd.pl\/kalendarz-z-zycia-tskn\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skgd.pl\/kalendarz-z-zycia-tskn\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/skgd.pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kalendarz &#8220;Z \u017cycia TSKN&#8221;\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/85c707754c582098cd63fe84414fb7ec\",\"name\":\"andrea.pownuk@skgd.pl\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3ae87e01af6182433e0c29b1952ba9d59afe546a3da14aeba66cd40124d56192?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3ae87e01af6182433e0c29b1952ba9d59afe546a3da14aeba66cd40124d56192?s=96&d=mm&r=g\",\"caption\":\"andrea.pownuk@skgd.pl\"},\"url\":\"https:\/\/skgd.pl\/de\/author\/andrea-pownukskgd-pl\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kalender \"Aus dem Leben der SKGD\" - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skgd.pl\/kalendarz-z-zycia-tskn\/","og_locale":"de_DE","og_type":"article","og_title":"Kalender \"Aus dem Leben der SKGD\" - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","og_description":"Am 28. Juni 2022 unterzeichnete die Sozial-Kulturelle Gesellschaft der Deutschen in Oppelner-Schlesien den Vertrag 4-83\/WMNiE\/2022 mit dem Polnischen Ministerium f\u00fcr Inneres und Verwaltung, Abteilung f\u00fcr religi\u00f6se Konfessionen sowie nationale und ethnische Minderheiten zur Umsetzung der Aufgabe \u201cKalender &#8220;Aus dem Leben der SKGD&#8221;\u201d. Wir bedanken uns f\u00fcr die Zuwendung und ermutigen Sie, das Projekt in den [&hellip;]","og_url":"https:\/\/skgd.pl\/kalendarz-z-zycia-tskn\/","og_site_name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","article_published_time":"2022-07-07T09:27:04+00:00","og_image":[{"width":940,"height":788,"url":"https:\/\/skgd.pl\/wp-content\/uploads\/2022\/06\/Kalendarz-Z-Zycia-TSKN-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"andrea.pownuk@skgd.pl","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/skgd.pl\/#website","url":"https:\/\/skgd.pl\/","name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","description":"Deutsche Minderheit in Polen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skgd.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/kalendarz-z-zycia-tskn\/#primaryimage","url":"https:\/\/skgd.pl\/wp-content\/uploads\/2022\/06\/Kalendarz-Z-Zycia-TSKN-1.png","contentUrl":"https:\/\/skgd.pl\/wp-content\/uploads\/2022\/06\/Kalendarz-Z-Zycia-TSKN-1.png","width":940,"height":788},{"@type":"WebPage","@id":"https:\/\/skgd.pl\/kalendarz-z-zycia-tskn\/#webpage","url":"https:\/\/skgd.pl\/kalendarz-z-zycia-tskn\/","name":"Kalender \"Aus dem Leben der SKGD\" - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","isPartOf":{"@id":"https:\/\/skgd.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skgd.pl\/kalendarz-z-zycia-tskn\/#primaryimage"},"datePublished":"2022-07-07T09:27:04+00:00","dateModified":"2022-07-07T09:27:04+00:00","author":{"@id":"https:\/\/skgd.pl\/#\/schema\/person\/85c707754c582098cd63fe84414fb7ec"},"breadcrumb":{"@id":"https:\/\/skgd.pl\/kalendarz-z-zycia-tskn\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skgd.pl\/kalendarz-z-zycia-tskn\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/skgd.pl\/kalendarz-z-zycia-tskn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/skgd.pl\/"},{"@type":"ListItem","position":2,"name":"Kalendarz &#8220;Z \u017cycia TSKN&#8221;"}]},{"@type":"Person","@id":"https:\/\/skgd.pl\/#\/schema\/person\/85c707754c582098cd63fe84414fb7ec","name":"andrea.pownuk@skgd.pl","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3ae87e01af6182433e0c29b1952ba9d59afe546a3da14aeba66cd40124d56192?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ae87e01af6182433e0c29b1952ba9d59afe546a3da14aeba66cd40124d56192?s=96&d=mm&r=g","caption":"andrea.pownuk@skgd.pl"},"url":"https:\/\/skgd.pl\/de\/author\/andrea-pownukskgd-pl\/"}]}},"_links":{"self":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/29999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/comments?post=29999"}],"version-history":[{"count":2,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/29999\/revisions"}],"predecessor-version":[{"id":30001,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/29999\/revisions\/30001"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media\/29993"}],"wp:attachment":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media?parent=29999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/categories?post=29999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/tags?post=29999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}