{"id":28765,"date":"2022-03-08T11:30:39","date_gmt":"2022-03-08T10:30:39","guid":{"rendered":"https:\/\/skgd.pl\/?p=28765"},"modified":"2022-03-08T14:50:04","modified_gmt":"2022-03-08T13:50:04","slug":"13-000-osob-podpisalo-petycje-rodzicow-przeciw-zmniejszeniu-subwencji-na-nauke-niemieckiego-jako-jezyka-mniejszosci","status":"publish","type":"post","link":"https:\/\/skgd.pl\/de\/13-000-osob-podpisalo-petycje-rodzicow-przeciw-zmniejszeniu-subwencji-na-nauke-niemieckiego-jako-jezyka-mniejszosci\/","title":{"rendered":"13.000 Menschen unterzeichnen eine Elternpetition gegen die K\u00fcrzung der Zusch\u00fcsse f\u00fcr den Unterricht von Deutsch als Minderheitensprache"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: justify;\"><strong>Im Dezember, kurz nach der Entscheidung des Sejm, die Subventionen f\u00fcr den Unterricht von Deutsch als Minderheitensprache im Haushalt 2022 zu k\u00fcrzen, begannen Eltern mit der Sammlung von Unterschriften f\u00fcr eine Petition gegen diese Entscheidung. <em>Sie nimmt unseren Kindern Chancen und diskriminiert sie<\/em> &#8211; sagten einstimmig Vertreter von Eltern, Lehrern und Vertretern der deutschen Minderheit, die heute (8.03) die Petition mit Unterschriften an das Ministerium f\u00fcr Bildung und Wissenschaft \u00fcbergaben. Die Petition wurde elektronisch von 9807 Personen und auf Papier von 3415 Personen unterzeichnet.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Agnieszka Ka\u0142a, Schuldirektorin, Lehrerin, Initiatorin der Petition:<\/strong>&nbsp;<em>Dank der vielen Unterschriften unter unserer Petition bin ich davon \u00fcberzeugt, dass meine Meinung und meine Bedenken von vielen besorgten Eltern und Lehrern geteilt werden. Als Deutschlehrerin, aber vor allem als Elternteil, bin ich mit der Entscheidung, die Anzahl der Unterrichtsstunden f\u00fcr die deutsche Minderheitensprache von 3 auf 1 zu reduzieren, nicht einverstanden. Es ist undenkbar, die M\u00f6glichkeiten zur Entwicklung und Pflege der eigenen Sprache und Kultur einzuschr\u00e4nken &#8211; vor allem, wenn es nur eine Minderheit und die j\u00fcngsten B\u00fcrger unseres Landes betrifft. Nach den ge\u00e4nderten Vorschriften wurde der Unterricht in der Minderheitensprache in unserem Fall quantitativ mit F\u00e4chern wie Musik oder Kunst verglichen. Dies ist, ohne jemandem zu nahe treten zu wollen, sehr traurig und sogar &#8211; ungerecht! Als Lehrerin kann ich mir nicht vorstellen, dass ich in nur einer Stunde pro Woche alle notwendigen Inhalte \u00fcber Kultur, Tradition, Geschichte und Sprache vermitteln muss. Das ist meiner Meinung nach schlichtweg unm\u00f6glich.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Martin Buballa, Elternteil:<\/strong> <em>Als Eltern sind wir zutiefst beunruhigt \u00fcber die Ignoranz, mit der der polnische Staat beschlossen hat, die Zusch\u00fcsse f\u00fcr den Deutschunterricht zu k\u00fcrzen. Eine Entscheidung, die die B\u00fcrger spaltet, weil sie ein klares Signal an die Gesellschaft sendet, dass bestimmte Gruppen weniger wert sind als andere. Wie k\u00f6nnen wir das unseren Kindern erkl\u00e4ren? Wie k\u00f6nnen wir ihnen erkl\u00e4ren, dass die Entscheidung der Politiker ihre Perspektiven einschr\u00e4nkt und dass die Politik ihnen, anstatt ihnen Chancen zu geben, diese gedankenlos vorenth\u00e4lt? In einem demokratischen Land, das zur europ\u00e4ischen Gemeinschaft geh\u00f6rt, w\u00e4re es vor nicht allzu langer Zeit undenkbar gewesen, dass Kinder zu Geiseln der Au\u00dfenpolitik werden. Angesichts der aktuellen geopolitischen Lage und der Herausforderungen der heutigen Zeit erscheint die Entscheidung der polnischen Regierung, die polnisch-deutschen Beziehungen auf Messers Schneide zu stellen, umso grotesker.<\/em><br \/>\n<em>Wir erinnern uns noch an die christlichen Werte, von denen sich die polnischen Bisch\u00f6fe in ihrer Botschaft an die deutschen Bisch\u00f6fe vor \u00fcber einem halben Jahrhundert leiten lie\u00dfen, als sie schrieben: Wir vergeben und bitten um Vergebung. Wir fordern daher die Politiker auf, politische Streitereien auf Kosten unserer Kinder abzulehnen und einen Dialog zu f\u00fchren, zu dem ein demokratischer Staat im heutigen Europa f\u00e4hig sein sollte.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Martin Lippa, Vizepr\u00e4sident des Verbandes der deutschen Sozial-Kulturellen Gesellschaften in Polen:<\/strong> <em>Als Verband der deutschen Sozial-Kulturellen Gesellschaften in Polen haben wir mit Sorge und unverhohlenem Unverst\u00e4ndnis die Verabschiedung der Parlamentsnovelle verfolgt, die die rechtliche Diskriminierung der deutschen Minderheit zu einer Tatsache macht. Als Dachverband der deutschen Minderheit haben wir entsprechende Schreiben an das Europ\u00e4ische Parlament, die Europ\u00e4ische Kommission und den Europarat gerichtet. Letztere hat sofort reagiert und teilt voll und ganz die von uns ge\u00e4u\u00dferte Besorgnis, denn die Ma\u00dfnahme der polnischen Regierung bedeutet eine weitere Schw\u00e4chung der Bildung der deutschen Sprache als Minderheitensprache. Gemeinschaften, Gemeinden, Schulen und vor allem die Kinder werden durch die Entscheidung des polnischen Parlaments benachteiligt. Wir haben den Minister, den Premierminister und sogar den Pr\u00e4sidenten um ein Gespr\u00e4ch oder eine Stellungnahme gebeten. Wir warten immer noch auf eine Antwort.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Andrea Polanski, Bund der Jugend der Deutschen Minderheit:<\/strong> <em>Der Bund der Jugend der Deutschen Minderheit \u00e4u\u00dfert sich auch zur K\u00fcrzung des Bildungsanteils der allgemeinen F\u00f6rderung f\u00fcr den Unterricht der Minderheiten- und Regionalsprachen. Dieses Vorgehen richtet sich ausschlie\u00dflich gegen die Angeh\u00f6rigen der deutschen Minderheit. Es handelt sich also um eine eklatante Diskriminierung polnischer B\u00fcrger deutscher Herkunft.&nbsp; Als Zeichen des Protests haben die Jugendlichen der deutschen Minderheit in Polen die Internetkampagne #niemaMowy #sprachlos initiiert.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Die politischen Entscheidungen der Beh\u00f6rden haben zur Folge, dass die Kinder und Jugendlichen, die die Minderheitensprache in der Schule lernen, am meisten darunter zu leiden haben. Durch das Erlernen der Sprache und die Teilnahme an Kursen \u00fcber die Geschichte und Kultur von Minderheiten erwerben die Jugendlichen nicht nur kommunikative, sondern auch kulturelle Kompetenzen, durch die sie sich der Vielfalt und dem Multikulturalismus des Ortes, an dem sie leben, \u00f6ffnen. Durch die drastische K\u00fcrzung der Zusch\u00fcsse f\u00fcr Minderheitensprachkurse nehmen wir ihnen die M\u00f6glichkeit, ihre eigene Identit\u00e4t, ihre gesetzlich garantierte Freiheit, die &#8220;Sprache des Herzens&#8221; zu lernen, und ihre umfassende Entwicklung zu f\u00f6rdern.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Wir appellieren an den Minister f\u00fcr Bildung und Wissenschaft, an den gesamten Ministerrat der Republik Polen, an den Senat und den Sejm der Republik Polen und an alle politischen Entscheidungstr\u00e4ger, die Auswirkungen der K\u00fcrzung der Mittel f\u00fcr den Unterricht von Minderheiten- und Regionalsprachen zu \u00fcberdenken und die Position der Minderheitengemeinschaften zu unterst\u00fctzen.<\/em><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-28770 size-large\" src=\"https:\/\/skgd.pl\/wp-content\/uploads\/2022\/03\/B05AE218-67E5-41BA-9237-2F9A0B8B8DFD1-1024x576.jpg\" alt=\"\" width=\"770\" height=\"433\" srcset=\"https:\/\/skgd.pl\/wp-content\/uploads\/2022\/03\/B05AE218-67E5-41BA-9237-2F9A0B8B8DFD1-1024x576.jpg 1024w, https:\/\/skgd.pl\/wp-content\/uploads\/2022\/03\/B05AE218-67E5-41BA-9237-2F9A0B8B8DFD1-scaled-600x338.jpg 600w, https:\/\/skgd.pl\/wp-content\/uploads\/2022\/03\/B05AE218-67E5-41BA-9237-2F9A0B8B8DFD1-300x169.jpg 300w, https:\/\/skgd.pl\/wp-content\/uploads\/2022\/03\/B05AE218-67E5-41BA-9237-2F9A0B8B8DFD1-768x432.jpg 768w, https:\/\/skgd.pl\/wp-content\/uploads\/2022\/03\/B05AE218-67E5-41BA-9237-2F9A0B8B8DFD1-1536x864.jpg 1536w, https:\/\/skgd.pl\/wp-content\/uploads\/2022\/03\/B05AE218-67E5-41BA-9237-2F9A0B8B8DFD1-2048x1152.jpg 2048w, https:\/\/skgd.pl\/wp-content\/uploads\/2022\/03\/B05AE218-67E5-41BA-9237-2F9A0B8B8DFD1-800x450.jpg 800w\" sizes=\"auto, (max-width: 770px) 100vw, 770px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-28771 size-large\" src=\"https:\/\/skgd.pl\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-08-at-12.05.42-1024x579.jpeg\" alt=\"\" width=\"770\" height=\"435\" srcset=\"https:\/\/skgd.pl\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-08-at-12.05.42-1024x579.jpeg 1024w, https:\/\/skgd.pl\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-08-at-12.05.42-600x340.jpeg 600w, https:\/\/skgd.pl\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-08-at-12.05.42-300x170.jpeg 300w, https:\/\/skgd.pl\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-08-at-12.05.42-768x435.jpeg 768w, https:\/\/skgd.pl\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-08-at-12.05.42-1536x869.jpeg 1536w, https:\/\/skgd.pl\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-08-at-12.05.42-800x453.jpeg 800w, https:\/\/skgd.pl\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-08-at-12.05.42.jpeg 1686w\" sizes=\"auto, (max-width: 770px) 100vw, 770px\" \/>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Im Dezember, kurz nach der Entscheidung des Sejm, die Subventionen f\u00fcr den Unterricht von Deutsch als Minderheitensprache im Haushalt 2022 zu k\u00fcrzen, begannen Eltern mit der Sammlung von Unterschriften f\u00fcr eine Petition gegen diese Entscheidung. Sie nimmt unseren Kindern Chancen und diskriminiert sie &#8211; sagten einstimmig Vertreter von Eltern, Lehrern und Vertretern der deutschen Minderheit, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":28769,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[751,1,450],"tags":[],"class_list":["post-28765","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dam","category-aktualnosci","category-biuro-prasowe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>13.000 Menschen unterzeichnen eine Elternpetition gegen die K\u00fcrzung der Zusch\u00fcsse f\u00fcr den Unterricht von Deutsch als Minderheitensprache - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skgd.pl\/de\/13-000-osob-podpisalo-petycje-rodzicow-przeciw-zmniejszeniu-subwencji-na-nauke-niemieckiego-jako-jezyka-mniejszosci\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"13.000 Menschen unterzeichnen eine Elternpetition gegen die K\u00fcrzung der Zusch\u00fcsse f\u00fcr den Unterricht von Deutsch als Minderheitensprache - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"og:description\" content=\"Im Dezember, kurz nach der Entscheidung des Sejm, die Subventionen f\u00fcr den Unterricht von Deutsch als Minderheitensprache im Haushalt 2022 zu k\u00fcrzen, begannen Eltern mit der Sammlung von Unterschriften f\u00fcr eine Petition gegen diese Entscheidung. Sie nimmt unseren Kindern Chancen und diskriminiert sie &#8211; sagten einstimmig Vertreter von Eltern, Lehrern und Vertretern der deutschen Minderheit, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skgd.pl\/de\/13-000-osob-podpisalo-petycje-rodzicow-przeciw-zmniejszeniu-subwencji-na-nauke-niemieckiego-jako-jezyka-mniejszosci\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-08T10:30:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-08T13:50:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skgd.pl\/wp-content\/uploads\/2022\/03\/W-MEIN-petycja-skladana-na-rece-dyr.-Banasia-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joanna Hassa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"9\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skgd.pl\/#website\",\"url\":\"https:\/\/skgd.pl\/\",\"name\":\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"description\":\"Deutsche Minderheit in Polen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skgd.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/de\/13-000-osob-podpisalo-petycje-rodzicow-przeciw-zmniejszeniu-subwencji-na-nauke-niemieckiego-jako-jezyka-mniejszosci\/#primaryimage\",\"url\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2022\/03\/W-MEIN-petycja-skladana-na-rece-dyr.-Banasia-scaled.jpg\",\"contentUrl\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2022\/03\/W-MEIN-petycja-skladana-na-rece-dyr.-Banasia-scaled.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skgd.pl\/de\/13-000-osob-podpisalo-petycje-rodzicow-przeciw-zmniejszeniu-subwencji-na-nauke-niemieckiego-jako-jezyka-mniejszosci\/#webpage\",\"url\":\"https:\/\/skgd.pl\/de\/13-000-osob-podpisalo-petycje-rodzicow-przeciw-zmniejszeniu-subwencji-na-nauke-niemieckiego-jako-jezyka-mniejszosci\/\",\"name\":\"13.000 Menschen unterzeichnen eine Elternpetition gegen die K\u00fcrzung der Zusch\u00fcsse f\u00fcr den Unterricht von Deutsch als Minderheitensprache - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"isPartOf\":{\"@id\":\"https:\/\/skgd.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skgd.pl\/de\/13-000-osob-podpisalo-petycje-rodzicow-przeciw-zmniejszeniu-subwencji-na-nauke-niemieckiego-jako-jezyka-mniejszosci\/#primaryimage\"},\"datePublished\":\"2022-03-08T10:30:39+00:00\",\"dateModified\":\"2022-03-08T13:50:04+00:00\",\"author\":{\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\"},\"breadcrumb\":{\"@id\":\"https:\/\/skgd.pl\/de\/13-000-osob-podpisalo-petycje-rodzicow-przeciw-zmniejszeniu-subwencji-na-nauke-niemieckiego-jako-jezyka-mniejszosci\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skgd.pl\/de\/13-000-osob-podpisalo-petycje-rodzicow-przeciw-zmniejszeniu-subwencji-na-nauke-niemieckiego-jako-jezyka-mniejszosci\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skgd.pl\/de\/13-000-osob-podpisalo-petycje-rodzicow-przeciw-zmniejszeniu-subwencji-na-nauke-niemieckiego-jako-jezyka-mniejszosci\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/skgd.pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"13.000 Menschen unterzeichnen eine Elternpetition gegen die K\u00fcrzung der Zusch\u00fcsse f\u00fcr den Unterricht von Deutsch als Minderheitensprache\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\",\"name\":\"Joanna Hassa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"caption\":\"Joanna Hassa\"},\"url\":\"https:\/\/skgd.pl\/de\/author\/asia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"13.000 Menschen unterzeichnen eine Elternpetition gegen die K\u00fcrzung der Zusch\u00fcsse f\u00fcr den Unterricht von Deutsch als Minderheitensprache - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skgd.pl\/de\/13-000-osob-podpisalo-petycje-rodzicow-przeciw-zmniejszeniu-subwencji-na-nauke-niemieckiego-jako-jezyka-mniejszosci\/","og_locale":"de_DE","og_type":"article","og_title":"13.000 Menschen unterzeichnen eine Elternpetition gegen die K\u00fcrzung der Zusch\u00fcsse f\u00fcr den Unterricht von Deutsch als Minderheitensprache - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","og_description":"Im Dezember, kurz nach der Entscheidung des Sejm, die Subventionen f\u00fcr den Unterricht von Deutsch als Minderheitensprache im Haushalt 2022 zu k\u00fcrzen, begannen Eltern mit der Sammlung von Unterschriften f\u00fcr eine Petition gegen diese Entscheidung. Sie nimmt unseren Kindern Chancen und diskriminiert sie &#8211; sagten einstimmig Vertreter von Eltern, Lehrern und Vertretern der deutschen Minderheit, [&hellip;]","og_url":"https:\/\/skgd.pl\/de\/13-000-osob-podpisalo-petycje-rodzicow-przeciw-zmniejszeniu-subwencji-na-nauke-niemieckiego-jako-jezyka-mniejszosci\/","og_site_name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","article_published_time":"2022-03-08T10:30:39+00:00","article_modified_time":"2022-03-08T13:50:04+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/skgd.pl\/wp-content\/uploads\/2022\/03\/W-MEIN-petycja-skladana-na-rece-dyr.-Banasia-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Joanna Hassa","Gesch\u00e4tzte Lesezeit":"9\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/skgd.pl\/#website","url":"https:\/\/skgd.pl\/","name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","description":"Deutsche Minderheit in Polen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skgd.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/de\/13-000-osob-podpisalo-petycje-rodzicow-przeciw-zmniejszeniu-subwencji-na-nauke-niemieckiego-jako-jezyka-mniejszosci\/#primaryimage","url":"https:\/\/skgd.pl\/wp-content\/uploads\/2022\/03\/W-MEIN-petycja-skladana-na-rece-dyr.-Banasia-scaled.jpg","contentUrl":"https:\/\/skgd.pl\/wp-content\/uploads\/2022\/03\/W-MEIN-petycja-skladana-na-rece-dyr.-Banasia-scaled.jpg","width":2560,"height":1440},{"@type":"WebPage","@id":"https:\/\/skgd.pl\/de\/13-000-osob-podpisalo-petycje-rodzicow-przeciw-zmniejszeniu-subwencji-na-nauke-niemieckiego-jako-jezyka-mniejszosci\/#webpage","url":"https:\/\/skgd.pl\/de\/13-000-osob-podpisalo-petycje-rodzicow-przeciw-zmniejszeniu-subwencji-na-nauke-niemieckiego-jako-jezyka-mniejszosci\/","name":"13.000 Menschen unterzeichnen eine Elternpetition gegen die K\u00fcrzung der Zusch\u00fcsse f\u00fcr den Unterricht von Deutsch als Minderheitensprache - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","isPartOf":{"@id":"https:\/\/skgd.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skgd.pl\/de\/13-000-osob-podpisalo-petycje-rodzicow-przeciw-zmniejszeniu-subwencji-na-nauke-niemieckiego-jako-jezyka-mniejszosci\/#primaryimage"},"datePublished":"2022-03-08T10:30:39+00:00","dateModified":"2022-03-08T13:50:04+00:00","author":{"@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03"},"breadcrumb":{"@id":"https:\/\/skgd.pl\/de\/13-000-osob-podpisalo-petycje-rodzicow-przeciw-zmniejszeniu-subwencji-na-nauke-niemieckiego-jako-jezyka-mniejszosci\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skgd.pl\/de\/13-000-osob-podpisalo-petycje-rodzicow-przeciw-zmniejszeniu-subwencji-na-nauke-niemieckiego-jako-jezyka-mniejszosci\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/skgd.pl\/de\/13-000-osob-podpisalo-petycje-rodzicow-przeciw-zmniejszeniu-subwencji-na-nauke-niemieckiego-jako-jezyka-mniejszosci\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/skgd.pl\/"},{"@type":"ListItem","position":2,"name":"13.000 Menschen unterzeichnen eine Elternpetition gegen die K\u00fcrzung der Zusch\u00fcsse f\u00fcr den Unterricht von Deutsch als Minderheitensprache"}]},{"@type":"Person","@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03","name":"Joanna Hassa","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","caption":"Joanna Hassa"},"url":"https:\/\/skgd.pl\/de\/author\/asia\/"}]}},"_links":{"self":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/28765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/comments?post=28765"}],"version-history":[{"count":4,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/28765\/revisions"}],"predecessor-version":[{"id":28783,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/28765\/revisions\/28783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media\/28769"}],"wp:attachment":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media?parent=28765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/categories?post=28765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/tags?post=28765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}