{"id":27850,"date":"2021-12-04T09:57:08","date_gmt":"2021-12-04T08:57:08","guid":{"rendered":"https:\/\/skgd.pl\/de\/?p=27850"},"modified":"2021-12-04T09:57:08","modified_gmt":"2021-12-04T08:57:08","slug":"spotkanie-adwentowe-adventstreffen","status":"publish","type":"post","link":"https:\/\/skgd.pl\/de\/spotkanie-adwentowe-adventstreffen\/","title":{"rendered":"Adventstreffen im DFK"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: justify;\">Seit Jahren ist es schon zur Tradition geworden, dass der DFK Zelasno am ersten Adventssonntag ein Treffen organisiert. Diesmal war es in begrenztem Rahmen, wegen der Pandemie. Immerhin konnten 30 Teilnehmer einen interessanten Vortrag von Prof. Joanna Rostropowicz \u00fcber Elisabeth Grabowski h\u00f6ren und einen sch\u00f6nen Nachmittag bei Adventsliedern verbriengen. Die B\u00fcrgermeisterin der Gemeinde Frau Katarzyna Go\u0142\u0119biowska Jarek weilte auch unter den Anwesenden.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Seit Jahren ist es schon zur Tradition geworden, dass der DFK Zelasno am ersten Adventssonntag ein Treffen organisiert. Diesmal war es in begrenztem Rahmen, wegen der Pandemie. Immerhin konnten 30 Teilnehmer einen interessanten Vortrag von Prof. Joanna Rostropowicz \u00fcber Elisabeth Grabowski h\u00f6ren und einen sch\u00f6nen Nachmittag bei Adventsliedern verbriengen. Die B\u00fcrgermeisterin der Gemeinde Frau Katarzyna [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27851,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[244],"tags":[],"class_list":["post-27850","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dfk-zelazna-zelazno"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Adventstreffen im DFK - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skgd.pl\/de\/spotkanie-adwentowe-adventstreffen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adventstreffen im DFK - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"og:description\" content=\"Seit Jahren ist es schon zur Tradition geworden, dass der DFK Zelasno am ersten Adventssonntag ein Treffen organisiert. Diesmal war es in begrenztem Rahmen, wegen der Pandemie. Immerhin konnten 30 Teilnehmer einen interessanten Vortrag von Prof. Joanna Rostropowicz \u00fcber Elisabeth Grabowski h\u00f6ren und einen sch\u00f6nen Nachmittag bei Adventsliedern verbriengen. Die B\u00fcrgermeisterin der Gemeinde Frau Katarzyna [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skgd.pl\/de\/spotkanie-adwentowe-adventstreffen\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-04T08:57:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skgd.pl\/wp-content\/uploads\/2021\/12\/20211128_153312-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skgd.pl\/#website\",\"url\":\"https:\/\/skgd.pl\/\",\"name\":\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"description\":\"Deutsche Minderheit in Polen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skgd.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/de\/spotkanie-adwentowe-adventstreffen\/#primaryimage\",\"url\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2021\/12\/20211128_153312-scaled.jpg\",\"contentUrl\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2021\/12\/20211128_153312-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skgd.pl\/de\/spotkanie-adwentowe-adventstreffen\/#webpage\",\"url\":\"https:\/\/skgd.pl\/de\/spotkanie-adwentowe-adventstreffen\/\",\"name\":\"Adventstreffen im DFK - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"isPartOf\":{\"@id\":\"https:\/\/skgd.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skgd.pl\/de\/spotkanie-adwentowe-adventstreffen\/#primaryimage\"},\"datePublished\":\"2021-12-04T08:57:08+00:00\",\"dateModified\":\"2021-12-04T08:57:08+00:00\",\"author\":{\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/709172ef205731476e77391cc87c04e8\"},\"breadcrumb\":{\"@id\":\"https:\/\/skgd.pl\/de\/spotkanie-adwentowe-adventstreffen\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skgd.pl\/de\/spotkanie-adwentowe-adventstreffen\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skgd.pl\/de\/spotkanie-adwentowe-adventstreffen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/skgd.pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adventstreffen im DFK\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/709172ef205731476e77391cc87c04e8\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a352aecaac6403c9ea5013a95dbe945e910d71bc652d01a07313977398158711?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a352aecaac6403c9ea5013a95dbe945e910d71bc652d01a07313977398158711?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/skgd.pl\/de\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Adventstreffen im DFK - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skgd.pl\/de\/spotkanie-adwentowe-adventstreffen\/","og_locale":"de_DE","og_type":"article","og_title":"Adventstreffen im DFK - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","og_description":"Seit Jahren ist es schon zur Tradition geworden, dass der DFK Zelasno am ersten Adventssonntag ein Treffen organisiert. Diesmal war es in begrenztem Rahmen, wegen der Pandemie. Immerhin konnten 30 Teilnehmer einen interessanten Vortrag von Prof. Joanna Rostropowicz \u00fcber Elisabeth Grabowski h\u00f6ren und einen sch\u00f6nen Nachmittag bei Adventsliedern verbriengen. Die B\u00fcrgermeisterin der Gemeinde Frau Katarzyna [&hellip;]","og_url":"https:\/\/skgd.pl\/de\/spotkanie-adwentowe-adventstreffen\/","og_site_name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","article_published_time":"2021-12-04T08:57:08+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/skgd.pl\/wp-content\/uploads\/2021\/12\/20211128_153312-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/skgd.pl\/#website","url":"https:\/\/skgd.pl\/","name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","description":"Deutsche Minderheit in Polen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skgd.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/de\/spotkanie-adwentowe-adventstreffen\/#primaryimage","url":"https:\/\/skgd.pl\/wp-content\/uploads\/2021\/12\/20211128_153312-scaled.jpg","contentUrl":"https:\/\/skgd.pl\/wp-content\/uploads\/2021\/12\/20211128_153312-scaled.jpg","width":2560,"height":1920},{"@type":"WebPage","@id":"https:\/\/skgd.pl\/de\/spotkanie-adwentowe-adventstreffen\/#webpage","url":"https:\/\/skgd.pl\/de\/spotkanie-adwentowe-adventstreffen\/","name":"Adventstreffen im DFK - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","isPartOf":{"@id":"https:\/\/skgd.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skgd.pl\/de\/spotkanie-adwentowe-adventstreffen\/#primaryimage"},"datePublished":"2021-12-04T08:57:08+00:00","dateModified":"2021-12-04T08:57:08+00:00","author":{"@id":"https:\/\/skgd.pl\/#\/schema\/person\/709172ef205731476e77391cc87c04e8"},"breadcrumb":{"@id":"https:\/\/skgd.pl\/de\/spotkanie-adwentowe-adventstreffen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skgd.pl\/de\/spotkanie-adwentowe-adventstreffen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/skgd.pl\/de\/spotkanie-adwentowe-adventstreffen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/skgd.pl\/"},{"@type":"ListItem","position":2,"name":"Adventstreffen im DFK"}]},{"@type":"Person","@id":"https:\/\/skgd.pl\/#\/schema\/person\/709172ef205731476e77391cc87c04e8","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a352aecaac6403c9ea5013a95dbe945e910d71bc652d01a07313977398158711?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a352aecaac6403c9ea5013a95dbe945e910d71bc652d01a07313977398158711?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/skgd.pl\/de\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/27850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/comments?post=27850"}],"version-history":[{"count":2,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/27850\/revisions"}],"predecessor-version":[{"id":27853,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/27850\/revisions\/27853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media\/27851"}],"wp:attachment":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media?parent=27850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/categories?post=27850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/tags?post=27850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}