{"id":27255,"date":"2021-09-01T15:37:40","date_gmt":"2021-09-01T13:37:40","guid":{"rendered":"https:\/\/skgd.pl\/?p=27255"},"modified":"2021-09-01T15:37:40","modified_gmt":"2021-09-01T13:37:40","slug":"pytania-do-kandydatow-do-bundestagu-die-linke","status":"publish","type":"post","link":"https:\/\/skgd.pl\/de\/pytania-do-kandydatow-do-bundestagu-die-linke\/","title":{"rendered":"Fragen an die Kandidaten zu den Budestagswahlen: DIE LINKE"},"content":{"rendered":"<p><\/p>\n<div class=\"itemFullText\">\n<p style=\"text-align: justify;\">Die n\u00e4chste Partei, die auf die Fragen der Deutschen Minderheit geantwortet hat ist DIE LINKE<\/p>\n<p style=\"text-align: justify;\"><strong>1. Welche Priorit\u00e4t haben in Ihrer politischen Planung die Angelegenheiten der deutschen Minderheiten in Mittel- und Osteuropa, darunter besonders der deutschen Minderheit in Polen?<\/strong><\/p>\n<p style=\"text-align: justify;\">DIE LINKE setzt sich generell f\u00fcr die Beseitigung von Diskriminierungen von Menschen aufgrund ihrer kulturellen Zugeh\u00f6rigkeit oder ihrer ethnischen Herkunft ein. Nationale Minderheiten in Deutschland und in der ganzen EU m\u00fcssen respektiert und unterst\u00fctzt werden.<\/p>\n<p style=\"text-align: justify;\"><strong>2. Haben Sie die Absicht, diese Angelegenheiten zu einem Punkt im Wahlprogramm Ihrer Partei in der Bundestagswahl 2021 zu machen? Wenn ja, in welchem Ausma\u00df?<\/strong><\/p>\n<p style=\"text-align: justify;\">Der Kampf gegen Diskriminierung von Minderheiten genie\u00dft in unserem Programm einen hohen Stellenwert. Auch auf der Ebene der EU setzen wir uns die Schaffung von verl\u00e4sslichen minderheitenpolitischen Instrumenten ein. Die Ablehnung der Minority-Safepack-Initiative durch die EU-Kommission darf nicht das letzte Wort sein.<\/p>\n<p style=\"text-align: justify;\"><strong>3. Wie steht Ihre Partei zu der Verankerung der Grundwerte der Minderheitenpolitik auf der Ebene der Europ\u00e4ischen Union, die trotz Regelungen in den Dokumenten des Europarates nicht immer beachtet werden und sich in den kritischen Berichten der Experten widerspiegeln?<\/strong><\/p>\n<p style=\"text-align: justify;\">Hier muss es dringend Nachbesserungen geben. Es wurde von der Linken stets angemahnt, dass die EU den Europ\u00e4ischen Menschenrechtskonvention des Europarats beitreten sollte,<\/p>\n<p style=\"text-align: justify;\"><strong>4. Die DMi hat nicht in allen EU-L\u00e4ndern Schulen mit Deutsch als Unterrichtssprache oder Schulen, die in zwei Sprachen unterrichten. Was m\u00f6chten Sie eventuell tun, um diese Unterschiede zu beseitigen, besonders in Bezug auf Polen mit einer der gr\u00f6\u00dften deutschen Minderheit in Europa?<\/strong><\/p>\n<p style=\"text-align: justify;\">DIE LINKE betrachtet Regional- oder Minderheitensprachen als Ausdruck des kulturellen Reichtums und ruft dazu auf dieses Angebot auch in Schulen zu f\u00f6rdern. Wir werben daf\u00fcr, dass sich auch die EUI-Kommission diesem Grundsatz verpflichtet sieht.<\/p>\n<p style=\"text-align: justify;\"><strong>5. Der Bundestag und das EU-Parlament haben sich 2020 f\u00fcr die Europ\u00e4ische B\u00fcrgerinitiative Minority Safepack ausgesprochen. Leider folgte die Europ\u00e4ische Kommission dem nicht und hat die B\u00fcrgerinitiative der FUEN abgelehnt. Werden Sie die Anerkennung dieser B\u00fcrgerinitiative weiter unterst\u00fctzen?<\/strong><\/p>\n<p style=\"text-align: justify;\">DIE LINKE setzt sich f\u00fcr eine gleichberechtigte Teilhabe aller B\u00fcrgerinnen und B\u00fcrger am gesellschaftlichen Leben ohne strukturelle Benachteiligungen ein &#8211; auch nicht aufgrund ihrer ethnischen Herkunft. Egal ob Sorbinnen oder Friesen, egal ob D\u00e4ninnen oder Sinti und Roma: Nationale Minderheiten in Deutschland und in der ganzen EU m\u00fcssen respektiert und unterst\u00fctzt werden. Es darf keine Unterschiede in der Unterst\u00fctzung geben. Der beste Garant daf\u00fcr ist eine schnelle Umsetzung der Forderungen der B\u00fcrgerinitiative auf EU-Ebene durch die Kommission . DIE LINKE hat deshalb sowohl im Europ\u00e4ischen Parlament als auch im Bundestag die Inhalte des Minority Safe Pack unterst\u00fctzt und wird dies auch weiterhin tun.<\/p>\n<p style=\"text-align: justify;\"><strong>6. Im Jahr 2019 hat die AGDM eine Resolution verabschiedet. Diese betraf die neuen Ausrichtungen der Unterst\u00fctzung der DMi u. a. auch die Finanzierung, die als zu niedrig im Vergleich mit den Bed\u00fcrfnissen der Minderheiten definiert wurde. Sind Sie bereit, das in Ihrem Wahlprogramm zu ber\u00fccksichtigen?<\/strong><\/p>\n<p style=\"text-align: justify;\">Zur Schaffung kultureller und sprachlicher Vielfalt geh\u00f6rt deshalb die F\u00f6rderung von Regional- und Minderheitensprachen, die entsprechend der Europ\u00e4ischen Minderheitencharta (Europ\u00e4ische Charta der Regional- oder Minderheitensprachen) anerkannt sind. DIE LINKE dringt hier auf eine finanzielle F\u00f6rderung, um diese Ziele umsetzen zu k\u00f6nnen.<\/p>\n<p style=\"text-align: justify;\"><strong>7. Anl\u00e4sslich des 30. Jubil\u00e4ums des deutsch-polnischen Nachbarschaftsvertrags wurden u. a. erstmals die Rechte der in Polen lebenden DMi festgelegt. Viele davon und von der gemeinsamen Erkl\u00e4rung aus 2011, wurden aus der Sicht der DMi in Polen nicht umgesetzt. Wie steht Ihre Partei dazu?<\/strong><\/p>\n<p style=\"text-align: justify;\">Freundschaft und Auss\u00f6hnung mit Polen hat f\u00fcr DIE LINKE eine hohe Priorit\u00e4t. DIE LINKE wirbt in diesem Zusammenhang, um die Erf\u00fcllung aller Bestimmungen des deutsch-polnischen Nachbarschaftsvertrags.<\/p>\n<p style=\"text-align: justify;\"><strong>8. Viele Mitglieder der DMi in Polen sind deutsche Staatsangeh\u00f6rige und besitzen als Auslandsdeutsche das Wahlrecht, das aber subjektive Begr\u00fcndungen der Vertrautheit und Betroffenheit von politischen Verh\u00e4ltnissen in BRD verlangt. Sind Sie bereit, das zu vereinfachen?<\/strong><\/p>\n<p style=\"text-align: justify;\">Nein. Aus unserer Sicht sind die bestehenden Regelungen im Grundsatz bew\u00e4hrt, allerdings bed\u00fcrfen aus unserer Sicht die Verfahren zur Teilnahme an der Wahl b\u00fcrokratischer Vereinfachungen.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.die-linke.de\/start\/\"><img loading=\"lazy\" decoding=\"async\" class=\" thumbnail\" src=\"https:\/\/vdg.pl\/images\/thumbnails\/images\/Bogna_\/Die_Linke-fill-300x67.jpg\" alt=\"Die Linke\" width=\"300\" height=\"67\"><\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Zur Erinnerung:<\/strong>&nbsp;die Bundestagswahlen finden am 26. September 2021 statt. Wahlberechtigte Deutsche,&nbsp;die sich dauerhaft im Ausland aufhalten, haben bis zum&nbsp;<strong>5. September 2021&nbsp;<\/strong>die M\u00f6glichkeit, einen Antrag auf die Eintragung in das W\u00e4hlerverzeichnis zu stellen. Mehr dazu erfahren Sie&nbsp;<a href=\"https:\/\/vdg.pl\/de\/portal\/aktuelles\/politik\/item\/5523-bundestagswahlen-informationen-zur-wahlteilnahme-aus-dem-ausland\">HIER<\/a>.&nbsp;<\/p>\n<\/div>\n<div class=\"itemBottom\" style=\"text-align: justify;\">&nbsp;<\/div>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Die n\u00e4chste Partei, die auf die Fragen der Deutschen Minderheit geantwortet hat ist DIE LINKE 1. Welche Priorit\u00e4t haben in Ihrer politischen Planung die Angelegenheiten der deutschen Minderheiten in Mittel- und Osteuropa, darunter besonders der deutschen Minderheit in Polen? DIE LINKE setzt sich generell f\u00fcr die Beseitigung von Diskriminierungen von Menschen aufgrund ihrer kulturellen Zugeh\u00f6rigkeit [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":27142,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-27255","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktualnosci"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fragen an die Kandidaten zu den Budestagswahlen: DIE LINKE - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skgd.pl\/pytania-do-kandydatow-do-bundestagu-die-linke\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fragen an die Kandidaten zu den Budestagswahlen: DIE LINKE - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"og:description\" content=\"Die n\u00e4chste Partei, die auf die Fragen der Deutschen Minderheit geantwortet hat ist DIE LINKE 1. Welche Priorit\u00e4t haben in Ihrer politischen Planung die Angelegenheiten der deutschen Minderheiten in Mittel- und Osteuropa, darunter besonders der deutschen Minderheit in Polen? DIE LINKE setzt sich generell f\u00fcr die Beseitigung von Diskriminierungen von Menschen aufgrund ihrer kulturellen Zugeh\u00f6rigkeit [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skgd.pl\/pytania-do-kandydatow-do-bundestagu-die-linke\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-01T13:37:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skgd.pl\/wp-content\/uploads\/2021\/08\/resize_640x427.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joanna Hassa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skgd.pl\/#website\",\"url\":\"https:\/\/skgd.pl\/\",\"name\":\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"description\":\"Deutsche Minderheit in Polen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skgd.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/pytania-do-kandydatow-do-bundestagu-die-linke\/#primaryimage\",\"url\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2021\/08\/resize_640x427.jpg\",\"contentUrl\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2021\/08\/resize_640x427.jpg\",\"width\":640,\"height\":427},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skgd.pl\/pytania-do-kandydatow-do-bundestagu-die-linke\/#webpage\",\"url\":\"https:\/\/skgd.pl\/pytania-do-kandydatow-do-bundestagu-die-linke\/\",\"name\":\"Fragen an die Kandidaten zu den Budestagswahlen: DIE LINKE - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"isPartOf\":{\"@id\":\"https:\/\/skgd.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skgd.pl\/pytania-do-kandydatow-do-bundestagu-die-linke\/#primaryimage\"},\"datePublished\":\"2021-09-01T13:37:40+00:00\",\"dateModified\":\"2021-09-01T13:37:40+00:00\",\"author\":{\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\"},\"breadcrumb\":{\"@id\":\"https:\/\/skgd.pl\/pytania-do-kandydatow-do-bundestagu-die-linke\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skgd.pl\/pytania-do-kandydatow-do-bundestagu-die-linke\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skgd.pl\/pytania-do-kandydatow-do-bundestagu-die-linke\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/skgd.pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pytania do kandydat\u00f3w do Bundestagu: DIE LINKE\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\",\"name\":\"Joanna Hassa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"caption\":\"Joanna Hassa\"},\"url\":\"https:\/\/skgd.pl\/de\/author\/asia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fragen an die Kandidaten zu den Budestagswahlen: DIE LINKE - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skgd.pl\/pytania-do-kandydatow-do-bundestagu-die-linke\/","og_locale":"de_DE","og_type":"article","og_title":"Fragen an die Kandidaten zu den Budestagswahlen: DIE LINKE - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","og_description":"Die n\u00e4chste Partei, die auf die Fragen der Deutschen Minderheit geantwortet hat ist DIE LINKE 1. Welche Priorit\u00e4t haben in Ihrer politischen Planung die Angelegenheiten der deutschen Minderheiten in Mittel- und Osteuropa, darunter besonders der deutschen Minderheit in Polen? DIE LINKE setzt sich generell f\u00fcr die Beseitigung von Diskriminierungen von Menschen aufgrund ihrer kulturellen Zugeh\u00f6rigkeit [&hellip;]","og_url":"https:\/\/skgd.pl\/pytania-do-kandydatow-do-bundestagu-die-linke\/","og_site_name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","article_published_time":"2021-09-01T13:37:40+00:00","og_image":[{"width":640,"height":427,"url":"https:\/\/skgd.pl\/wp-content\/uploads\/2021\/08\/resize_640x427.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Joanna Hassa","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/skgd.pl\/#website","url":"https:\/\/skgd.pl\/","name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","description":"Deutsche Minderheit in Polen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skgd.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/pytania-do-kandydatow-do-bundestagu-die-linke\/#primaryimage","url":"https:\/\/skgd.pl\/wp-content\/uploads\/2021\/08\/resize_640x427.jpg","contentUrl":"https:\/\/skgd.pl\/wp-content\/uploads\/2021\/08\/resize_640x427.jpg","width":640,"height":427},{"@type":"WebPage","@id":"https:\/\/skgd.pl\/pytania-do-kandydatow-do-bundestagu-die-linke\/#webpage","url":"https:\/\/skgd.pl\/pytania-do-kandydatow-do-bundestagu-die-linke\/","name":"Fragen an die Kandidaten zu den Budestagswahlen: DIE LINKE - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","isPartOf":{"@id":"https:\/\/skgd.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skgd.pl\/pytania-do-kandydatow-do-bundestagu-die-linke\/#primaryimage"},"datePublished":"2021-09-01T13:37:40+00:00","dateModified":"2021-09-01T13:37:40+00:00","author":{"@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03"},"breadcrumb":{"@id":"https:\/\/skgd.pl\/pytania-do-kandydatow-do-bundestagu-die-linke\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skgd.pl\/pytania-do-kandydatow-do-bundestagu-die-linke\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/skgd.pl\/pytania-do-kandydatow-do-bundestagu-die-linke\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/skgd.pl\/"},{"@type":"ListItem","position":2,"name":"Pytania do kandydat\u00f3w do Bundestagu: DIE LINKE"}]},{"@type":"Person","@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03","name":"Joanna Hassa","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","caption":"Joanna Hassa"},"url":"https:\/\/skgd.pl\/de\/author\/asia\/"}]}},"_links":{"self":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/27255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/comments?post=27255"}],"version-history":[{"count":1,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/27255\/revisions"}],"predecessor-version":[{"id":27256,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/27255\/revisions\/27256"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media\/27142"}],"wp:attachment":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media?parent=27255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/categories?post=27255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/tags?post=27255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}