{"id":26834,"date":"2021-06-24T08:42:48","date_gmt":"2021-06-24T06:42:48","guid":{"rendered":"https:\/\/skgd.pl\/?p=26834"},"modified":"2021-06-23T20:45:39","modified_gmt":"2021-06-23T18:45:39","slug":"msza-sw-w-intencji-zmarlych-i-zyjacych-czlonkow-tskn-na-slasku-opolskim-2","status":"publish","type":"post","link":"https:\/\/skgd.pl\/de\/msza-sw-w-intencji-zmarlych-i-zyjacych-czlonkow-tskn-na-slasku-opolskim-2\/","title":{"rendered":"Hl. Messe in der Intention der lebenden und verstorbenen Mitglieder der SKGD"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: justify;\">Sehr geehrte Damen und Herren,<\/p>\n<p style=\"text-align: justify;\">am kommenden Samstag findet die Jahresversammlung der SKGD statt. Wegen der COVID-Pandemie wurde die Jahresversammlung, die normalerweise in Mai stattfindet, verschoben. Um die Jahresversammlung kompakt zu veranstalten, hat sich der Vorstand der SKGD entschieden, die Heilige Messe die jedes Mal vor der Jahresversammlung statt findet, auf Sonntag, den 27.06.2021 zu verschieben.<\/p>\n<p style=\"text-align: justify;\">Die Heilige Messe findet um 10 Uhr in der Sebastian Kirche in Oppeln (plac \u015awi\u0119tego Sebastiana 2, 46-020 Opole) statt.<\/p>\n<p style=\"text-align: justify;\">Wir werden f\u00fcr die Verstorbenen und lebenden Mitglieder der Sozial-Kulturellen Gesellschaft der Deutschen im Oppelner Schlesien beten.<\/p>\n<p style=\"text-align: justify;\">Wir laden Sie ganz herzlich zu dieser Heiligen Messe ein.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Sehr geehrte Damen und Herren, am kommenden Samstag findet die Jahresversammlung der SKGD statt. Wegen der COVID-Pandemie wurde die Jahresversammlung, die normalerweise in Mai stattfindet, verschoben. Um die Jahresversammlung kompakt zu veranstalten, hat sich der Vorstand der SKGD entschieden, die Heilige Messe die jedes Mal vor der Jahresversammlung statt findet, auf Sonntag, den 27.06.2021 zu [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":24426,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-26834","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktualnosci"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hl. Messe in der Intention der lebenden und verstorbenen Mitglieder der SKGD - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skgd.pl\/msza-sw-w-intencji-zmarlych-i-zyjacych-czlonkow-tskn-na-slasku-opolskim-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hl. Messe in der Intention der lebenden und verstorbenen Mitglieder der SKGD - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"og:description\" content=\"Sehr geehrte Damen und Herren, am kommenden Samstag findet die Jahresversammlung der SKGD statt. Wegen der COVID-Pandemie wurde die Jahresversammlung, die normalerweise in Mai stattfindet, verschoben. Um die Jahresversammlung kompakt zu veranstalten, hat sich der Vorstand der SKGD entschieden, die Heilige Messe die jedes Mal vor der Jahresversammlung statt findet, auf Sonntag, den 27.06.2021 zu [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skgd.pl\/msza-sw-w-intencji-zmarlych-i-zyjacych-czlonkow-tskn-na-slasku-opolskim-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-24T06:42:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-23T18:45:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skgd.pl\/wp-content\/uploads\/2020\/08\/Opole-ko\u015bci\u00f3\u0142_\u015bw._Sebastiana.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1516\" \/>\n\t<meta property=\"og:image:height\" content=\"2428\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joanna Hassa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skgd.pl\/#website\",\"url\":\"https:\/\/skgd.pl\/\",\"name\":\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"description\":\"Deutsche Minderheit in Polen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skgd.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/msza-sw-w-intencji-zmarlych-i-zyjacych-czlonkow-tskn-na-slasku-opolskim-2\/#primaryimage\",\"url\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2020\/08\/Opole-ko\u015bci\u00f3\u0142_\u015bw._Sebastiana.jpg\",\"contentUrl\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2020\/08\/Opole-ko\u015bci\u00f3\u0142_\u015bw._Sebastiana.jpg\",\"width\":1516,\"height\":2428,\"caption\":\"Processed by: Helicon Filter;\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skgd.pl\/msza-sw-w-intencji-zmarlych-i-zyjacych-czlonkow-tskn-na-slasku-opolskim-2\/#webpage\",\"url\":\"https:\/\/skgd.pl\/msza-sw-w-intencji-zmarlych-i-zyjacych-czlonkow-tskn-na-slasku-opolskim-2\/\",\"name\":\"Hl. Messe in der Intention der lebenden und verstorbenen Mitglieder der SKGD - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"isPartOf\":{\"@id\":\"https:\/\/skgd.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skgd.pl\/msza-sw-w-intencji-zmarlych-i-zyjacych-czlonkow-tskn-na-slasku-opolskim-2\/#primaryimage\"},\"datePublished\":\"2021-06-24T06:42:48+00:00\",\"dateModified\":\"2021-06-23T18:45:39+00:00\",\"author\":{\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\"},\"breadcrumb\":{\"@id\":\"https:\/\/skgd.pl\/msza-sw-w-intencji-zmarlych-i-zyjacych-czlonkow-tskn-na-slasku-opolskim-2\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skgd.pl\/msza-sw-w-intencji-zmarlych-i-zyjacych-czlonkow-tskn-na-slasku-opolskim-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skgd.pl\/msza-sw-w-intencji-zmarlych-i-zyjacych-czlonkow-tskn-na-slasku-opolskim-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/skgd.pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Msza \u015bw. w intencji zmar\u0142ych i \u017cyj\u0105cych cz\u0142onk\u00f3w TSKN na \u015al\u0105sku Opolskim\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\",\"name\":\"Joanna Hassa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"caption\":\"Joanna Hassa\"},\"url\":\"https:\/\/skgd.pl\/de\/author\/asia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hl. Messe in der Intention der lebenden und verstorbenen Mitglieder der SKGD - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skgd.pl\/msza-sw-w-intencji-zmarlych-i-zyjacych-czlonkow-tskn-na-slasku-opolskim-2\/","og_locale":"de_DE","og_type":"article","og_title":"Hl. Messe in der Intention der lebenden und verstorbenen Mitglieder der SKGD - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","og_description":"Sehr geehrte Damen und Herren, am kommenden Samstag findet die Jahresversammlung der SKGD statt. Wegen der COVID-Pandemie wurde die Jahresversammlung, die normalerweise in Mai stattfindet, verschoben. Um die Jahresversammlung kompakt zu veranstalten, hat sich der Vorstand der SKGD entschieden, die Heilige Messe die jedes Mal vor der Jahresversammlung statt findet, auf Sonntag, den 27.06.2021 zu [&hellip;]","og_url":"https:\/\/skgd.pl\/msza-sw-w-intencji-zmarlych-i-zyjacych-czlonkow-tskn-na-slasku-opolskim-2\/","og_site_name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","article_published_time":"2021-06-24T06:42:48+00:00","article_modified_time":"2021-06-23T18:45:39+00:00","og_image":[{"width":1516,"height":2428,"url":"https:\/\/skgd.pl\/wp-content\/uploads\/2020\/08\/Opole-ko\u015bci\u00f3\u0142_\u015bw._Sebastiana.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Joanna Hassa","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/skgd.pl\/#website","url":"https:\/\/skgd.pl\/","name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","description":"Deutsche Minderheit in Polen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skgd.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/msza-sw-w-intencji-zmarlych-i-zyjacych-czlonkow-tskn-na-slasku-opolskim-2\/#primaryimage","url":"https:\/\/skgd.pl\/wp-content\/uploads\/2020\/08\/Opole-ko\u015bci\u00f3\u0142_\u015bw._Sebastiana.jpg","contentUrl":"https:\/\/skgd.pl\/wp-content\/uploads\/2020\/08\/Opole-ko\u015bci\u00f3\u0142_\u015bw._Sebastiana.jpg","width":1516,"height":2428,"caption":"Processed by: Helicon Filter;"},{"@type":"WebPage","@id":"https:\/\/skgd.pl\/msza-sw-w-intencji-zmarlych-i-zyjacych-czlonkow-tskn-na-slasku-opolskim-2\/#webpage","url":"https:\/\/skgd.pl\/msza-sw-w-intencji-zmarlych-i-zyjacych-czlonkow-tskn-na-slasku-opolskim-2\/","name":"Hl. Messe in der Intention der lebenden und verstorbenen Mitglieder der SKGD - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","isPartOf":{"@id":"https:\/\/skgd.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skgd.pl\/msza-sw-w-intencji-zmarlych-i-zyjacych-czlonkow-tskn-na-slasku-opolskim-2\/#primaryimage"},"datePublished":"2021-06-24T06:42:48+00:00","dateModified":"2021-06-23T18:45:39+00:00","author":{"@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03"},"breadcrumb":{"@id":"https:\/\/skgd.pl\/msza-sw-w-intencji-zmarlych-i-zyjacych-czlonkow-tskn-na-slasku-opolskim-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skgd.pl\/msza-sw-w-intencji-zmarlych-i-zyjacych-czlonkow-tskn-na-slasku-opolskim-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/skgd.pl\/msza-sw-w-intencji-zmarlych-i-zyjacych-czlonkow-tskn-na-slasku-opolskim-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/skgd.pl\/"},{"@type":"ListItem","position":2,"name":"Msza \u015bw. w intencji zmar\u0142ych i \u017cyj\u0105cych cz\u0142onk\u00f3w TSKN na \u015al\u0105sku Opolskim"}]},{"@type":"Person","@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03","name":"Joanna Hassa","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","caption":"Joanna Hassa"},"url":"https:\/\/skgd.pl\/de\/author\/asia\/"}]}},"_links":{"self":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/26834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/comments?post=26834"}],"version-history":[{"count":1,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/26834\/revisions"}],"predecessor-version":[{"id":26835,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/26834\/revisions\/26835"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media\/24426"}],"wp:attachment":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media?parent=26834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/categories?post=26834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/tags?post=26834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}