{"id":19749,"date":"2019-02-15T10:51:29","date_gmt":"2019-02-15T09:51:29","guid":{"rendered":"http:\/\/skgd.pl\/?p=19749"},"modified":"2019-02-15T10:51:29","modified_gmt":"2019-02-15T09:51:29","slug":"dyzur-przewodniczacego-w-jemielnicy","status":"publish","type":"post","link":"https:\/\/skgd.pl\/de\/dyzur-przewodniczacego-w-jemielnicy\/","title":{"rendered":"Sprechstunden des Vorsitzenden in Himmelwitz"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: justify;\">Die ersten Sprechstunden des Vorsitzenden der SKGD Rafa\u0142 Bartek im Jahr 2019 erfolgte in der Gemeinde Himmelwitz. W\u00e4hrend des Treffens mit dem B\u00fcrgermeister der Gemeinde, Herrn Marcin Wycis\u0142o, hatte der Vorsitzende Gelegenheit, \u00fcber die Situation der Gemeinde und die geplanten Investitionen (einschlie\u00dflich des geplanten Kindergartens) zu sprechen. Nach 16.00 Uhr fand ein Treffen mit den DFK-Mitgliedern und Bewohnern der Gemeinde Jemielnica statt. An dem Treffen nahmen auch der stellvertretende Marschall Roman Kolek, Landrat J\u00f3zef Swaczyna, sowie der Vorsitzende und der stellvertretende Vorsitzende des Gemeinderats in Himmelwitz teil.<\/p>\n<p style=\"text-align: justify;\">Das Treffen war eine Gelegenheit, um \u00fcber Themen zu sprechen, die sich auf die laufenden Aktivit\u00e4ten der SKGD beziehen, einschlie\u00dflich \u00fcber anstehende Initiativen wie die Einrichtung des SKGD-Jugendrates, sowie \u00fcber Wahlen in Strukturen. Ein wichtiges Thema war auch das Thema Deutsch als Minderheitensprache in Grundschulen, insbesondere in der 7. und 8. Klasse. Ein gro\u00dfer Teil des Treffens widmete sich auch dem Thema der Erneuerung von Dokumenten, die die deutsche Staatsb\u00fcrgerschaft best\u00e4tigen.<\/p>\n<p style=\"text-align: justify;\">Am Treffen nahm auch die BJDM-Vorsitzende teil, die die Projekte von BDJM vorstellte.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-19751\" src=\"https:\/\/skgd.pl\/wp-content\/uploads\/2019\/02\/IMG_2875-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/skgd.pl\/wp-content\/uploads\/2019\/02\/IMG_2875-300x200.jpg 300w, https:\/\/skgd.pl\/wp-content\/uploads\/2019\/02\/IMG_2875-600x400.jpg 600w, https:\/\/skgd.pl\/wp-content\/uploads\/2019\/02\/IMG_2875-768x512.jpg 768w, https:\/\/skgd.pl\/wp-content\/uploads\/2019\/02\/IMG_2875-1024x683.jpg 1024w, https:\/\/skgd.pl\/wp-content\/uploads\/2019\/02\/IMG_2875-800x533.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-19752\" src=\"https:\/\/skgd.pl\/wp-content\/uploads\/2019\/02\/IMG_2887-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/skgd.pl\/wp-content\/uploads\/2019\/02\/IMG_2887-300x200.jpg 300w, https:\/\/skgd.pl\/wp-content\/uploads\/2019\/02\/IMG_2887-600x400.jpg 600w, https:\/\/skgd.pl\/wp-content\/uploads\/2019\/02\/IMG_2887-768x512.jpg 768w, https:\/\/skgd.pl\/wp-content\/uploads\/2019\/02\/IMG_2887-1024x683.jpg 1024w, https:\/\/skgd.pl\/wp-content\/uploads\/2019\/02\/IMG_2887-800x533.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Die ersten Sprechstunden des Vorsitzenden der SKGD Rafa\u0142 Bartek im Jahr 2019 erfolgte in der Gemeinde Himmelwitz. W\u00e4hrend des Treffens mit dem B\u00fcrgermeister der Gemeinde, Herrn Marcin Wycis\u0142o, hatte der Vorsitzende Gelegenheit, \u00fcber die Situation der Gemeinde und die geplanten Investitionen (einschlie\u00dflich des geplanten Kindergartens) zu sprechen. Nach 16.00 Uhr fand ein Treffen mit den [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":19750,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-19749","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktualnosci"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sprechstunden des Vorsitzenden in Himmelwitz - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skgd.pl\/en\/dyzur-przewodniczacego-w-jemielnicy\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sprechstunden des Vorsitzenden in Himmelwitz - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"og:description\" content=\"Die ersten Sprechstunden des Vorsitzenden der SKGD Rafa\u0142 Bartek im Jahr 2019 erfolgte in der Gemeinde Himmelwitz. W\u00e4hrend des Treffens mit dem B\u00fcrgermeister der Gemeinde, Herrn Marcin Wycis\u0142o, hatte der Vorsitzende Gelegenheit, \u00fcber die Situation der Gemeinde und die geplanten Investitionen (einschlie\u00dflich des geplanten Kindergartens) zu sprechen. Nach 16.00 Uhr fand ein Treffen mit den [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skgd.pl\/en\/dyzur-przewodniczacego-w-jemielnicy\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-15T09:51:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skgd.pl\/wp-content\/uploads\/2019\/02\/IMG_2890-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joanna Hassa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skgd.pl\/#website\",\"url\":\"https:\/\/skgd.pl\/\",\"name\":\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"description\":\"Deutsche Minderheit in Polen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skgd.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/en\/dyzur-przewodniczacego-w-jemielnicy\/#primaryimage\",\"url\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2019\/02\/IMG_2890-scaled.jpg\",\"contentUrl\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2019\/02\/IMG_2890-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skgd.pl\/en\/dyzur-przewodniczacego-w-jemielnicy\/#webpage\",\"url\":\"https:\/\/skgd.pl\/en\/dyzur-przewodniczacego-w-jemielnicy\/\",\"name\":\"Sprechstunden des Vorsitzenden in Himmelwitz - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"isPartOf\":{\"@id\":\"https:\/\/skgd.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skgd.pl\/en\/dyzur-przewodniczacego-w-jemielnicy\/#primaryimage\"},\"datePublished\":\"2019-02-15T09:51:29+00:00\",\"dateModified\":\"2019-02-15T09:51:29+00:00\",\"author\":{\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\"},\"breadcrumb\":{\"@id\":\"https:\/\/skgd.pl\/en\/dyzur-przewodniczacego-w-jemielnicy\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skgd.pl\/en\/dyzur-przewodniczacego-w-jemielnicy\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skgd.pl\/en\/dyzur-przewodniczacego-w-jemielnicy\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/skgd.pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"(Polski) Dy\u017cur Przewodnicz\u0105cego w Jemielnicy\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\",\"name\":\"Joanna Hassa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"caption\":\"Joanna Hassa\"},\"url\":\"https:\/\/skgd.pl\/de\/author\/asia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sprechstunden des Vorsitzenden in Himmelwitz - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skgd.pl\/en\/dyzur-przewodniczacego-w-jemielnicy\/","og_locale":"de_DE","og_type":"article","og_title":"Sprechstunden des Vorsitzenden in Himmelwitz - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","og_description":"Die ersten Sprechstunden des Vorsitzenden der SKGD Rafa\u0142 Bartek im Jahr 2019 erfolgte in der Gemeinde Himmelwitz. W\u00e4hrend des Treffens mit dem B\u00fcrgermeister der Gemeinde, Herrn Marcin Wycis\u0142o, hatte der Vorsitzende Gelegenheit, \u00fcber die Situation der Gemeinde und die geplanten Investitionen (einschlie\u00dflich des geplanten Kindergartens) zu sprechen. Nach 16.00 Uhr fand ein Treffen mit den [&hellip;]","og_url":"https:\/\/skgd.pl\/en\/dyzur-przewodniczacego-w-jemielnicy\/","og_site_name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","article_published_time":"2019-02-15T09:51:29+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/skgd.pl\/wp-content\/uploads\/2019\/02\/IMG_2890-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Joanna Hassa","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/skgd.pl\/#website","url":"https:\/\/skgd.pl\/","name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","description":"Deutsche Minderheit in Polen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skgd.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/en\/dyzur-przewodniczacego-w-jemielnicy\/#primaryimage","url":"https:\/\/skgd.pl\/wp-content\/uploads\/2019\/02\/IMG_2890-scaled.jpg","contentUrl":"https:\/\/skgd.pl\/wp-content\/uploads\/2019\/02\/IMG_2890-scaled.jpg","width":2560,"height":1707},{"@type":"WebPage","@id":"https:\/\/skgd.pl\/en\/dyzur-przewodniczacego-w-jemielnicy\/#webpage","url":"https:\/\/skgd.pl\/en\/dyzur-przewodniczacego-w-jemielnicy\/","name":"Sprechstunden des Vorsitzenden in Himmelwitz - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","isPartOf":{"@id":"https:\/\/skgd.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skgd.pl\/en\/dyzur-przewodniczacego-w-jemielnicy\/#primaryimage"},"datePublished":"2019-02-15T09:51:29+00:00","dateModified":"2019-02-15T09:51:29+00:00","author":{"@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03"},"breadcrumb":{"@id":"https:\/\/skgd.pl\/en\/dyzur-przewodniczacego-w-jemielnicy\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skgd.pl\/en\/dyzur-przewodniczacego-w-jemielnicy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/skgd.pl\/en\/dyzur-przewodniczacego-w-jemielnicy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/skgd.pl\/"},{"@type":"ListItem","position":2,"name":"(Polski) Dy\u017cur Przewodnicz\u0105cego w Jemielnicy"}]},{"@type":"Person","@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03","name":"Joanna Hassa","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","caption":"Joanna Hassa"},"url":"https:\/\/skgd.pl\/de\/author\/asia\/"}]}},"_links":{"self":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/19749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/comments?post=19749"}],"version-history":[{"count":1,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/19749\/revisions"}],"predecessor-version":[{"id":19753,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/19749\/revisions\/19753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media\/19750"}],"wp:attachment":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media?parent=19749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/categories?post=19749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/tags?post=19749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}