{"id":18430,"date":"2018-08-01T10:04:58","date_gmt":"2018-08-01T08:04:58","guid":{"rendered":"http:\/\/skgd.pl\/?p=18430"},"modified":"2018-08-06T12:42:33","modified_gmt":"2018-08-06T10:42:33","slug":"rozpoczal-sie-nabor-kol-dfk-do-jesiennej-edycji-kursow-sobotnich","status":"publish","type":"post","link":"https:\/\/skgd.pl\/de\/rozpoczal-sie-nabor-kol-dfk-do-jesiennej-edycji-kursow-sobotnich\/","title":{"rendered":"Samstagskurs Edition Herbst 2018 &#8211; Anmeldeverfahren beginnt"},"content":{"rendered":"<p><\/p>\n<div class=\"itemIntroText\">\n<p style=\"text-align: justify;\">Der VdG startet Vorbereitungen f\u00fcr die n\u00e4chste Edition des Projekts Samstagskurs. Ab heute k\u00f6nnen sich die DFKs zur Teilnahme an der Herbstedition 2018 anmelden.<\/p>\n<\/div>\n<div class=\"itemFullText\">\n<p style=\"text-align: justify;\">Das Aufnahmeverfahren beginnt diesmal fr\u00fcher als \u00fcblich. Die DFKs k\u00f6nnen schon jetzt ihre Bereitschaft anmelden und haben daf\u00fcr bis 26. August Zeit.<\/p>\n<p style=\"text-align: justify;\">In der Anfangsphase der Vorbereitungen will der VdG ermitteln, welche DFKs zur Durchf\u00fchrung eines Samstagskurses in den Monaten September bis Dezember bereit sind. Ende August kommt dann die Zeit f\u00fcr die Bildung der Gruppen. &#8211; Dann k\u00f6nnen die Eltern bei ihrem DFK&nbsp;auch ihre Kinder anmleden.<\/p>\n<p style=\"text-align: justify;\">Die genaue Anmeldeprozedur, notwendige Anmeldeformulare, alle Termine des Herbstedition, Ziele und Inhalte des Projekts und vieles mehr finden die DFKs auf der Webseite des Projekts Samstagskurs unter&nbsp;<a href=\"http:\/\/samstagskurs.vdg.pl\/edition.html\" target=\"_blank\" rel=\"noopener noreferrer\">www.samstagskurs.vdg.pl<\/a>.<\/p>\n<\/div>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Der VdG startet Vorbereitungen f\u00fcr die n\u00e4chste Edition des Projekts Samstagskurs. Ab heute k\u00f6nnen sich die DFKs zur Teilnahme an der Herbstedition 2018 anmelden. Das Aufnahmeverfahren beginnt diesmal fr\u00fcher als \u00fcblich. Die DFKs k\u00f6nnen schon jetzt ihre Bereitschaft anmelden und haben daf\u00fcr bis 26. August Zeit. In der Anfangsphase der Vorbereitungen will der VdG ermitteln, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18431,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-18430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktualnosci"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Samstagskurs Edition Herbst 2018 - Anmeldeverfahren beginnt - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skgd.pl\/en\/rozpoczal-sie-nabor-kol-dfk-do-jesiennej-edycji-kursow-sobotnich\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Samstagskurs Edition Herbst 2018 - Anmeldeverfahren beginnt - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"og:description\" content=\"Der VdG startet Vorbereitungen f\u00fcr die n\u00e4chste Edition des Projekts Samstagskurs. Ab heute k\u00f6nnen sich die DFKs zur Teilnahme an der Herbstedition 2018 anmelden. Das Aufnahmeverfahren beginnt diesmal fr\u00fcher als \u00fcblich. Die DFKs k\u00f6nnen schon jetzt ihre Bereitschaft anmelden und haben daf\u00fcr bis 26. August Zeit. In der Anfangsphase der Vorbereitungen will der VdG ermitteln, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skgd.pl\/en\/rozpoczal-sie-nabor-kol-dfk-do-jesiennej-edycji-kursow-sobotnich\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-01T08:04:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-08-06T10:42:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skgd.pl\/wp-content\/uploads\/2018\/07\/1e81e4bb01f3fbda395a3dd46b185b07_L.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"829\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joanna Hassa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skgd.pl\/#website\",\"url\":\"https:\/\/skgd.pl\/\",\"name\":\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"description\":\"Deutsche Minderheit in Polen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skgd.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/en\/rozpoczal-sie-nabor-kol-dfk-do-jesiennej-edycji-kursow-sobotnich\/#primaryimage\",\"url\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2018\/07\/1e81e4bb01f3fbda395a3dd46b185b07_L.jpg\",\"contentUrl\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2018\/07\/1e81e4bb01f3fbda395a3dd46b185b07_L.jpg\",\"width\":829,\"height\":485},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skgd.pl\/en\/rozpoczal-sie-nabor-kol-dfk-do-jesiennej-edycji-kursow-sobotnich\/#webpage\",\"url\":\"https:\/\/skgd.pl\/en\/rozpoczal-sie-nabor-kol-dfk-do-jesiennej-edycji-kursow-sobotnich\/\",\"name\":\"Samstagskurs Edition Herbst 2018 - Anmeldeverfahren beginnt - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"isPartOf\":{\"@id\":\"https:\/\/skgd.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skgd.pl\/en\/rozpoczal-sie-nabor-kol-dfk-do-jesiennej-edycji-kursow-sobotnich\/#primaryimage\"},\"datePublished\":\"2018-08-01T08:04:58+00:00\",\"dateModified\":\"2018-08-06T10:42:33+00:00\",\"author\":{\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\"},\"breadcrumb\":{\"@id\":\"https:\/\/skgd.pl\/en\/rozpoczal-sie-nabor-kol-dfk-do-jesiennej-edycji-kursow-sobotnich\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skgd.pl\/en\/rozpoczal-sie-nabor-kol-dfk-do-jesiennej-edycji-kursow-sobotnich\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skgd.pl\/en\/rozpoczal-sie-nabor-kol-dfk-do-jesiennej-edycji-kursow-sobotnich\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/skgd.pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"(Polski) Rozpocz\u0105\u0142 si\u0119 nab\u00f3r k\u00f3\u0142 DFK do jesiennej edycji kurs\u00f3w sobotnich\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\",\"name\":\"Joanna Hassa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"caption\":\"Joanna Hassa\"},\"url\":\"https:\/\/skgd.pl\/de\/author\/asia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Samstagskurs Edition Herbst 2018 - Anmeldeverfahren beginnt - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skgd.pl\/en\/rozpoczal-sie-nabor-kol-dfk-do-jesiennej-edycji-kursow-sobotnich\/","og_locale":"de_DE","og_type":"article","og_title":"Samstagskurs Edition Herbst 2018 - Anmeldeverfahren beginnt - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","og_description":"Der VdG startet Vorbereitungen f\u00fcr die n\u00e4chste Edition des Projekts Samstagskurs. Ab heute k\u00f6nnen sich die DFKs zur Teilnahme an der Herbstedition 2018 anmelden. Das Aufnahmeverfahren beginnt diesmal fr\u00fcher als \u00fcblich. Die DFKs k\u00f6nnen schon jetzt ihre Bereitschaft anmelden und haben daf\u00fcr bis 26. August Zeit. In der Anfangsphase der Vorbereitungen will der VdG ermitteln, [&hellip;]","og_url":"https:\/\/skgd.pl\/en\/rozpoczal-sie-nabor-kol-dfk-do-jesiennej-edycji-kursow-sobotnich\/","og_site_name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","article_published_time":"2018-08-01T08:04:58+00:00","article_modified_time":"2018-08-06T10:42:33+00:00","og_image":[{"width":829,"height":485,"url":"https:\/\/skgd.pl\/wp-content\/uploads\/2018\/07\/1e81e4bb01f3fbda395a3dd46b185b07_L.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Joanna Hassa","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/skgd.pl\/#website","url":"https:\/\/skgd.pl\/","name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","description":"Deutsche Minderheit in Polen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skgd.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/en\/rozpoczal-sie-nabor-kol-dfk-do-jesiennej-edycji-kursow-sobotnich\/#primaryimage","url":"https:\/\/skgd.pl\/wp-content\/uploads\/2018\/07\/1e81e4bb01f3fbda395a3dd46b185b07_L.jpg","contentUrl":"https:\/\/skgd.pl\/wp-content\/uploads\/2018\/07\/1e81e4bb01f3fbda395a3dd46b185b07_L.jpg","width":829,"height":485},{"@type":"WebPage","@id":"https:\/\/skgd.pl\/en\/rozpoczal-sie-nabor-kol-dfk-do-jesiennej-edycji-kursow-sobotnich\/#webpage","url":"https:\/\/skgd.pl\/en\/rozpoczal-sie-nabor-kol-dfk-do-jesiennej-edycji-kursow-sobotnich\/","name":"Samstagskurs Edition Herbst 2018 - Anmeldeverfahren beginnt - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","isPartOf":{"@id":"https:\/\/skgd.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skgd.pl\/en\/rozpoczal-sie-nabor-kol-dfk-do-jesiennej-edycji-kursow-sobotnich\/#primaryimage"},"datePublished":"2018-08-01T08:04:58+00:00","dateModified":"2018-08-06T10:42:33+00:00","author":{"@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03"},"breadcrumb":{"@id":"https:\/\/skgd.pl\/en\/rozpoczal-sie-nabor-kol-dfk-do-jesiennej-edycji-kursow-sobotnich\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skgd.pl\/en\/rozpoczal-sie-nabor-kol-dfk-do-jesiennej-edycji-kursow-sobotnich\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/skgd.pl\/en\/rozpoczal-sie-nabor-kol-dfk-do-jesiennej-edycji-kursow-sobotnich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/skgd.pl\/"},{"@type":"ListItem","position":2,"name":"(Polski) Rozpocz\u0105\u0142 si\u0119 nab\u00f3r k\u00f3\u0142 DFK do jesiennej edycji kurs\u00f3w sobotnich"}]},{"@type":"Person","@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03","name":"Joanna Hassa","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","caption":"Joanna Hassa"},"url":"https:\/\/skgd.pl\/de\/author\/asia\/"}]}},"_links":{"self":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/18430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/comments?post=18430"}],"version-history":[{"count":2,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/18430\/revisions"}],"predecessor-version":[{"id":18471,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/18430\/revisions\/18471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media\/18431"}],"wp:attachment":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media?parent=18430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/categories?post=18430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/tags?post=18430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}