{"id":16963,"date":"2018-02-16T10:21:14","date_gmt":"2018-02-16T09:21:14","guid":{"rendered":"http:\/\/skgd.pl\/?p=16963"},"modified":"2018-02-25T10:26:25","modified_gmt":"2018-02-25T09:26:25","slug":"kursy-jezyka-niemieckiego-edycja-wiosenna","status":"publish","type":"post","link":"https:\/\/skgd.pl\/de\/kursy-jezyka-niemieckiego-edycja-wiosenna\/","title":{"rendered":"Deutschkurse &#8211; Fr\u00fchlingsedition"},"content":{"rendered":"<p>Bald ist Fr\u00fchling \u2013 die beste Zeit um einen Deutschkurs anzufangen!<\/p>\n<p>M\u00f6chtest Du Deutsch lernen, hast aber keine Lust weit hinzufahren und viel Geld auszugeben? Melde dich schon heute f\u00fcr einen Kurs in Deiner Umgebung an!<\/p>\n<p>Die Sprachkurse sind vor allem f\u00fcr Angeh\u00f6rige der deutschen Minderheit und f\u00fcr alle Personen, die ihre Deutschkenntnisse verbessern m\u00f6chten. Unsere Lektoren passen das Sprachniveau des Kurses an, genau wie die Auswahl von Materialien und Themen, um Deinen Erwartungen entgegen zu kommen.<\/p>\n<p>Die Registrierung erfolgt Online auf der Internetseite der SKGD. Ein Heft und Kugelschreiber gen\u00fcgt, denn alle Materialien werden vom Lektor kostenlos zur Verf\u00fcgung gestellt.<\/p>\n<p>SKGD-Mitglieder zahlen f\u00fcr den ganzen Kurs nur 100 z\u0142, alle Anderen 160 z\u0142.<\/p>\n<p>Weitere Informationen:<\/p>\n<ul>\n<li>24 Unterrichtsstunden<\/li>\n<li>kleine Gruppen<\/li>\n<li>qualifizierte Lektoren<\/li>\n<li>sehr attraktiver Preis<\/li>\n<\/ul>\n<p>Anmeldeanfang: 6.02.2018, Anmeldeschluss: 26.02.2018<\/p>\n<p><a href=\"https:\/\/skgd.pl\/de\/sprachkurs\/\">HIER ANMELDEN<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Bald ist Fr\u00fchling \u2013 die beste Zeit um einen Deutschkurs anzufangen! M\u00f6chtest Du Deutsch lernen, hast aber keine Lust weit hinzufahren und viel Geld auszugeben? Melde dich schon heute f\u00fcr einen Kurs in Deiner Umgebung an! Die Sprachkurse sind vor allem f\u00fcr Angeh\u00f6rige der deutschen Minderheit und f\u00fcr alle Personen, die ihre Deutschkenntnisse verbessern m\u00f6chten. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":16968,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-16963","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktualnosci"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Deutschkurse - Fr\u00fchlingsedition - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skgd.pl\/kursy-jezyka-niemieckiego-edycja-wiosenna\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deutschkurse - Fr\u00fchlingsedition - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"og:description\" content=\"Bald ist Fr\u00fchling \u2013 die beste Zeit um einen Deutschkurs anzufangen! M\u00f6chtest Du Deutsch lernen, hast aber keine Lust weit hinzufahren und viel Geld auszugeben? Melde dich schon heute f\u00fcr einen Kurs in Deiner Umgebung an! Die Sprachkurse sind vor allem f\u00fcr Angeh\u00f6rige der deutschen Minderheit und f\u00fcr alle Personen, die ihre Deutschkenntnisse verbessern m\u00f6chten. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skgd.pl\/kursy-jezyka-niemieckiego-edycja-wiosenna\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-16T09:21:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-25T09:26:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skgd.pl\/wp-content\/uploads\/2018\/02\/kurs-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2258\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joanna Hassa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skgd.pl\/#website\",\"url\":\"https:\/\/skgd.pl\/\",\"name\":\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"description\":\"Deutsche Minderheit in Polen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skgd.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/kursy-jezyka-niemieckiego-edycja-wiosenna\/#primaryimage\",\"url\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2018\/02\/kurs-2-scaled.jpg\",\"contentUrl\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2018\/02\/kurs-2-scaled.jpg\",\"width\":2560,\"height\":2258},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skgd.pl\/kursy-jezyka-niemieckiego-edycja-wiosenna\/#webpage\",\"url\":\"https:\/\/skgd.pl\/kursy-jezyka-niemieckiego-edycja-wiosenna\/\",\"name\":\"Deutschkurse - Fr\u00fchlingsedition - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"isPartOf\":{\"@id\":\"https:\/\/skgd.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skgd.pl\/kursy-jezyka-niemieckiego-edycja-wiosenna\/#primaryimage\"},\"datePublished\":\"2018-02-16T09:21:14+00:00\",\"dateModified\":\"2018-02-25T09:26:25+00:00\",\"author\":{\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\"},\"breadcrumb\":{\"@id\":\"https:\/\/skgd.pl\/kursy-jezyka-niemieckiego-edycja-wiosenna\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skgd.pl\/kursy-jezyka-niemieckiego-edycja-wiosenna\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skgd.pl\/kursy-jezyka-niemieckiego-edycja-wiosenna\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/skgd.pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kursy j\u0119zyka niemieckiego &#8211; edycja wiosenna\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\",\"name\":\"Joanna Hassa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"caption\":\"Joanna Hassa\"},\"url\":\"https:\/\/skgd.pl\/de\/author\/asia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deutschkurse - Fr\u00fchlingsedition - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skgd.pl\/kursy-jezyka-niemieckiego-edycja-wiosenna\/","og_locale":"de_DE","og_type":"article","og_title":"Deutschkurse - Fr\u00fchlingsedition - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","og_description":"Bald ist Fr\u00fchling \u2013 die beste Zeit um einen Deutschkurs anzufangen! M\u00f6chtest Du Deutsch lernen, hast aber keine Lust weit hinzufahren und viel Geld auszugeben? Melde dich schon heute f\u00fcr einen Kurs in Deiner Umgebung an! Die Sprachkurse sind vor allem f\u00fcr Angeh\u00f6rige der deutschen Minderheit und f\u00fcr alle Personen, die ihre Deutschkenntnisse verbessern m\u00f6chten. [&hellip;]","og_url":"https:\/\/skgd.pl\/kursy-jezyka-niemieckiego-edycja-wiosenna\/","og_site_name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","article_published_time":"2018-02-16T09:21:14+00:00","article_modified_time":"2018-02-25T09:26:25+00:00","og_image":[{"width":2560,"height":2258,"url":"https:\/\/skgd.pl\/wp-content\/uploads\/2018\/02\/kurs-2-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Joanna Hassa","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/skgd.pl\/#website","url":"https:\/\/skgd.pl\/","name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","description":"Deutsche Minderheit in Polen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skgd.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/kursy-jezyka-niemieckiego-edycja-wiosenna\/#primaryimage","url":"https:\/\/skgd.pl\/wp-content\/uploads\/2018\/02\/kurs-2-scaled.jpg","contentUrl":"https:\/\/skgd.pl\/wp-content\/uploads\/2018\/02\/kurs-2-scaled.jpg","width":2560,"height":2258},{"@type":"WebPage","@id":"https:\/\/skgd.pl\/kursy-jezyka-niemieckiego-edycja-wiosenna\/#webpage","url":"https:\/\/skgd.pl\/kursy-jezyka-niemieckiego-edycja-wiosenna\/","name":"Deutschkurse - Fr\u00fchlingsedition - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","isPartOf":{"@id":"https:\/\/skgd.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skgd.pl\/kursy-jezyka-niemieckiego-edycja-wiosenna\/#primaryimage"},"datePublished":"2018-02-16T09:21:14+00:00","dateModified":"2018-02-25T09:26:25+00:00","author":{"@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03"},"breadcrumb":{"@id":"https:\/\/skgd.pl\/kursy-jezyka-niemieckiego-edycja-wiosenna\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skgd.pl\/kursy-jezyka-niemieckiego-edycja-wiosenna\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/skgd.pl\/kursy-jezyka-niemieckiego-edycja-wiosenna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/skgd.pl\/"},{"@type":"ListItem","position":2,"name":"Kursy j\u0119zyka niemieckiego &#8211; edycja wiosenna"}]},{"@type":"Person","@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03","name":"Joanna Hassa","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","caption":"Joanna Hassa"},"url":"https:\/\/skgd.pl\/de\/author\/asia\/"}]}},"_links":{"self":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/16963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/comments?post=16963"}],"version-history":[{"count":2,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/16963\/revisions"}],"predecessor-version":[{"id":16989,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/16963\/revisions\/16989"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media\/16968"}],"wp:attachment":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media?parent=16963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/categories?post=16963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/tags?post=16963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}