{"id":16910,"date":"2018-01-30T12:16:40","date_gmt":"2018-01-30T11:16:40","guid":{"rendered":"http:\/\/skgd.pl\/?p=16910"},"modified":"2018-01-30T12:16:40","modified_gmt":"2018-01-30T11:16:40","slug":"tragedia-niemieckiego-wschodu-przemowienie-b-gaidy-28-01-2018","status":"publish","type":"post","link":"https:\/\/skgd.pl\/de\/tragedia-niemieckiego-wschodu-przemowienie-b-gaidy-28-01-2018\/","title":{"rendered":"Trag\u00f6die des deutschen Ostens. Rede von B. Gaida (28.01.2018)"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: justify;\">Der Januar f\u00fchrt unsere Gedanken zu den tragischen Ereignissen von vor 73 Jahren. Seit vielen Jahren besuchen wir die Gedenkst\u00e4tten sowohl in Schwientochlowitz-Zgoda, in Myslowitz-Rosengarten und in Lamsdorf. Der Begriff der Oberschlesischen Trag\u00f6die hat sich bereits in der \u00d6ffentlichkeit Schlesiens etabliert, auch wenn auf verschiedene Weise.<\/p>\n<p style=\"text-align: justify;\">Die einen haben sich daran gew\u00f6hnt das Verbrechen als kommunistisches zu deklarieren, die anderen versichern st\u00e4ndig, dass es stattgefunden hat weil die Opfer Schlesier waren und nur als Deutsche angesehen wurden. Als das ein Unterschied sein k\u00f6nnte. &nbsp;Noch andere meinen, dass die einzigen T\u00e4ter und Organisatoren des Verbrechens Russen waren. Fast alle aber denken \u00fcber die Trag\u00f6die als ein schlesisches oder gar nur den \u00f6stlichen Teil Oberschlesiens&nbsp; umfassendes Ereignis.<\/p>\n<p style=\"text-align: justify;\">Als ich aber im vorigen Jahr in Berlin eine Ausstellung \u00fcber alle 25 deutsche Minderheiten in Europa er\u00f6ffnet habe, musste ich feststellen, dass das Schicksal der deutschen Bev\u00f6lkerung in Mitteleuropa \u00e4hnlich war: Vertreibungen, sog. Arbeitslager, Deportationen in die UdSSR, Vergewaltigungen, Leid und Tod. So war es in Rum\u00e4nien, in Ungarn, in der Tschechoslowakei und in ganz Ostdeutschland, also in Schlesien, Pommern, Ost- und Westpreu\u00dfen, in Danzig, Lodsch und Posen.<\/p>\n<p style=\"text-align: justify;\">Wenn wir hier an der Gedenktafel oder Gr\u00e4bern der in Schlesien ermordeten stehen, denken wir also auch an die get\u00f6teten Sudetendeutsche, die aus Siebenb\u00fcrgen deportierten, die aus Ungarn vertriebenen, die in Ermland vergewaltigte Frauen, die in K\u00f6nigsberg verhungerte Kinder, die Waisen aus Masuren, die in litauischen W\u00e4ldern herumirrten, die M\u00fctter, denen man in Potulitz ihre S\u00e4uglinge weggenommen hatte.<\/p>\n<p style=\"text-align: justify;\">Versuchen wir hier in Schlesien das Leid der anderen, die ebenfalls Opfer der Sieger wurden, nicht zu \u00fcberbieten. Denn wie soll man das Leid der einen mit dem Leid der anderen vergleichen. Das Leid der in Lagern umgekommenen Familien mit dem Leid der Familien, deren Mitglieder nach Donbas oder Sibirien deportiert wurden.&nbsp; Das Leid der Waisenkinder aus Ostpreu\u00dfen die den Hungertod der M\u00fctter und Omas gesehen haben und dann ausgehungert nach Osten, \u00fcber den Memel&nbsp; nach Litauen gefl\u00fcchtet haben nur um weiter von den Gebieten unter der polnischen Verwaltung zu sein. Weil die Litauern besser f\u00fcr sie waren. &nbsp;&nbsp;Wie kann man den Schmerz des Verlustes der Namen, Sprache und Religion messen.&nbsp; Es ist unm\u00f6glich einzusch\u00e4tzen wie der Verlust der Kinder schmerzt die in Potulitz zu Adoption gegeben wurden und die erfolglose jahrelange Suche der M\u00fctter nach den verlorenen Kinder.&nbsp;&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span>Denken wir daran, dass zu der Zeit, als die Welt den Frieden feierte, zwischen der Ostsee, dem Mittelmeer und dem Schwarzen Meer das Leid von Millionen hat gerade erst begonnen. <\/span><\/p>\n<p style=\"text-align: justify;\">Heute stehen wir symbolisch an der einer von wenigen, unseren Gedenkst\u00e4tten.&nbsp; Aber das&nbsp; Gedenken von uns muss breit sein, viel breiter als nur Schlesien.&nbsp; Die meisten St\u00e4tten unseres Gedenkens haben keine Tafeln. Deswegen vor zwei Wochen, als Deutscher und Schlesier in dem Pr\u00e4sidenten Palast in Warschau habe ich gesagt: \u201e In Polen leben auch B\u00fcrger die keine Polen&nbsp; sind, mit einer eigenen Geschichte und anderen Empfindlichkeit, mit den gleichen Pflichten aber auch Rechte\u201c und das wir st\u00e4ndig aufrufen&nbsp; &nbsp;&nbsp;nicht nur um bessere Bildung, Medienzugang&nbsp; \u201eaber auch um Achtung gegen\u00fcber auch unseren Gedenkst\u00e4tten\u201c.<\/p>\n<p style=\"text-align: justify;\">Hier in Schlesien an den, im Vergleich mit dem Ausma\u00df &nbsp;des Nachkriegsterrors, wenigen Gedenkst\u00e4tten&nbsp; rufe ich auf um alle Opfer der Sieger zu gedenken, weil sie oft in der Geschichte verschwiegen sind.&nbsp; Deswegen m\u00fcssen wir rufen um die zu erinnern , die zwar das Kriegsende erleben d\u00fcrfen, nicht aber den Frieden. Jedoch ich kann nicht schlie\u00dfen ohne zu sagen, dass das Leid keine Volkszugeh\u00f6rigkeit kennt&nbsp; und so Opfer als auch T\u00e4ter, ohne die Proportionen zu vergessen, in jedem Volk waren.&nbsp;&nbsp; Unseres Christentum verlangt, dass wir f\u00fcr alle beten und die Gedenkstunde zum Werkzeug des Friedens und Eintracht und nicht Spaltung machen, in der wir immer mehr leben. &nbsp;<\/p>\n<p style=\"text-align: justify;\">Gedenken wir uneingeschr\u00e4nkt aller Opfer des Krieges und der Nachkriegsgewalt. &nbsp;<\/p>\n<p style=\"text-align: justify;\">Das Gedenken wie immer begann mit dem Gebet um zu zeigen, dass unsere Betrachtung \u00fcber unseren Gedenkst\u00e4tten f\u00fchrt nicht zu Relativierung der Geschichte sondern zu &nbsp;Wiederherstellung ihrer vollen Inhalt. Es war auch nie mit der Feindlichkeit verbunden. Gestern sagte Frau Sabine Haake, Konsulin der Bundesrepublik Deutschland, dass nach den Verbrechen die Deutschland gegen\u00fcber Polen in dem II Weltkrieg begangen hat,&nbsp; die gegenw\u00e4rtige partnerschaftliche und freundschaftliche deutsch-polnische Beziehungen&nbsp; grenzen an ein Wunder. Dass hier mit uns auch Polen stehen, best\u00e4tigt nur dieses Wunder. Die Gedenkstunde widmen wir den die heute Feindlichkeit s\u00e4en. Die sollen sich besinnen weil die gef\u00e4hrlich spielen. &nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Der Januar f\u00fchrt unsere Gedanken zu den tragischen Ereignissen von vor 73 Jahren. Seit vielen Jahren besuchen wir die Gedenkst\u00e4tten sowohl in Schwientochlowitz-Zgoda, in Myslowitz-Rosengarten und in Lamsdorf. Der Begriff der Oberschlesischen Trag\u00f6die hat sich bereits in der \u00d6ffentlichkeit Schlesiens etabliert, auch wenn auf verschiedene Weise. Die einen haben sich daran gew\u00f6hnt das Verbrechen als [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":16900,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-16910","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktualnosci"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trag\u00f6die des deutschen Ostens. Rede von B. Gaida (28.01.2018) - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skgd.pl\/tragedia-niemieckiego-wschodu-przemowienie-b-gaidy-28-01-2018\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trag\u00f6die des deutschen Ostens. Rede von B. Gaida (28.01.2018) - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"og:description\" content=\"Der Januar f\u00fchrt unsere Gedanken zu den tragischen Ereignissen von vor 73 Jahren. Seit vielen Jahren besuchen wir die Gedenkst\u00e4tten sowohl in Schwientochlowitz-Zgoda, in Myslowitz-Rosengarten und in Lamsdorf. Der Begriff der Oberschlesischen Trag\u00f6die hat sich bereits in der \u00d6ffentlichkeit Schlesiens etabliert, auch wenn auf verschiedene Weise. Die einen haben sich daran gew\u00f6hnt das Verbrechen als [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skgd.pl\/tragedia-niemieckiego-wschodu-przemowienie-b-gaidy-28-01-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-30T11:16:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skgd.pl\/wp-content\/uploads\/2018\/01\/IMG-20180128-WA0005.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joanna Hassa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skgd.pl\/#website\",\"url\":\"https:\/\/skgd.pl\/\",\"name\":\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"description\":\"Deutsche Minderheit in Polen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skgd.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/tragedia-niemieckiego-wschodu-przemowienie-b-gaidy-28-01-2018\/#primaryimage\",\"url\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2018\/01\/IMG-20180128-WA0005.jpg\",\"contentUrl\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2018\/01\/IMG-20180128-WA0005.jpg\",\"width\":1200,\"height\":1600},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skgd.pl\/tragedia-niemieckiego-wschodu-przemowienie-b-gaidy-28-01-2018\/#webpage\",\"url\":\"https:\/\/skgd.pl\/tragedia-niemieckiego-wschodu-przemowienie-b-gaidy-28-01-2018\/\",\"name\":\"Trag\u00f6die des deutschen Ostens. Rede von B. Gaida (28.01.2018) - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"isPartOf\":{\"@id\":\"https:\/\/skgd.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skgd.pl\/tragedia-niemieckiego-wschodu-przemowienie-b-gaidy-28-01-2018\/#primaryimage\"},\"datePublished\":\"2018-01-30T11:16:40+00:00\",\"dateModified\":\"2018-01-30T11:16:40+00:00\",\"author\":{\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\"},\"breadcrumb\":{\"@id\":\"https:\/\/skgd.pl\/tragedia-niemieckiego-wschodu-przemowienie-b-gaidy-28-01-2018\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skgd.pl\/tragedia-niemieckiego-wschodu-przemowienie-b-gaidy-28-01-2018\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skgd.pl\/tragedia-niemieckiego-wschodu-przemowienie-b-gaidy-28-01-2018\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/skgd.pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tragedia niemieckiego wschodu. Przem\u00f3wienie B. Gaidy, 28.01.2018\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\",\"name\":\"Joanna Hassa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"caption\":\"Joanna Hassa\"},\"url\":\"https:\/\/skgd.pl\/de\/author\/asia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trag\u00f6die des deutschen Ostens. Rede von B. Gaida (28.01.2018) - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skgd.pl\/tragedia-niemieckiego-wschodu-przemowienie-b-gaidy-28-01-2018\/","og_locale":"de_DE","og_type":"article","og_title":"Trag\u00f6die des deutschen Ostens. Rede von B. Gaida (28.01.2018) - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","og_description":"Der Januar f\u00fchrt unsere Gedanken zu den tragischen Ereignissen von vor 73 Jahren. Seit vielen Jahren besuchen wir die Gedenkst\u00e4tten sowohl in Schwientochlowitz-Zgoda, in Myslowitz-Rosengarten und in Lamsdorf. Der Begriff der Oberschlesischen Trag\u00f6die hat sich bereits in der \u00d6ffentlichkeit Schlesiens etabliert, auch wenn auf verschiedene Weise. Die einen haben sich daran gew\u00f6hnt das Verbrechen als [&hellip;]","og_url":"https:\/\/skgd.pl\/tragedia-niemieckiego-wschodu-przemowienie-b-gaidy-28-01-2018\/","og_site_name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","article_published_time":"2018-01-30T11:16:40+00:00","og_image":[{"width":1200,"height":1600,"url":"https:\/\/skgd.pl\/wp-content\/uploads\/2018\/01\/IMG-20180128-WA0005.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Joanna Hassa","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/skgd.pl\/#website","url":"https:\/\/skgd.pl\/","name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","description":"Deutsche Minderheit in Polen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skgd.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/tragedia-niemieckiego-wschodu-przemowienie-b-gaidy-28-01-2018\/#primaryimage","url":"https:\/\/skgd.pl\/wp-content\/uploads\/2018\/01\/IMG-20180128-WA0005.jpg","contentUrl":"https:\/\/skgd.pl\/wp-content\/uploads\/2018\/01\/IMG-20180128-WA0005.jpg","width":1200,"height":1600},{"@type":"WebPage","@id":"https:\/\/skgd.pl\/tragedia-niemieckiego-wschodu-przemowienie-b-gaidy-28-01-2018\/#webpage","url":"https:\/\/skgd.pl\/tragedia-niemieckiego-wschodu-przemowienie-b-gaidy-28-01-2018\/","name":"Trag\u00f6die des deutschen Ostens. Rede von B. Gaida (28.01.2018) - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","isPartOf":{"@id":"https:\/\/skgd.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skgd.pl\/tragedia-niemieckiego-wschodu-przemowienie-b-gaidy-28-01-2018\/#primaryimage"},"datePublished":"2018-01-30T11:16:40+00:00","dateModified":"2018-01-30T11:16:40+00:00","author":{"@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03"},"breadcrumb":{"@id":"https:\/\/skgd.pl\/tragedia-niemieckiego-wschodu-przemowienie-b-gaidy-28-01-2018\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skgd.pl\/tragedia-niemieckiego-wschodu-przemowienie-b-gaidy-28-01-2018\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/skgd.pl\/tragedia-niemieckiego-wschodu-przemowienie-b-gaidy-28-01-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/skgd.pl\/"},{"@type":"ListItem","position":2,"name":"Tragedia niemieckiego wschodu. Przem\u00f3wienie B. Gaidy, 28.01.2018"}]},{"@type":"Person","@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03","name":"Joanna Hassa","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","caption":"Joanna Hassa"},"url":"https:\/\/skgd.pl\/de\/author\/asia\/"}]}},"_links":{"self":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/16910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/comments?post=16910"}],"version-history":[{"count":1,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/16910\/revisions"}],"predecessor-version":[{"id":16911,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/16910\/revisions\/16911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media\/16900"}],"wp:attachment":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media?parent=16910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/categories?post=16910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/tags?post=16910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}