{"id":16773,"date":"2018-02-03T22:08:34","date_gmt":"2018-02-03T21:08:34","guid":{"rendered":"http:\/\/skgd.pl\/?p=16773"},"modified":"2018-02-04T19:16:08","modified_gmt":"2018-02-04T18:16:08","slug":"duchowosc-i-tozsamosc-rozwoj-osobowosci-i-sluzby-spotkania-dla-przedstawicieli-dfk-na-rok-2018","status":"publish","type":"post","link":"https:\/\/skgd.pl\/de\/duchowosc-i-tozsamosc-rozwoj-osobowosci-i-sluzby-spotkania-dla-przedstawicieli-dfk-na-rok-2018\/","title":{"rendered":"&#8221;Geistigkeit und Identit\u00e4t &#8211; Entwicklung der Pers\u00f6nlichkeit und des Dienstes&#8221;"},"content":{"rendered":"<p>&#8221;Geistigkeit und Identit\u00e4t &#8211; Entwicklung von Pers\u00f6nlichkeit und Dienst&#8221;<\/p>\n<p>Treffen fuer die Vertreter der DFKs im Jahr 2018&nbsp;<\/p>\n<p>(2 Vertreter von jedem DFK)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>13.01<\/strong> &nbsp;&nbsp; \u2013 Samstag\/Sobota \u2013 <strong>G\u0142og\u00f3wek<\/strong> (Krapkowice, Prudnik), sala przy ko\u015bciele \u015bw. &nbsp;&nbsp;Bart\u0142omieja, ul. Ko\u015bcielna 2<\/p>\n<p><strong>20.01<\/strong> &nbsp;&nbsp; \u2013 Samstag\/Sobota \u2013 <strong>Opole<\/strong> (powiat opolski), Centralna Biblioteka Polsko-Niemiecka im. J. von Eichendorffa, ul. Szpitalna 7a<\/p>\n<p><strong>27.01<\/strong> &nbsp;&nbsp; \u2013 Samstag\/Sobota \u2013 <strong>Kluczbork<\/strong> (Kluczbork, Olesno) sala przy Ko\u015bciele Naj\u015bwi\u0119tszego Serca Pana Jezusa w Kluczborku, ul. Jana Paw\u0142a II nr 7<\/p>\n<p><strong>10.02<\/strong> &nbsp;&nbsp; \u2013 Samstag\/Sobota \u2013 <strong>Dziewkowice<\/strong> (powiat strzelecki, gliwicki), sala przy Ko\u015bciele pw. \u015bw. Joachima i Anny, Plac Klasztorny 10<\/p>\n<p><strong>17.02<\/strong> &nbsp;&nbsp; \u2013 Samstag\/Sobota \u2013 <strong>Bierawa<\/strong> (powiat&nbsp;k\u0119dzierzy\u0144sko-Kozielski) Sala naprzeciwko ko\u015bcio\u0142a Pw. Tr\u00f3jcy \u015awi\u0119tej, ul. Ko\u015bcielna 4a<\/p>\n<p>&nbsp;<\/p>\n<p>Szczeg\u00f3\u0142y spotka\u0144 oraz program zostanie przes\u0142any w najbli\u017cszym czasie.<\/p>\n<p><strong>Orientacyjny program \/ Vorl\u00e4ufiges Programm:<\/strong><\/p>\n<p>9.30: &nbsp; <strong>Rozpocz\u0119cie \u2013 Modlitwa \/ Er\u00f6ffnung \u2013 Gebet<\/strong><\/p>\n<p>9.35:&nbsp;&nbsp; 1. Konferenz: <strong><em>Glaube und Kultur in Schlesien vor 1989 und heute<\/em><\/strong><\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 20-25 Minuten Inhaltliche Einf\u00fchrung \/ 15-20 Minuten Diskussion<\/p>\n<p>10.15: PRZERWA \/ PAUSE (Kaffee, Tee, Geb\u00e4ck)<\/p>\n<p>10.30: 2. Konferenz: <strong><em>Die christliche Identit\u00e4t und ihre Auswirkung auf die Pflege der deutschen Kultur \u2013 offene Pers\u00f6nlichkeit (otwarta osobowo\u015b\u0107)<\/em><\/strong><\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 25 Minuten Inhaltliche Einf\u00fchrung \/ 20 Minuten Diskussion<\/p>\n<p>11.15: PRZERWA \/ PAUSE (Kaffee, Tee, Geb\u00e4ck)<\/p>\n<p>11.30: 3. Konferenz: <strong><em>\u00d6ffentliches Glaubensbekenntnis in der Hl. Messe, den Andachten und Wallfahrten \u2013 als St\u00fctze der kulturellen Identit\u00e4t<\/em><\/strong><\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 25 Minuten Inhaltliche Einf\u00fchrung \/ 20 Minuten Diskussion<\/p>\n<p>12.15: <strong>Abschluss \u2013 Gebet \/ Zako\u0144czenie modlitw\u0105<\/strong><\/p>\n<p>12.30: Mittagsimbiss \/ Pocz\u0119stunek \u2013 Lunch (Z.B. Gulasch-Suppe)<\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Abreise \/ Wyjazd<\/p>","protected":false},"excerpt":{"rendered":"<p>&#8221;Geistigkeit und Identit\u00e4t &#8211; Entwicklung von Pers\u00f6nlichkeit und Dienst&#8221; Treffen fuer die Vertreter der DFKs im Jahr 2018&nbsp; (2 Vertreter von jedem DFK) &nbsp; 13.01 &nbsp;&nbsp; \u2013 Samstag\/Sobota \u2013 G\u0142og\u00f3wek (Krapkowice, Prudnik), sala przy ko\u015bciele \u015bw. &nbsp;&nbsp;Bart\u0142omieja, ul. Ko\u015bcielna 2 20.01 &nbsp;&nbsp; \u2013 Samstag\/Sobota \u2013 Opole (powiat opolski), Centralna Biblioteka Polsko-Niemiecka im. J. von Eichendorffa, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":16161,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-16773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktualnosci"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Geistigkeit und Identit\u00e4t - Entwicklung der Pers\u00f6nlichkeit und des Dienstes&quot; - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skgd.pl\/de\/duchowosc-i-tozsamosc-rozwoj-osobowosci-i-sluzby-spotkania-dla-przedstawicieli-dfk-na-rok-2018\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Geistigkeit und Identit\u00e4t - Entwicklung der Pers\u00f6nlichkeit und des Dienstes&quot; - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"og:description\" content=\"&#8221;Geistigkeit und Identit\u00e4t &#8211; Entwicklung von Pers\u00f6nlichkeit und Dienst&#8221; Treffen fuer die Vertreter der DFKs im Jahr 2018&nbsp; (2 Vertreter von jedem DFK) &nbsp; 13.01 &nbsp;&nbsp; \u2013 Samstag\/Sobota \u2013 G\u0142og\u00f3wek (Krapkowice, Prudnik), sala przy ko\u015bciele \u015bw. &nbsp;&nbsp;Bart\u0142omieja, ul. Ko\u015bcielna 2 20.01 &nbsp;&nbsp; \u2013 Samstag\/Sobota \u2013 Opole (powiat opolski), Centralna Biblioteka Polsko-Niemiecka im. J. von Eichendorffa, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skgd.pl\/de\/duchowosc-i-tozsamosc-rozwoj-osobowosci-i-sluzby-spotkania-dla-przedstawicieli-dfk-na-rok-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-03T21:08:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-04T18:16:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/10\/wielkanoc-02.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"360\" \/>\n\t<meta property=\"og:image:height\" content=\"308\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joanna Hassa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skgd.pl\/#website\",\"url\":\"https:\/\/skgd.pl\/\",\"name\":\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"description\":\"Deutsche Minderheit in Polen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skgd.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/de\/duchowosc-i-tozsamosc-rozwoj-osobowosci-i-sluzby-spotkania-dla-przedstawicieli-dfk-na-rok-2018\/#primaryimage\",\"url\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/10\/wielkanoc-02.jpg\",\"contentUrl\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/10\/wielkanoc-02.jpg\",\"width\":360,\"height\":308},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skgd.pl\/de\/duchowosc-i-tozsamosc-rozwoj-osobowosci-i-sluzby-spotkania-dla-przedstawicieli-dfk-na-rok-2018\/#webpage\",\"url\":\"https:\/\/skgd.pl\/de\/duchowosc-i-tozsamosc-rozwoj-osobowosci-i-sluzby-spotkania-dla-przedstawicieli-dfk-na-rok-2018\/\",\"name\":\"\\\"Geistigkeit und Identit\u00e4t - Entwicklung der Pers\u00f6nlichkeit und des Dienstes\\\" - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"isPartOf\":{\"@id\":\"https:\/\/skgd.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skgd.pl\/de\/duchowosc-i-tozsamosc-rozwoj-osobowosci-i-sluzby-spotkania-dla-przedstawicieli-dfk-na-rok-2018\/#primaryimage\"},\"datePublished\":\"2018-02-03T21:08:34+00:00\",\"dateModified\":\"2018-02-04T18:16:08+00:00\",\"author\":{\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\"},\"breadcrumb\":{\"@id\":\"https:\/\/skgd.pl\/de\/duchowosc-i-tozsamosc-rozwoj-osobowosci-i-sluzby-spotkania-dla-przedstawicieli-dfk-na-rok-2018\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skgd.pl\/de\/duchowosc-i-tozsamosc-rozwoj-osobowosci-i-sluzby-spotkania-dla-przedstawicieli-dfk-na-rok-2018\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skgd.pl\/de\/duchowosc-i-tozsamosc-rozwoj-osobowosci-i-sluzby-spotkania-dla-przedstawicieli-dfk-na-rok-2018\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/skgd.pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8221;Geistigkeit und Identit\u00e4t &#8211; Entwicklung der Pers\u00f6nlichkeit und des Dienstes&#8221;\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\",\"name\":\"Joanna Hassa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"caption\":\"Joanna Hassa\"},\"url\":\"https:\/\/skgd.pl\/de\/author\/asia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Geistigkeit und Identit\u00e4t - Entwicklung der Pers\u00f6nlichkeit und des Dienstes\" - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skgd.pl\/de\/duchowosc-i-tozsamosc-rozwoj-osobowosci-i-sluzby-spotkania-dla-przedstawicieli-dfk-na-rok-2018\/","og_locale":"de_DE","og_type":"article","og_title":"\"Geistigkeit und Identit\u00e4t - Entwicklung der Pers\u00f6nlichkeit und des Dienstes\" - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","og_description":"&#8221;Geistigkeit und Identit\u00e4t &#8211; Entwicklung von Pers\u00f6nlichkeit und Dienst&#8221; Treffen fuer die Vertreter der DFKs im Jahr 2018&nbsp; (2 Vertreter von jedem DFK) &nbsp; 13.01 &nbsp;&nbsp; \u2013 Samstag\/Sobota \u2013 G\u0142og\u00f3wek (Krapkowice, Prudnik), sala przy ko\u015bciele \u015bw. &nbsp;&nbsp;Bart\u0142omieja, ul. Ko\u015bcielna 2 20.01 &nbsp;&nbsp; \u2013 Samstag\/Sobota \u2013 Opole (powiat opolski), Centralna Biblioteka Polsko-Niemiecka im. J. von Eichendorffa, [&hellip;]","og_url":"https:\/\/skgd.pl\/de\/duchowosc-i-tozsamosc-rozwoj-osobowosci-i-sluzby-spotkania-dla-przedstawicieli-dfk-na-rok-2018\/","og_site_name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","article_published_time":"2018-02-03T21:08:34+00:00","article_modified_time":"2018-02-04T18:16:08+00:00","og_image":[{"width":360,"height":308,"url":"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/10\/wielkanoc-02.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Joanna Hassa","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/skgd.pl\/#website","url":"https:\/\/skgd.pl\/","name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","description":"Deutsche Minderheit in Polen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skgd.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/de\/duchowosc-i-tozsamosc-rozwoj-osobowosci-i-sluzby-spotkania-dla-przedstawicieli-dfk-na-rok-2018\/#primaryimage","url":"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/10\/wielkanoc-02.jpg","contentUrl":"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/10\/wielkanoc-02.jpg","width":360,"height":308},{"@type":"WebPage","@id":"https:\/\/skgd.pl\/de\/duchowosc-i-tozsamosc-rozwoj-osobowosci-i-sluzby-spotkania-dla-przedstawicieli-dfk-na-rok-2018\/#webpage","url":"https:\/\/skgd.pl\/de\/duchowosc-i-tozsamosc-rozwoj-osobowosci-i-sluzby-spotkania-dla-przedstawicieli-dfk-na-rok-2018\/","name":"\"Geistigkeit und Identit\u00e4t - Entwicklung der Pers\u00f6nlichkeit und des Dienstes\" - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","isPartOf":{"@id":"https:\/\/skgd.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skgd.pl\/de\/duchowosc-i-tozsamosc-rozwoj-osobowosci-i-sluzby-spotkania-dla-przedstawicieli-dfk-na-rok-2018\/#primaryimage"},"datePublished":"2018-02-03T21:08:34+00:00","dateModified":"2018-02-04T18:16:08+00:00","author":{"@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03"},"breadcrumb":{"@id":"https:\/\/skgd.pl\/de\/duchowosc-i-tozsamosc-rozwoj-osobowosci-i-sluzby-spotkania-dla-przedstawicieli-dfk-na-rok-2018\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skgd.pl\/de\/duchowosc-i-tozsamosc-rozwoj-osobowosci-i-sluzby-spotkania-dla-przedstawicieli-dfk-na-rok-2018\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/skgd.pl\/de\/duchowosc-i-tozsamosc-rozwoj-osobowosci-i-sluzby-spotkania-dla-przedstawicieli-dfk-na-rok-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/skgd.pl\/"},{"@type":"ListItem","position":2,"name":"&#8221;Geistigkeit und Identit\u00e4t &#8211; Entwicklung der Pers\u00f6nlichkeit und des Dienstes&#8221;"}]},{"@type":"Person","@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03","name":"Joanna Hassa","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","caption":"Joanna Hassa"},"url":"https:\/\/skgd.pl\/de\/author\/asia\/"}]}},"_links":{"self":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/16773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/comments?post=16773"}],"version-history":[{"count":3,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/16773\/revisions"}],"predecessor-version":[{"id":16935,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/16773\/revisions\/16935"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media\/16161"}],"wp:attachment":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media?parent=16773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/categories?post=16773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/tags?post=16773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}