{"id":16107,"date":"2017-10-16T10:10:51","date_gmt":"2017-10-16T08:10:51","guid":{"rendered":"http:\/\/skgd.pl\/?p=16107"},"modified":"2017-12-28T10:50:03","modified_gmt":"2017-12-28T09:50:03","slug":"koncert-powiatowy-w-zakrzowie-powiat-kedzierzynsko-kozielski","status":"publish","type":"post","link":"https:\/\/skgd.pl\/de\/koncert-powiatowy-w-zakrzowie-powiat-kedzierzynsko-kozielski\/","title":{"rendered":"Kreiskonzert in Sakrau (Kreis Kandrzin-Cosel)"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: center;\"><span>Kreisvorstand der SKGD in Kandrzin-Cosel l<\/span><span>\u00e4dt herzlich ein zum<\/span><br \/>\n<span>KREISKONZERT<\/span><br \/>\n<span>Pr\u00e4sentation der Kulturgruppen der Deutschen Minderheit<\/span><\/p>\n<p style=\"text-align: center;\"><span>Gemeinde Sport- und Freizeitszentrum&nbsp;<\/span><br \/>\n<span>ul. Parkowa 20, 47-260 Sakrau&nbsp;<\/span><br \/>\n<span>Termin: 22.10.2017 Start: 15.00<\/span><\/p>\n<p><span>Im Programm<\/span><br \/>\nOrkiestra D\u0119ta Pokrzywnica &#8211; Blasorchester DFK Nesselwitz<span>&nbsp;(gm. Re\u0144ska Wie\u015b)&nbsp;<\/span><br \/>\n<span>Blasorchester Pawlowitzke (gm. Paw\u0142owiczki)<\/span><span class=\"text_exposed_show\"><br \/>\nAzalee Ostroznitz&nbsp; (gm. Paw\u0142owiczki)<br \/>\nSOLARIS (gm. Bierawa)<br \/>\nPoesie und Neues Trio&nbsp; (gm. Re\u0144ska Wie\u015b)<br \/>\nVokal Studio BIS <span>&nbsp;<\/span>(Le\u015bnica)<br \/>\nAgnieszka Treffon (gm. Paw\u0142owiczki)<br \/>\nStar des Abends Marc Bianco<\/span><\/p>\n<p>Wej\u015bci\u00f3wki do odebrania w ko\u0142ach DFK na terenie powiatu.<\/p>\n<p>Veranstalter:<br \/>\nSozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien<br \/>\nFinanzierung \/ Finansowanie:<br \/>\nKonsulat der BRD in Oppeln, Ministrestwo Spraw Wewen\u0119trznych i Administracji<br \/>\nPartner: Starostwo powiatowe w K\u0119dzierzynie-Ko\u017alu<br \/>\nMedienschirmherrschaft<br \/>\nPro Futura &#8211; Produktionsgesellschaft \/ Zesp\u00f3\u0142 Producencki,<span>&nbsp;<\/span><a href=\"https:\/\/www.facebook.com\/wochenblattpl\/\" data-hovercard=\"\/ajax\/hovercard\/page.php?id=166937709984046&amp;extragetparams=%7B%22directed_target_id%22%3A1484042541681185%7D\" data-hovercard-prefer-more-content-show=\"1\">wochenblatt.pl<\/a>,Radio Park Fm,<span>&nbsp;<\/span>Nowa Trybuna Opolska NTO,<span>&nbsp;<\/span>KK24.pl,<span>&nbsp;<\/span>Nowa Gazeta Lokalna \/ Lokalna24,<span>&nbsp;<\/span>Dobra Gazeta<\/p>\n<p><span>Begleitveranstaltung der 14. Deutschen Kulturtage im Oppelner Schlesien<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Kreisvorstand der SKGD in Kandrzin-Cosel l\u00e4dt herzlich ein zum KREISKONZERT Pr\u00e4sentation der Kulturgruppen der Deutschen Minderheit Gemeinde Sport- und Freizeitszentrum&nbsp; ul. Parkowa 20, 47-260 Sakrau&nbsp; Termin: 22.10.2017 Start: 15.00 Im Programm Orkiestra D\u0119ta Pokrzywnica &#8211; Blasorchester DFK Nesselwitz&nbsp;(gm. Re\u0144ska Wie\u015b)&nbsp; Blasorchester Pawlowitzke (gm. Paw\u0142owiczki) Azalee Ostroznitz&nbsp; (gm. Paw\u0142owiczki) SOLARIS (gm. Bierawa) Poesie und Neues Trio&nbsp; [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":16104,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-16107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktualnosci"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kreiskonzert in Sakrau (Kreis Kandrzin-Cosel) - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skgd.pl\/koncert-powiatowy-w-zakrzowie-powiat-kedzierzynsko-kozielski\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kreiskonzert in Sakrau (Kreis Kandrzin-Cosel) - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"og:description\" content=\"Kreisvorstand der SKGD in Kandrzin-Cosel l\u00e4dt herzlich ein zum KREISKONZERT Pr\u00e4sentation der Kulturgruppen der Deutschen Minderheit Gemeinde Sport- und Freizeitszentrum&nbsp; ul. Parkowa 20, 47-260 Sakrau&nbsp; Termin: 22.10.2017 Start: 15.00 Im Programm Orkiestra D\u0119ta Pokrzywnica &#8211; Blasorchester DFK Nesselwitz&nbsp;(gm. Re\u0144ska Wie\u015b)&nbsp; Blasorchester Pawlowitzke (gm. Paw\u0142owiczki) Azalee Ostroznitz&nbsp; (gm. Paw\u0142owiczki) SOLARIS (gm. Bierawa) Poesie und Neues Trio&nbsp; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skgd.pl\/koncert-powiatowy-w-zakrzowie-powiat-kedzierzynsko-kozielski\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-16T08:10:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-12-28T09:50:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/10\/Kreiskonzert-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"912\" \/>\n\t<meta property=\"og:image:height\" content=\"857\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joanna Hassa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skgd.pl\/#website\",\"url\":\"https:\/\/skgd.pl\/\",\"name\":\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"description\":\"Deutsche Minderheit in Polen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skgd.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/koncert-powiatowy-w-zakrzowie-powiat-kedzierzynsko-kozielski\/#primaryimage\",\"url\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/10\/Kreiskonzert-1.png\",\"contentUrl\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/10\/Kreiskonzert-1.png\",\"width\":912,\"height\":857},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skgd.pl\/koncert-powiatowy-w-zakrzowie-powiat-kedzierzynsko-kozielski\/#webpage\",\"url\":\"https:\/\/skgd.pl\/koncert-powiatowy-w-zakrzowie-powiat-kedzierzynsko-kozielski\/\",\"name\":\"Kreiskonzert in Sakrau (Kreis Kandrzin-Cosel) - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"isPartOf\":{\"@id\":\"https:\/\/skgd.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skgd.pl\/koncert-powiatowy-w-zakrzowie-powiat-kedzierzynsko-kozielski\/#primaryimage\"},\"datePublished\":\"2017-10-16T08:10:51+00:00\",\"dateModified\":\"2017-12-28T09:50:03+00:00\",\"author\":{\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\"},\"breadcrumb\":{\"@id\":\"https:\/\/skgd.pl\/koncert-powiatowy-w-zakrzowie-powiat-kedzierzynsko-kozielski\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skgd.pl\/koncert-powiatowy-w-zakrzowie-powiat-kedzierzynsko-kozielski\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skgd.pl\/koncert-powiatowy-w-zakrzowie-powiat-kedzierzynsko-kozielski\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/skgd.pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Koncert powiatowy w Zakrzowie (powiat K\u0119dzierzy\u0144sko-kozielski)\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\",\"name\":\"Joanna Hassa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"caption\":\"Joanna Hassa\"},\"url\":\"https:\/\/skgd.pl\/de\/author\/asia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kreiskonzert in Sakrau (Kreis Kandrzin-Cosel) - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skgd.pl\/koncert-powiatowy-w-zakrzowie-powiat-kedzierzynsko-kozielski\/","og_locale":"de_DE","og_type":"article","og_title":"Kreiskonzert in Sakrau (Kreis Kandrzin-Cosel) - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","og_description":"Kreisvorstand der SKGD in Kandrzin-Cosel l\u00e4dt herzlich ein zum KREISKONZERT Pr\u00e4sentation der Kulturgruppen der Deutschen Minderheit Gemeinde Sport- und Freizeitszentrum&nbsp; ul. Parkowa 20, 47-260 Sakrau&nbsp; Termin: 22.10.2017 Start: 15.00 Im Programm Orkiestra D\u0119ta Pokrzywnica &#8211; Blasorchester DFK Nesselwitz&nbsp;(gm. Re\u0144ska Wie\u015b)&nbsp; Blasorchester Pawlowitzke (gm. Paw\u0142owiczki) Azalee Ostroznitz&nbsp; (gm. Paw\u0142owiczki) SOLARIS (gm. Bierawa) Poesie und Neues Trio&nbsp; [&hellip;]","og_url":"https:\/\/skgd.pl\/koncert-powiatowy-w-zakrzowie-powiat-kedzierzynsko-kozielski\/","og_site_name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","article_published_time":"2017-10-16T08:10:51+00:00","article_modified_time":"2017-12-28T09:50:03+00:00","og_image":[{"width":912,"height":857,"url":"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/10\/Kreiskonzert-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Joanna Hassa","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/skgd.pl\/#website","url":"https:\/\/skgd.pl\/","name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","description":"Deutsche Minderheit in Polen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skgd.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/koncert-powiatowy-w-zakrzowie-powiat-kedzierzynsko-kozielski\/#primaryimage","url":"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/10\/Kreiskonzert-1.png","contentUrl":"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/10\/Kreiskonzert-1.png","width":912,"height":857},{"@type":"WebPage","@id":"https:\/\/skgd.pl\/koncert-powiatowy-w-zakrzowie-powiat-kedzierzynsko-kozielski\/#webpage","url":"https:\/\/skgd.pl\/koncert-powiatowy-w-zakrzowie-powiat-kedzierzynsko-kozielski\/","name":"Kreiskonzert in Sakrau (Kreis Kandrzin-Cosel) - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","isPartOf":{"@id":"https:\/\/skgd.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skgd.pl\/koncert-powiatowy-w-zakrzowie-powiat-kedzierzynsko-kozielski\/#primaryimage"},"datePublished":"2017-10-16T08:10:51+00:00","dateModified":"2017-12-28T09:50:03+00:00","author":{"@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03"},"breadcrumb":{"@id":"https:\/\/skgd.pl\/koncert-powiatowy-w-zakrzowie-powiat-kedzierzynsko-kozielski\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skgd.pl\/koncert-powiatowy-w-zakrzowie-powiat-kedzierzynsko-kozielski\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/skgd.pl\/koncert-powiatowy-w-zakrzowie-powiat-kedzierzynsko-kozielski\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/skgd.pl\/"},{"@type":"ListItem","position":2,"name":"Koncert powiatowy w Zakrzowie (powiat K\u0119dzierzy\u0144sko-kozielski)"}]},{"@type":"Person","@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03","name":"Joanna Hassa","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","caption":"Joanna Hassa"},"url":"https:\/\/skgd.pl\/de\/author\/asia\/"}]}},"_links":{"self":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/16107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/comments?post=16107"}],"version-history":[{"count":2,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/16107\/revisions"}],"predecessor-version":[{"id":16111,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/16107\/revisions\/16111"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media\/16104"}],"wp:attachment":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media?parent=16107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/categories?post=16107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/tags?post=16107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}