{"id":16023,"date":"2017-09-28T00:05:36","date_gmt":"2017-09-27T22:05:36","guid":{"rendered":"http:\/\/skgd.pl\/?p=16023"},"modified":"2017-09-28T00:05:36","modified_gmt":"2017-09-27T22:05:36","slug":"co-powstanie-koalicji-cducsu-zielonych-i-fdp-moze-oznaczac-dla-mniejszosci-niemieckiej-w-polsce-komentarz-r-bartka","status":"publish","type":"post","link":"https:\/\/skgd.pl\/de\/co-powstanie-koalicji-cducsu-zielonych-i-fdp-moze-oznaczac-dla-mniejszosci-niemieckiej-w-polsce-komentarz-r-bartka\/","title":{"rendered":"Was kann die Koalition CDU\/CSU, Gr\u00fcne und FDP f\u00fcr die Deutsche Minderheit bedeuten? Kommentar von R. Bartek"},"content":{"rendered":"<p>In Vorbereitung<\/p>","protected":false},"excerpt":{"rendered":"<p>In Vorbereitung<\/p>\n","protected":false},"author":2,"featured_media":10610,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-16023","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktualnosci"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Was kann die Koalition CDU\/CSU, Gr\u00fcne und FDP f\u00fcr die Deutsche Minderheit bedeuten? Kommentar von R. Bartek - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skgd.pl\/co-powstanie-koalicji-cducsu-zielonych-i-fdp-moze-oznaczac-dla-mniejszosci-niemieckiej-w-polsce-komentarz-r-bartka\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Was kann die Koalition CDU\/CSU, Gr\u00fcne und FDP f\u00fcr die Deutsche Minderheit bedeuten? Kommentar von R. Bartek - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"og:description\" content=\"In Vorbereitung\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skgd.pl\/co-powstanie-koalicji-cducsu-zielonych-i-fdp-moze-oznaczac-dla-mniejszosci-niemieckiej-w-polsce-komentarz-r-bartka\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-27T22:05:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skgd.pl\/wp-content\/uploads\/2016\/01\/bartek.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joanna Hassa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skgd.pl\/#website\",\"url\":\"https:\/\/skgd.pl\/\",\"name\":\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"description\":\"Deutsche Minderheit in Polen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skgd.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/co-powstanie-koalicji-cducsu-zielonych-i-fdp-moze-oznaczac-dla-mniejszosci-niemieckiej-w-polsce-komentarz-r-bartka\/#primaryimage\",\"url\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2016\/01\/bartek.jpg\",\"contentUrl\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2016\/01\/bartek.jpg\",\"width\":2000,\"height\":1333},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skgd.pl\/co-powstanie-koalicji-cducsu-zielonych-i-fdp-moze-oznaczac-dla-mniejszosci-niemieckiej-w-polsce-komentarz-r-bartka\/#webpage\",\"url\":\"https:\/\/skgd.pl\/co-powstanie-koalicji-cducsu-zielonych-i-fdp-moze-oznaczac-dla-mniejszosci-niemieckiej-w-polsce-komentarz-r-bartka\/\",\"name\":\"Was kann die Koalition CDU\/CSU, Gr\u00fcne und FDP f\u00fcr die Deutsche Minderheit bedeuten? Kommentar von R. Bartek - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"isPartOf\":{\"@id\":\"https:\/\/skgd.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skgd.pl\/co-powstanie-koalicji-cducsu-zielonych-i-fdp-moze-oznaczac-dla-mniejszosci-niemieckiej-w-polsce-komentarz-r-bartka\/#primaryimage\"},\"datePublished\":\"2017-09-27T22:05:36+00:00\",\"dateModified\":\"2017-09-27T22:05:36+00:00\",\"author\":{\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\"},\"breadcrumb\":{\"@id\":\"https:\/\/skgd.pl\/co-powstanie-koalicji-cducsu-zielonych-i-fdp-moze-oznaczac-dla-mniejszosci-niemieckiej-w-polsce-komentarz-r-bartka\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skgd.pl\/co-powstanie-koalicji-cducsu-zielonych-i-fdp-moze-oznaczac-dla-mniejszosci-niemieckiej-w-polsce-komentarz-r-bartka\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skgd.pl\/co-powstanie-koalicji-cducsu-zielonych-i-fdp-moze-oznaczac-dla-mniejszosci-niemieckiej-w-polsce-komentarz-r-bartka\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/skgd.pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Co powstanie koalicji CDU\/CSU, Zielonych i FDP mo\u017ce oznacza\u0107 dla Mniejszo\u015bci Niemieckiej w Polsce? &#8211; Komentarz R. Bartka\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\",\"name\":\"Joanna Hassa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"caption\":\"Joanna Hassa\"},\"url\":\"https:\/\/skgd.pl\/de\/author\/asia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Was kann die Koalition CDU\/CSU, Gr\u00fcne und FDP f\u00fcr die Deutsche Minderheit bedeuten? Kommentar von R. Bartek - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skgd.pl\/co-powstanie-koalicji-cducsu-zielonych-i-fdp-moze-oznaczac-dla-mniejszosci-niemieckiej-w-polsce-komentarz-r-bartka\/","og_locale":"de_DE","og_type":"article","og_title":"Was kann die Koalition CDU\/CSU, Gr\u00fcne und FDP f\u00fcr die Deutsche Minderheit bedeuten? Kommentar von R. Bartek - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","og_description":"In Vorbereitung","og_url":"https:\/\/skgd.pl\/co-powstanie-koalicji-cducsu-zielonych-i-fdp-moze-oznaczac-dla-mniejszosci-niemieckiej-w-polsce-komentarz-r-bartka\/","og_site_name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","article_published_time":"2017-09-27T22:05:36+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/skgd.pl\/wp-content\/uploads\/2016\/01\/bartek.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Joanna Hassa","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/skgd.pl\/#website","url":"https:\/\/skgd.pl\/","name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","description":"Deutsche Minderheit in Polen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skgd.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/co-powstanie-koalicji-cducsu-zielonych-i-fdp-moze-oznaczac-dla-mniejszosci-niemieckiej-w-polsce-komentarz-r-bartka\/#primaryimage","url":"https:\/\/skgd.pl\/wp-content\/uploads\/2016\/01\/bartek.jpg","contentUrl":"https:\/\/skgd.pl\/wp-content\/uploads\/2016\/01\/bartek.jpg","width":2000,"height":1333},{"@type":"WebPage","@id":"https:\/\/skgd.pl\/co-powstanie-koalicji-cducsu-zielonych-i-fdp-moze-oznaczac-dla-mniejszosci-niemieckiej-w-polsce-komentarz-r-bartka\/#webpage","url":"https:\/\/skgd.pl\/co-powstanie-koalicji-cducsu-zielonych-i-fdp-moze-oznaczac-dla-mniejszosci-niemieckiej-w-polsce-komentarz-r-bartka\/","name":"Was kann die Koalition CDU\/CSU, Gr\u00fcne und FDP f\u00fcr die Deutsche Minderheit bedeuten? Kommentar von R. Bartek - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","isPartOf":{"@id":"https:\/\/skgd.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skgd.pl\/co-powstanie-koalicji-cducsu-zielonych-i-fdp-moze-oznaczac-dla-mniejszosci-niemieckiej-w-polsce-komentarz-r-bartka\/#primaryimage"},"datePublished":"2017-09-27T22:05:36+00:00","dateModified":"2017-09-27T22:05:36+00:00","author":{"@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03"},"breadcrumb":{"@id":"https:\/\/skgd.pl\/co-powstanie-koalicji-cducsu-zielonych-i-fdp-moze-oznaczac-dla-mniejszosci-niemieckiej-w-polsce-komentarz-r-bartka\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skgd.pl\/co-powstanie-koalicji-cducsu-zielonych-i-fdp-moze-oznaczac-dla-mniejszosci-niemieckiej-w-polsce-komentarz-r-bartka\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/skgd.pl\/co-powstanie-koalicji-cducsu-zielonych-i-fdp-moze-oznaczac-dla-mniejszosci-niemieckiej-w-polsce-komentarz-r-bartka\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/skgd.pl\/"},{"@type":"ListItem","position":2,"name":"Co powstanie koalicji CDU\/CSU, Zielonych i FDP mo\u017ce oznacza\u0107 dla Mniejszo\u015bci Niemieckiej w Polsce? &#8211; Komentarz R. Bartka"}]},{"@type":"Person","@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03","name":"Joanna Hassa","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","caption":"Joanna Hassa"},"url":"https:\/\/skgd.pl\/de\/author\/asia\/"}]}},"_links":{"self":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/16023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/comments?post=16023"}],"version-history":[{"count":1,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/16023\/revisions"}],"predecessor-version":[{"id":16024,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/16023\/revisions\/16024"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media\/10610"}],"wp:attachment":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media?parent=16023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/categories?post=16023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/tags?post=16023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}