{"id":15102,"date":"2017-04-19T00:56:52","date_gmt":"2017-04-18T22:56:52","guid":{"rendered":"http:\/\/skgd.pl\/?p=15102"},"modified":"2017-04-27T18:26:39","modified_gmt":"2017-04-27T16:26:39","slug":"czlonkowie-dfk-zywo-zainteresowani-tematem-tegorocznych-wyborow-do-bundestagu","status":"publish","type":"post","link":"https:\/\/skgd.pl\/de\/czlonkowie-dfk-zywo-zainteresowani-tematem-tegorocznych-wyborow-do-bundestagu\/","title":{"rendered":"Die Mitglieder der DFKs zeigten grosses Interesse an dem Thema der Bundestagswahlen"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: justify;\">Der Vorsitzende der Sozial-Kulturellen Gesellschaft der Deutschen im Oppelner Schlesien &#8211; Rafa\u0142 Bartek, w\u00e4hlte f\u00fcr die n\u00e4chsten Sprechstunden des Vorsitzenden die Gemeinde Deschowitz. Vor dem Treffen mit den Mitgliedern der DFKs, traf er sich mit der B\u00fcrgermeisterin Sybila Zimerman. Es gab die Gelegenheit sich \u00fcber die aktuelle Lage der Gemeinde auszutauschen, der Vorsitzende nahm sich auch Zeit \u00fcber die Schulreform und \u00fcber die eventuelle Unterst\u00fctzung der lokalen DFKs vom Budget der Gemeinde <span>zu sprechen<\/span>.&nbsp;<\/p>\n<p style=\"text-align: justify;\">Das Treffen mit den Mitgliedern der deutschen Minderheit in der Gemeinde Deschowitz, fand im DFK Roswadze statt &#8211; im SKGD-Geb\u00e4ude, welches in der letzten Zeit renoviert wurde. Der Vorsitzende stellte die aktuellen Themen vor, hat unter anderem zu kommenden Veranstaltungen eingeladen und erinnerte an den Termin den Antrag f\u00fcr den&nbsp;Unterricht Deutsch als Minderheitensprache einzureichen.<\/p>\n<p style=\"text-align: justify;\">Das gr\u00f6\u00dfte Interesse weckte jedoch das Thema der Bundestagswahlen in diesem Jahr. Die Mitglieder der DFKs weisten darauf hin, dass wenn man an den Wahlen teilnehmen will muss die&nbsp;deutsche Staatsangeh\u00f6rigkeit&nbsp;mit einem Pass oder Personalausweis best\u00e4tigt werden. F\u00fcr viele \u00e4ltere Mitglieder des DFK, neue P\u00e4sse oder Personalausweise sind zu teuer, betragen ca. 60 Euro.&nbsp;Es scheint daher angebracht, eine Werbekampagne zu starten, die Teilnahme an den Wahlen zu f\u00f6rdern gezielt an die Menschen, die solche Dokumente schon besitzen (z.B. wegen der Arbeitsstelle).&nbsp;<span lang=\"de\">Die Mitglieder des DFK appellierten auch, dass die deutschen Politiker eine Informationskampagne durchf\u00fchren sollten, die einerseits die Teilnahme an den Wahlen f\u00f6rdert, auf der anderen Seite das Wahlprogramm der deutschen Parteien darstellt.<\/span><\/p>\n<p style=\"text-align: justify;\">[envira-gallery id=&#8221;15098&#8243;]<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Der Vorsitzende der Sozial-Kulturellen Gesellschaft der Deutschen im Oppelner Schlesien &#8211; Rafa\u0142 Bartek, w\u00e4hlte f\u00fcr die n\u00e4chsten Sprechstunden des Vorsitzenden die Gemeinde Deschowitz. Vor dem Treffen mit den Mitgliedern der DFKs, traf er sich mit der B\u00fcrgermeisterin Sybila Zimerman. Es gab die Gelegenheit sich \u00fcber die aktuelle Lage der Gemeinde auszutauschen, der Vorsitzende nahm sich [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":15101,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-15102","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktualnosci"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Die Mitglieder der DFKs zeigten grosses Interesse an dem Thema der Bundestagswahlen - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skgd.pl\/de\/czlonkowie-dfk-zywo-zainteresowani-tematem-tegorocznych-wyborow-do-bundestagu\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Mitglieder der DFKs zeigten grosses Interesse an dem Thema der Bundestagswahlen - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"og:description\" content=\"Der Vorsitzende der Sozial-Kulturellen Gesellschaft der Deutschen im Oppelner Schlesien &#8211; Rafa\u0142 Bartek, w\u00e4hlte f\u00fcr die n\u00e4chsten Sprechstunden des Vorsitzenden die Gemeinde Deschowitz. Vor dem Treffen mit den Mitgliedern der DFKs, traf er sich mit der B\u00fcrgermeisterin Sybila Zimerman. Es gab die Gelegenheit sich \u00fcber die aktuelle Lage der Gemeinde auszutauschen, der Vorsitzende nahm sich [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skgd.pl\/de\/czlonkowie-dfk-zywo-zainteresowani-tematem-tegorocznych-wyborow-do-bundestagu\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-18T22:56:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-27T16:26:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/04\/IMG_8240-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joanna Hassa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skgd.pl\/#website\",\"url\":\"https:\/\/skgd.pl\/\",\"name\":\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"description\":\"Deutsche Minderheit in Polen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skgd.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/de\/czlonkowie-dfk-zywo-zainteresowani-tematem-tegorocznych-wyborow-do-bundestagu\/#primaryimage\",\"url\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/04\/IMG_8240-scaled.jpg\",\"contentUrl\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/04\/IMG_8240-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skgd.pl\/de\/czlonkowie-dfk-zywo-zainteresowani-tematem-tegorocznych-wyborow-do-bundestagu\/#webpage\",\"url\":\"https:\/\/skgd.pl\/de\/czlonkowie-dfk-zywo-zainteresowani-tematem-tegorocznych-wyborow-do-bundestagu\/\",\"name\":\"Die Mitglieder der DFKs zeigten grosses Interesse an dem Thema der Bundestagswahlen - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"isPartOf\":{\"@id\":\"https:\/\/skgd.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skgd.pl\/de\/czlonkowie-dfk-zywo-zainteresowani-tematem-tegorocznych-wyborow-do-bundestagu\/#primaryimage\"},\"datePublished\":\"2017-04-18T22:56:52+00:00\",\"dateModified\":\"2017-04-27T16:26:39+00:00\",\"author\":{\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\"},\"breadcrumb\":{\"@id\":\"https:\/\/skgd.pl\/de\/czlonkowie-dfk-zywo-zainteresowani-tematem-tegorocznych-wyborow-do-bundestagu\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skgd.pl\/de\/czlonkowie-dfk-zywo-zainteresowani-tematem-tegorocznych-wyborow-do-bundestagu\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skgd.pl\/de\/czlonkowie-dfk-zywo-zainteresowani-tematem-tegorocznych-wyborow-do-bundestagu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/skgd.pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Mitglieder der DFKs zeigten grosses Interesse an dem Thema der Bundestagswahlen\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\",\"name\":\"Joanna Hassa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"caption\":\"Joanna Hassa\"},\"url\":\"https:\/\/skgd.pl\/de\/author\/asia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Mitglieder der DFKs zeigten grosses Interesse an dem Thema der Bundestagswahlen - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skgd.pl\/de\/czlonkowie-dfk-zywo-zainteresowani-tematem-tegorocznych-wyborow-do-bundestagu\/","og_locale":"de_DE","og_type":"article","og_title":"Die Mitglieder der DFKs zeigten grosses Interesse an dem Thema der Bundestagswahlen - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","og_description":"Der Vorsitzende der Sozial-Kulturellen Gesellschaft der Deutschen im Oppelner Schlesien &#8211; Rafa\u0142 Bartek, w\u00e4hlte f\u00fcr die n\u00e4chsten Sprechstunden des Vorsitzenden die Gemeinde Deschowitz. Vor dem Treffen mit den Mitgliedern der DFKs, traf er sich mit der B\u00fcrgermeisterin Sybila Zimerman. Es gab die Gelegenheit sich \u00fcber die aktuelle Lage der Gemeinde auszutauschen, der Vorsitzende nahm sich [&hellip;]","og_url":"https:\/\/skgd.pl\/de\/czlonkowie-dfk-zywo-zainteresowani-tematem-tegorocznych-wyborow-do-bundestagu\/","og_site_name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","article_published_time":"2017-04-18T22:56:52+00:00","article_modified_time":"2017-04-27T16:26:39+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/04\/IMG_8240-1024x683.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Joanna Hassa","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/skgd.pl\/#website","url":"https:\/\/skgd.pl\/","name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","description":"Deutsche Minderheit in Polen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skgd.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/de\/czlonkowie-dfk-zywo-zainteresowani-tematem-tegorocznych-wyborow-do-bundestagu\/#primaryimage","url":"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/04\/IMG_8240-scaled.jpg","contentUrl":"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/04\/IMG_8240-scaled.jpg","width":2560,"height":1707},{"@type":"WebPage","@id":"https:\/\/skgd.pl\/de\/czlonkowie-dfk-zywo-zainteresowani-tematem-tegorocznych-wyborow-do-bundestagu\/#webpage","url":"https:\/\/skgd.pl\/de\/czlonkowie-dfk-zywo-zainteresowani-tematem-tegorocznych-wyborow-do-bundestagu\/","name":"Die Mitglieder der DFKs zeigten grosses Interesse an dem Thema der Bundestagswahlen - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","isPartOf":{"@id":"https:\/\/skgd.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skgd.pl\/de\/czlonkowie-dfk-zywo-zainteresowani-tematem-tegorocznych-wyborow-do-bundestagu\/#primaryimage"},"datePublished":"2017-04-18T22:56:52+00:00","dateModified":"2017-04-27T16:26:39+00:00","author":{"@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03"},"breadcrumb":{"@id":"https:\/\/skgd.pl\/de\/czlonkowie-dfk-zywo-zainteresowani-tematem-tegorocznych-wyborow-do-bundestagu\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skgd.pl\/de\/czlonkowie-dfk-zywo-zainteresowani-tematem-tegorocznych-wyborow-do-bundestagu\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/skgd.pl\/de\/czlonkowie-dfk-zywo-zainteresowani-tematem-tegorocznych-wyborow-do-bundestagu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/skgd.pl\/"},{"@type":"ListItem","position":2,"name":"Die Mitglieder der DFKs zeigten grosses Interesse an dem Thema der Bundestagswahlen"}]},{"@type":"Person","@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03","name":"Joanna Hassa","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","caption":"Joanna Hassa"},"url":"https:\/\/skgd.pl\/de\/author\/asia\/"}]}},"_links":{"self":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/15102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/comments?post=15102"}],"version-history":[{"count":3,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/15102\/revisions"}],"predecessor-version":[{"id":15173,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/15102\/revisions\/15173"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media\/15101"}],"wp:attachment":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media?parent=15102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/categories?post=15102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/tags?post=15102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}