{"id":14858,"date":"2017-03-23T15:26:25","date_gmt":"2017-03-23T14:26:25","guid":{"rendered":"http:\/\/skgd.pl\/?p=14858"},"modified":"2017-03-23T15:26:25","modified_gmt":"2017-03-23T14:26:25","slug":"wielkanocne-bastlowanie-w-dfk-zelazna","status":"publish","type":"post","link":"https:\/\/skgd.pl\/de\/wielkanocne-bastlowanie-w-dfk-zelazna\/","title":{"rendered":"Osterbasteln im DFK Zelazno"},"content":{"rendered":"<p>DFK Zelazno laedt ganz herzlich alle Interessenten zum Osterbasteln am 25.03.2017 um 14.00 Uhr in Zelazno ein.<\/p>\n<p>WIr laden Sie ganz gerzlich ein.<\/p>\n<p>Anmeldung unter: 602 263 655<\/p>","protected":false},"excerpt":{"rendered":"<p>DFK Zelazno laedt ganz herzlich alle Interessenten zum Osterbasteln am 25.03.2017 um 14.00 Uhr in Zelazno ein. WIr laden Sie ganz gerzlich ein. Anmeldung unter: 602 263 655<\/p>\n","protected":false},"author":2,"featured_media":14859,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[244],"tags":[],"class_list":["post-14858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dfk-zelazna-zelazno"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Osterbasteln im DFK Zelazno - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skgd.pl\/en\/wielkanocne-bastlowanie-w-dfk-zelazna\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Osterbasteln im DFK Zelazno - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"og:description\" content=\"DFK Zelazno laedt ganz herzlich alle Interessenten zum Osterbasteln am 25.03.2017 um 14.00 Uhr in Zelazno ein. WIr laden Sie ganz gerzlich ein. Anmeldung unter: 602 263 655\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skgd.pl\/en\/wielkanocne-bastlowanie-w-dfk-zelazna\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-23T14:26:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/03\/IMG-20170323-WA0001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joanna Hassa\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skgd.pl\/#website\",\"url\":\"https:\/\/skgd.pl\/\",\"name\":\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"description\":\"Deutsche Minderheit in Polen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skgd.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/en\/wielkanocne-bastlowanie-w-dfk-zelazna\/#primaryimage\",\"url\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/03\/IMG-20170323-WA0001.jpg\",\"contentUrl\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/03\/IMG-20170323-WA0001.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skgd.pl\/en\/wielkanocne-bastlowanie-w-dfk-zelazna\/#webpage\",\"url\":\"https:\/\/skgd.pl\/en\/wielkanocne-bastlowanie-w-dfk-zelazna\/\",\"name\":\"Osterbasteln im DFK Zelazno - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"isPartOf\":{\"@id\":\"https:\/\/skgd.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skgd.pl\/en\/wielkanocne-bastlowanie-w-dfk-zelazna\/#primaryimage\"},\"datePublished\":\"2017-03-23T14:26:25+00:00\",\"dateModified\":\"2017-03-23T14:26:25+00:00\",\"author\":{\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\"},\"breadcrumb\":{\"@id\":\"https:\/\/skgd.pl\/en\/wielkanocne-bastlowanie-w-dfk-zelazna\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skgd.pl\/en\/wielkanocne-bastlowanie-w-dfk-zelazna\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skgd.pl\/en\/wielkanocne-bastlowanie-w-dfk-zelazna\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/skgd.pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"(Polski) Wielkanocne bastlowanie w DFK \u017belazna\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\",\"name\":\"Joanna Hassa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"caption\":\"Joanna Hassa\"},\"url\":\"https:\/\/skgd.pl\/de\/author\/asia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Osterbasteln im DFK Zelazno - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skgd.pl\/en\/wielkanocne-bastlowanie-w-dfk-zelazna\/","og_locale":"de_DE","og_type":"article","og_title":"Osterbasteln im DFK Zelazno - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","og_description":"DFK Zelazno laedt ganz herzlich alle Interessenten zum Osterbasteln am 25.03.2017 um 14.00 Uhr in Zelazno ein. WIr laden Sie ganz gerzlich ein. Anmeldung unter: 602 263 655","og_url":"https:\/\/skgd.pl\/en\/wielkanocne-bastlowanie-w-dfk-zelazna\/","og_site_name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","article_published_time":"2017-03-23T14:26:25+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/03\/IMG-20170323-WA0001.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Joanna Hassa"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/skgd.pl\/#website","url":"https:\/\/skgd.pl\/","name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","description":"Deutsche Minderheit in Polen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skgd.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/en\/wielkanocne-bastlowanie-w-dfk-zelazna\/#primaryimage","url":"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/03\/IMG-20170323-WA0001.jpg","contentUrl":"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/03\/IMG-20170323-WA0001.jpg","width":1600,"height":1200},{"@type":"WebPage","@id":"https:\/\/skgd.pl\/en\/wielkanocne-bastlowanie-w-dfk-zelazna\/#webpage","url":"https:\/\/skgd.pl\/en\/wielkanocne-bastlowanie-w-dfk-zelazna\/","name":"Osterbasteln im DFK Zelazno - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","isPartOf":{"@id":"https:\/\/skgd.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skgd.pl\/en\/wielkanocne-bastlowanie-w-dfk-zelazna\/#primaryimage"},"datePublished":"2017-03-23T14:26:25+00:00","dateModified":"2017-03-23T14:26:25+00:00","author":{"@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03"},"breadcrumb":{"@id":"https:\/\/skgd.pl\/en\/wielkanocne-bastlowanie-w-dfk-zelazna\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skgd.pl\/en\/wielkanocne-bastlowanie-w-dfk-zelazna\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/skgd.pl\/en\/wielkanocne-bastlowanie-w-dfk-zelazna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/skgd.pl\/"},{"@type":"ListItem","position":2,"name":"(Polski) Wielkanocne bastlowanie w DFK \u017belazna"}]},{"@type":"Person","@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03","name":"Joanna Hassa","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","caption":"Joanna Hassa"},"url":"https:\/\/skgd.pl\/de\/author\/asia\/"}]}},"_links":{"self":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/14858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/comments?post=14858"}],"version-history":[{"count":1,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/14858\/revisions"}],"predecessor-version":[{"id":14860,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/14858\/revisions\/14860"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media\/14859"}],"wp:attachment":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media?parent=14858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/categories?post=14858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/tags?post=14858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}