{"id":14757,"date":"2017-03-01T00:15:59","date_gmt":"2017-02-28T23:15:59","guid":{"rendered":"http:\/\/skgd.pl\/de\/?p=14757"},"modified":"2017-03-01T00:16:31","modified_gmt":"2017-02-28T23:16:31","slug":"ferie-zimowe-2017","status":"publish","type":"post","link":"https:\/\/skgd.pl\/de\/ferie-zimowe-2017\/","title":{"rendered":"Winterferien 2017"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: justify;\">Vorst\u00e4nde der DFKs: Roschowitzdorf und Niesnaschin haben f\u00fcr Kinder und Jugendliche die Freizeit w\u00e4hrend der diesj\u00e4hrigen Winterferien gestaltet. In den R\u00e4umlichkeiten des DFK Roschowitzdorf fand am 15.02.2017 das M\u00e4rchenkino mit Spielanimationen statt, wiederum am 24.02.2017 Zumba f\u00fcr alle. Wiederum DFK Niesnaschin hat f\u00fcr die kleinsten einen \u00dcberraschungsweg, verbunden mit dem Kinderball vorbereitet, der am 21.02.2017 stattfand.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Vorst\u00e4nde der DFKs: Roschowitzdorf und Niesnaschin haben f\u00fcr Kinder und Jugendliche die Freizeit w\u00e4hrend der diesj\u00e4hrigen Winterferien gestaltet. In den R\u00e4umlichkeiten des DFK Roschowitzdorf fand am 15.02.2017 das M\u00e4rchenkino mit Spielanimationen statt, wiederum am 24.02.2017 Zumba f\u00fcr alle. Wiederum DFK Niesnaschin hat f\u00fcr die kleinsten einen \u00dcberraschungsweg, verbunden mit dem Kinderball vorbereitet, der am 21.02.2017 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14758,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[82],"tags":[],"class_list":["post-14757","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dfk-roszowice-roschowitzdorf"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Winterferien 2017 - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skgd.pl\/ferie-zimowe-2017\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Winterferien 2017 - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"og:description\" content=\"Vorst\u00e4nde der DFKs: Roschowitzdorf und Niesnaschin haben f\u00fcr Kinder und Jugendliche die Freizeit w\u00e4hrend der diesj\u00e4hrigen Winterferien gestaltet. In den R\u00e4umlichkeiten des DFK Roschowitzdorf fand am 15.02.2017 das M\u00e4rchenkino mit Spielanimationen statt, wiederum am 24.02.2017 Zumba f\u00fcr alle. Wiederum DFK Niesnaschin hat f\u00fcr die kleinsten einen \u00dcberraschungsweg, verbunden mit dem Kinderball vorbereitet, der am 21.02.2017 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skgd.pl\/ferie-zimowe-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-28T23:15:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-02-28T23:16:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/02\/Zusammenfassung-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skgd.pl\/#website\",\"url\":\"https:\/\/skgd.pl\/\",\"name\":\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"description\":\"Deutsche Minderheit in Polen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skgd.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/ferie-zimowe-2017\/#primaryimage\",\"url\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/02\/Zusammenfassung-scaled.jpg\",\"contentUrl\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/02\/Zusammenfassung-scaled.jpg\",\"width\":2560,\"height\":1810},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skgd.pl\/ferie-zimowe-2017\/#webpage\",\"url\":\"https:\/\/skgd.pl\/ferie-zimowe-2017\/\",\"name\":\"Winterferien 2017 - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"isPartOf\":{\"@id\":\"https:\/\/skgd.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skgd.pl\/ferie-zimowe-2017\/#primaryimage\"},\"datePublished\":\"2017-02-28T23:15:59+00:00\",\"dateModified\":\"2017-02-28T23:16:31+00:00\",\"author\":{\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/709172ef205731476e77391cc87c04e8\"},\"breadcrumb\":{\"@id\":\"https:\/\/skgd.pl\/ferie-zimowe-2017\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skgd.pl\/ferie-zimowe-2017\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skgd.pl\/ferie-zimowe-2017\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/skgd.pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ferie zimowe 2017\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/709172ef205731476e77391cc87c04e8\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a352aecaac6403c9ea5013a95dbe945e910d71bc652d01a07313977398158711?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a352aecaac6403c9ea5013a95dbe945e910d71bc652d01a07313977398158711?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/skgd.pl\/de\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Winterferien 2017 - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skgd.pl\/ferie-zimowe-2017\/","og_locale":"de_DE","og_type":"article","og_title":"Winterferien 2017 - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","og_description":"Vorst\u00e4nde der DFKs: Roschowitzdorf und Niesnaschin haben f\u00fcr Kinder und Jugendliche die Freizeit w\u00e4hrend der diesj\u00e4hrigen Winterferien gestaltet. In den R\u00e4umlichkeiten des DFK Roschowitzdorf fand am 15.02.2017 das M\u00e4rchenkino mit Spielanimationen statt, wiederum am 24.02.2017 Zumba f\u00fcr alle. Wiederum DFK Niesnaschin hat f\u00fcr die kleinsten einen \u00dcberraschungsweg, verbunden mit dem Kinderball vorbereitet, der am 21.02.2017 [&hellip;]","og_url":"https:\/\/skgd.pl\/ferie-zimowe-2017\/","og_site_name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","article_published_time":"2017-02-28T23:15:59+00:00","article_modified_time":"2017-02-28T23:16:31+00:00","og_image":[{"width":2560,"height":1810,"url":"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/02\/Zusammenfassung-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/skgd.pl\/#website","url":"https:\/\/skgd.pl\/","name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","description":"Deutsche Minderheit in Polen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skgd.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/ferie-zimowe-2017\/#primaryimage","url":"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/02\/Zusammenfassung-scaled.jpg","contentUrl":"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/02\/Zusammenfassung-scaled.jpg","width":2560,"height":1810},{"@type":"WebPage","@id":"https:\/\/skgd.pl\/ferie-zimowe-2017\/#webpage","url":"https:\/\/skgd.pl\/ferie-zimowe-2017\/","name":"Winterferien 2017 - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","isPartOf":{"@id":"https:\/\/skgd.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skgd.pl\/ferie-zimowe-2017\/#primaryimage"},"datePublished":"2017-02-28T23:15:59+00:00","dateModified":"2017-02-28T23:16:31+00:00","author":{"@id":"https:\/\/skgd.pl\/#\/schema\/person\/709172ef205731476e77391cc87c04e8"},"breadcrumb":{"@id":"https:\/\/skgd.pl\/ferie-zimowe-2017\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skgd.pl\/ferie-zimowe-2017\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/skgd.pl\/ferie-zimowe-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/skgd.pl\/"},{"@type":"ListItem","position":2,"name":"Ferie zimowe 2017"}]},{"@type":"Person","@id":"https:\/\/skgd.pl\/#\/schema\/person\/709172ef205731476e77391cc87c04e8","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a352aecaac6403c9ea5013a95dbe945e910d71bc652d01a07313977398158711?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a352aecaac6403c9ea5013a95dbe945e910d71bc652d01a07313977398158711?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/skgd.pl\/de\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/14757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/comments?post=14757"}],"version-history":[{"count":2,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/14757\/revisions"}],"predecessor-version":[{"id":14760,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/14757\/revisions\/14760"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media\/14758"}],"wp:attachment":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media?parent=14757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/categories?post=14757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/tags?post=14757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}