{"id":14741,"date":"2017-02-27T10:01:20","date_gmt":"2017-02-27T09:01:20","guid":{"rendered":"http:\/\/skgd.pl\/?p=14741"},"modified":"2017-02-27T10:01:20","modified_gmt":"2017-02-27T09:01:20","slug":"schlagertanz-w-przysieczy","status":"publish","type":"post","link":"https:\/\/skgd.pl\/de\/schlagertanz-w-przysieczy\/","title":{"rendered":"Schlagertanz in Przyschetz"},"content":{"rendered":"<p>Gemeindevorstand in Proskau organisierte am 18.02.2017 einen&nbsp;Schlagertanz in Przyschetz.&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/nW8DMfVYnqo\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>Gemeindevorstand in Proskau organisierte am 18.02.2017 einen&nbsp;Schlagertanz in Przyschetz.&nbsp;<\/p>\n","protected":false},"author":2,"featured_media":14742,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[296],"tags":[],"class_list":["post-14741","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dfk-gmina-proszkow-gemeinde-proskau"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Schlagertanz in Przyschetz - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skgd.pl\/schlagertanz-w-przysieczy\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schlagertanz in Przyschetz - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"og:description\" content=\"Gemeindevorstand in Proskau organisierte am 18.02.2017 einen&nbsp;Schlagertanz in Przyschetz.&nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skgd.pl\/schlagertanz-w-przysieczy\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-27T09:01:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/02\/16797532_639599596230205_3308598873696834167_o.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joanna Hassa\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skgd.pl\/#website\",\"url\":\"https:\/\/skgd.pl\/\",\"name\":\"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"description\":\"Deutsche Minderheit in Polen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skgd.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/schlagertanz-w-przysieczy\/#primaryimage\",\"url\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/02\/16797532_639599596230205_3308598873696834167_o.jpg\",\"contentUrl\":\"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/02\/16797532_639599596230205_3308598873696834167_o.jpg\",\"width\":2048,\"height\":1536},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skgd.pl\/schlagertanz-w-przysieczy\/#webpage\",\"url\":\"https:\/\/skgd.pl\/schlagertanz-w-przysieczy\/\",\"name\":\"Schlagertanz in Przyschetz - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien\",\"isPartOf\":{\"@id\":\"https:\/\/skgd.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skgd.pl\/schlagertanz-w-przysieczy\/#primaryimage\"},\"datePublished\":\"2017-02-27T09:01:20+00:00\",\"dateModified\":\"2017-02-27T09:01:20+00:00\",\"author\":{\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\"},\"breadcrumb\":{\"@id\":\"https:\/\/skgd.pl\/schlagertanz-w-przysieczy\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skgd.pl\/schlagertanz-w-przysieczy\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skgd.pl\/schlagertanz-w-przysieczy\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/skgd.pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schlagertanz w Przysieczy\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03\",\"name\":\"Joanna Hassa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skgd.pl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g\",\"caption\":\"Joanna Hassa\"},\"url\":\"https:\/\/skgd.pl\/de\/author\/asia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schlagertanz in Przyschetz - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skgd.pl\/schlagertanz-w-przysieczy\/","og_locale":"de_DE","og_type":"article","og_title":"Schlagertanz in Przyschetz - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","og_description":"Gemeindevorstand in Proskau organisierte am 18.02.2017 einen&nbsp;Schlagertanz in Przyschetz.&nbsp;","og_url":"https:\/\/skgd.pl\/schlagertanz-w-przysieczy\/","og_site_name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","article_published_time":"2017-02-27T09:01:20+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/02\/16797532_639599596230205_3308598873696834167_o.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Joanna Hassa"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/skgd.pl\/#website","url":"https:\/\/skgd.pl\/","name":"Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","description":"Deutsche Minderheit in Polen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skgd.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/schlagertanz-w-przysieczy\/#primaryimage","url":"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/02\/16797532_639599596230205_3308598873696834167_o.jpg","contentUrl":"https:\/\/skgd.pl\/wp-content\/uploads\/2017\/02\/16797532_639599596230205_3308598873696834167_o.jpg","width":2048,"height":1536},{"@type":"WebPage","@id":"https:\/\/skgd.pl\/schlagertanz-w-przysieczy\/#webpage","url":"https:\/\/skgd.pl\/schlagertanz-w-przysieczy\/","name":"Schlagertanz in Przyschetz - Deutsche Minderheit, Sozial-Kulturelle Gesellschaft der Deutschen im Oppelner Schlesien","isPartOf":{"@id":"https:\/\/skgd.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skgd.pl\/schlagertanz-w-przysieczy\/#primaryimage"},"datePublished":"2017-02-27T09:01:20+00:00","dateModified":"2017-02-27T09:01:20+00:00","author":{"@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03"},"breadcrumb":{"@id":"https:\/\/skgd.pl\/schlagertanz-w-przysieczy\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skgd.pl\/schlagertanz-w-przysieczy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/skgd.pl\/schlagertanz-w-przysieczy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/skgd.pl\/"},{"@type":"ListItem","position":2,"name":"Schlagertanz w Przysieczy"}]},{"@type":"Person","@id":"https:\/\/skgd.pl\/#\/schema\/person\/0620fbcc0ddc3adae2d5dd9fdc163f03","name":"Joanna Hassa","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skgd.pl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e6bc131fd6ead2388ce9b90989110adf4601766749b52c1c5132e4a2cc812ccc?s=96&d=mm&r=g","caption":"Joanna Hassa"},"url":"https:\/\/skgd.pl\/de\/author\/asia\/"}]}},"_links":{"self":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/14741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/comments?post=14741"}],"version-history":[{"count":1,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/14741\/revisions"}],"predecessor-version":[{"id":14743,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/posts\/14741\/revisions\/14743"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media\/14742"}],"wp:attachment":[{"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/media?parent=14741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/categories?post=14741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skgd.pl\/de\/wp-json\/wp\/v2\/tags?post=14741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}